{"id":32385,"date":"2016-06-13T12:03:42","date_gmt":"2016-06-13T17:03:42","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/como-encuentro-a-la-mujer-ideal-existe\/"},"modified":"2016-06-13T12:03:42","modified_gmt":"2016-06-13T17:03:42","slug":"como-encuentro-a-la-mujer-ideal-existe","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/como-encuentro-a-la-mujer-ideal-existe\/","title":{"rendered":"\u00bfC\u00f3mo encuentro a la mujer ideal?&nbsp;\u00bfExiste?"},"content":{"rendered":"<p><b>Por: La Opci\u00f3n V<\/b><\/p>\n<p align=\"justify\"><em>Cuando yo era muy chiquita mi hermano mayor me escribi&oacute; esta carta que quiero compartirles. Para m&iacute; es un tesoro, un legado important&iacute;simo que marc&oacute; mi camino en la b&uacute;squeda del amor verdadero. Me alegrar&iacute;a mucho saber que mi hermano puede seguir ayudando a muchos, tocando sus corazones y cambiando sus vidas con esta carta.<\/em><br \/> &nbsp;<br \/> Querida Yori:<br \/> &nbsp;<br \/> Desde chicos, los hombres estamos expuestos a ser formados como \u201cmachos alfa\u201d. Crecemos queriendo que todo venga r&aacute;pido y buscamos hacer cosas de grandes \u201cya ya\u201d, dejando de lado el \u201cpaso a paso\u201d.<br \/> &nbsp;<br \/> Mi vida ha sido buena en varios aspectos, pero no te quiero negar que muchas veces me he cuestionado el c&oacute;mo llevar una relaci&oacute;n y mi rol como hombre.<br \/> &nbsp;<br \/><strong>Siempre he anhelado tener una relaci&oacute;n como la de pap&aacute; y mam&aacute;. No ha sido perfecta, pero he visto sus bases muy s&oacute;lidas<\/strong>: se aman, se comunican, no dejan de conocerse, se cuidan entre ellos, van a Misa todos los Domingos. Yo busco una mujer tan bella como mam&aacute;: responsable con la familia, que ame a Dios sobre todas las cosas, que me haga crecer en lo espiritual y muchas otras cosas esenciales. Me parece l&oacute;gico que si yo espero eso de una chica, yo deber&iacute;a ser ese hombre que siga el ejemplo de un hombre justo tambi&eacute;n.<br \/> &nbsp;<br \/> La verdad es que el camino para llegar a serlo ha sido demasiado complejo, despojarme del d&iacute;a a d&iacute;a, tratar de ser diferente parece imposible, negarme a propuestas \u201cinteresantes\u201d de mis amigos es un verdadero reto, decir que NO o parar la mano cuando deb&iacute;a hacerlo, otro tanto complicado.<\/p>\n<p align=\"justify\"> Comet&iacute; muchos errores desde que era chico. Luego, ya m&aacute;s grande, cuando cre&iacute; conocer por primera vez el \u201camor\u201d, la fregu&eacute; (<em>*&nbsp;peruanismo que significa estropear<\/em>) varias veces y despu&eacute;s, a&uacute;n cuando fui consciente de esas experiencias err&oacute;neas, volv&iacute; a caer. No sab&iacute;a hasta cu&aacute;ndo suceder&iacute;a esto. Pero estoy esforz&aacute;ndome por hacer las cosas bien.<br \/> &nbsp;<br \/> Peque&ntilde;a, con Pili llevamos 3 a&ntilde;os de relaci&oacute;n ya y estoy feliz. Es una mujer que me ha ense&ntilde;ado y demostrado que el amor puro y santo &iexcl;s&iacute; existe! La lucha contra la tentaci&oacute;n no ha sido f&aacute;cil, fuimos ingenuos much&iacute;simas veces y de esos malos ratos, por los que sentimos que nos hab&iacute;amos fallado a nosotros mismos, el uno al otro y a Dios, hemos ido aprendiendo y madurando.<br \/> &nbsp;<br \/><strong>Puede sonarte hasta exagerado, pero en estas &eacute;pocas todav&iacute;a existen las reglas de la casa para estar con una chica: el llamarla hasta tal hora, el regresarla a casa en el tiempo pactado, <\/strong>etc. Me acuerdo que la primera vez que habl&eacute; con sus pap&aacute;s fue m&aacute;s complicado que sustentar mi tesis de Administraci&oacute;n en la Garcilaso (* Universidad en Lima). &iexcl;Estaba muy nervioso! Podr&iacute;a seguir cont&aacute;ndote m&aacute;s experiencias de este tipo, pero el punto al que quiero llegar es que <strong>todos estos detalles, que a los ojos del mundo son \u201canticuados\u201d o \u201cdemasiado tradicionales\u201d, eran la garant&iacute;a para saber de la clase de mujer con la que estaba, y eso fue lo que me enamor&oacute; profundamente de ella<\/strong>. Tuve que pasar por todo eso para encontrar a la mujer que siempre quise y que ahora tengo.<br \/> &nbsp;<br \/> Ahora hay un poco m&aacute;s de flexibilidad, pero siguen existiendo las reglas de sus padres y las cosas que ella me ha dejado en claro sobre la grandeza y pureza de esta relaci&oacute;n, y eso a&uacute;n como enamorado sigo respetando. No ha sido f&aacute;cil aceptarlas, tuve que ceder en mucho y renunciar a muchas cosas, porque sencillamente estaba acostumbrado a otras. Ahora reci&eacute;n comprendo que todo ten&iacute;a su prop&oacute;sito. <strong>&iquest;Pod&iacute;a encontrar de otra manera a la mujer de mis sue&ntilde;os, si no era sacrific&aacute;ndome a m&iacute; mismo y cambiando las maneras aprendidas desde peque&ntilde;o de c&oacute;mo un \u201cmacho alfa\u201d encuentra a su \u201chembra\u201d? <\/strong>Pues no hermanita, este sacrificio ha sido necesario para encontrar el amor puro y verdadero en una mujer excepcional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: La Opci\u00f3n V Cuando yo era muy chiquita mi hermano mayor me escribi&oacute; esta carta que quiero compartirles. Para m&iacute; es un tesoro, un legado important&iacute;simo que marc&oacute; mi camino en la b&uacute;squeda del amor verdadero. Me alegrar&iacute;a mucho saber que mi hermano puede seguir ayudando a muchos, tocando sus corazones y cambiando sus &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/como-encuentro-a-la-mujer-ideal-existe\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab\u00bfC\u00f3mo encuentro a la mujer ideal?&nbsp;\u00bfExiste?\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-32385","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=32385"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32385\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=32385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=32385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=32385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}