{"id":32388,"date":"2016-06-13T12:03:51","date_gmt":"2016-06-13T17:03:51","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/la-iglesia-argentina-quiere-ser-creativa-para-ayudar-a-los-novios\/"},"modified":"2016-06-13T12:03:51","modified_gmt":"2016-06-13T17:03:51","slug":"la-iglesia-argentina-quiere-ser-creativa-para-ayudar-a-los-novios","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/la-iglesia-argentina-quiere-ser-creativa-para-ayudar-a-los-novios\/","title":{"rendered":"La Iglesia argentina quiere ser creativa para ayudar a los&nbsp;novios"},"content":{"rendered":"<p><b>Por: Esteban Pittaro<\/b><\/p>\n<p align=\"justify\">\u201cLa elecci&oacute;n del Papa Francisco ha sido un regalo de Dios para la Iglesia que peregrina en la Argentina\u201d. Dos a&ntilde;os despu&eacute;s de la elecci&oacute;n de Francisco, los obispos argentinos siguen conmovidos por la elecci&oacute;n de Jorge Bergoglio. La gran mayor&iacute;a de los integrantes del episcopado argentino conocen de primera mano el pensamiento del Papa, y desde su esp&iacute;ritu, manifestado tanto en mensajes directos al episcopado argentino como en sus alocuciones y en la Evangelii Gaudium, elaboraron sus l&iacute;neas pastorales para el trienio 2015-2017.<\/p>\n<p align=\"justify\"> El documento de 15 p&aacute;ginas presentado por la Comisi&oacute;n Permanente destaca algunas \u201coportunidades evangelizadoras privilegiadas\u201d para estos a&ntilde;os, y nombra al Congreso Ecuar&iacute;stico Nacional de 2016, con el que la Iglesia celebrar&aacute; el Bicentenario de la Independencia argentina, los a&ntilde;os dedicados a la Vida Consagrada (2015) y a la Misericordia (2016) y la \u201cdeseada y esperada\u201d visita de Francisco al pa&iacute;s. Los prelados ofrecen ideas para trabajar las pastorales juveniles y vocaciones y la catequesis, entre otros puntos.<\/p>\n<p align=\"justify\"> Los Obispos sintetizan en Misi&oacute;n y Misericordia las \u201cinsistencias y matices\u201d propias del ministerio de Francisco. \u201cPara que el impulso misionero no quede simplemente en un esfuerzo funcionalista la misi&oacute;n tiene como fin poner de manifiesto la misericordia de Dios\u201d, consideran los prelados argentinos. <strong>Tras repasar aportes de Francisco a la Pastoral, los obispos sintetizan que su aporte podr&iacute;a definirse con este binomio: \u201cla Iglesia evangeliza amando (\u2018misericordiando\u2019) y cuando ama y es misericordiosa, la Iglesia evangeliza\u201d.<\/strong><\/p>\n<p align=\"justify\"> Al reflexionar sobre el a&ntilde;o de la Misericordia convocado por Francisco los obispos argentinos lo ven \u201ccomo un camino de conversi&oacute;n espiritual, en el cual no debemos cansarnos de pedir perd&oacute;n\u201d.<\/p>\n<p align=\"justify\"> \u201cQue Jes&uacute;s siga siendo el eje fundamental de la historia de nuestro pueblo\u201d, desean los obispos al escribir sobre el lema \u201cJesucristo, Se&ntilde;or de la historia, te necesitamos\u201d, con el que se rotula el Congreso Eucar&iacute;stico de 2016. \u201cSer&aacute; una oportunidad para hacer presente los valores cristianos que estuvieron en el origen de nuestra independencia, la participaci&oacute;n comprometida por la libertad de tantos hombres y mujeres, consagrados y laicos miembros de la Iglesia y el compromiso necesario hoy para ser una patria de hermanos que viva una mayor comuni&oacute;n, justicia y solidaridad\u201d, escriben.<\/p>\n<p align=\"justify\"> La preocupaci&oacute;n de Francisco por la familia tambi&eacute;n est&aacute; presente en las l&iacute;neas pastorales. El s&iacute;nodo sobre la Familia de este a&ntilde;o compromete a los pastores y a los agentes de pastoral a \u201cser creativos para encontrar caminos que ayuden a los novios a descubrir la belleza de la vocaci&oacute;n matrimonial\u201d. Adem&aacute;s de los novios, los obispos piensan en las familias, y llaman a que puedan \u201capreciar la riqueza de la misi&oacute;n que tienen como escuela de vida fundada en el amor de los esposos, y como \u2018Iglesia dom&eacute;stica\u2019\u201d.<\/p>\n<p align=\"justify\"> Los Obispos incluso advierten que tras las conclusiones del S&iacute;nodo ser&aacute; necesario conformar una pastoral familiar diocesana que incluya la catequesis para la preparaci&oacute;n al Matrimonio.<\/p>\n<p align=\"justify\"> Adem&aacute;s, los prelados argentinos reflexionan sobre el acompa&ntilde;amiento de los j&oacute;venes, sobre la \u201ccercan&iacute;a\u201d a la que est&aacute;n llamadas las parroquias y a su orientaci&oacute;n a la misi&oacute;n, y la catequesis. Sobre este &uacute;ltimo punto, consideran que es necesario \u201cdefinir un Itinerario Catequ&iacute;stico Permanente como lugar de maduraci&oacute;n comunitaria en la fe\u201d. \u201cQue la Palabra de Dios, la Liturgia, el Catecismo de la Iglesia Cat&oacute;lica y tambi&eacute;n la Doctrina Social de la Iglesia, sean permanentes referencias para la tarea catequ&iacute;stica\u201d.<\/p>\n<p align=\"justify\"> El documento concluye haciendo referencias a los presb&iacute;teros y su compromiso con la Caridad Pastoral, a la vida consagrada y religiosa y el compromiso de los prelados a acompa&ntilde;arlos, y termina pidiendo rezar por el aumento y la perseverancia de las vocaciones tanto sacerdotales como religiosas y consagradas. Puede descargarse y leerse entero en el sitio de internet de la Conferencia Episcopal Argentina: <a target=\"_blank\" href=\"http:\/\/www.episcopado.org\">www.episcopado.org<\/a>.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Esteban Pittaro \u201cLa elecci&oacute;n del Papa Francisco ha sido un regalo de Dios para la Iglesia que peregrina en la Argentina\u201d. Dos a&ntilde;os despu&eacute;s de la elecci&oacute;n de Francisco, los obispos argentinos siguen conmovidos por la elecci&oacute;n de Jorge Bergoglio. La gran mayor&iacute;a de los integrantes del episcopado argentino conocen de primera mano el &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/la-iglesia-argentina-quiere-ser-creativa-para-ayudar-a-los-novios\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLa Iglesia argentina quiere ser creativa para ayudar a los&nbsp;novios\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-32388","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=32388"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32388\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=32388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=32388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=32388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}