{"id":32389,"date":"2016-06-13T12:03:53","date_gmt":"2016-06-13T17:03:53","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/de-repente-30-y-soltero\/"},"modified":"2016-06-13T12:03:53","modified_gmt":"2016-06-13T17:03:53","slug":"de-repente-30-y-soltero","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/de-repente-30-y-soltero\/","title":{"rendered":"De repente 30&#8230; y&nbsp;soltero"},"content":{"rendered":"<p><b>Por: DESTRAVE<\/b><\/p>\n<p align=\"justify\">No es raro, actualmente, encontrar personas que lleguen a los 30 a\u00f1os y a\u00fan est\u00e9n solteras. En algunas generaciones, la mayor\u00eda se casaba alrededor de los 20 o 25 a\u00f1os, probablemente haya sido as\u00ed con nuestros padres. Ya con nuestros abuelos, el matrimonio era a\u00fan m\u00e1s temprano, entre los 15 y los 19 a\u00f1os.<\/p>\n<p align=\"justify\"><strong>Los tiempos han cambiado<\/strong>, los planes de las personas y el medio en que viven se han vuelto diferentes.<\/p>\n<p align=\"justify\">Antiguamente, cuando alguien se volv\u00eda adulto \u2013en condiciones de trabajar y producir como \u201cgente mayor\u201d\u2013 la familia ya se preocupaba con un matrimonio para \u00e9l. \u00a1Hoy no!<\/p>\n<p align=\"justify\">Actualmente, se piensa que, primero, el individuo debe cursar la universidad o aprender un oficio, luego <strong>estabilizarse<\/strong> profesionalmente para adquirir cierta estructura econ\u00f3mica. S\u00f3lo entonces, buscar a alguien para casarse.<\/p>\n<p align=\"justify\">Cuando entramos en la tercera d\u00e9cada de nuestra vida, atravesamos, definitivamente, la frontera entre la juventud y la edad adulta. Parece que algo sucede en nuestro interior, una conciencia nueva, una responsabilidad mayor, sobretodo, con nosotros mismos.<\/p>\n<p align=\"justify\">Nos damos cuenta de que <strong>parte de nuestra vida pas\u00f3, pero a\u00fan nos falta proporcionar elementos esenciales como el matrimonio.<\/strong><\/p>\n<p align=\"justify\">A esas alturas de la vida, la mayor crisis es estar todav\u00eda soltero. Y muchos se preguntan: \u201c\u00bfPor qu\u00e9 estoy solo? \u00bfPor qu\u00e9 no aparece una buena persona de quien enamorarme? <strong>\u00bfHay alg\u00fan problema conmigo?<\/strong>\u201d.<\/p>\n<p align=\"justify\"><strong>Ventajas<\/strong><\/p>\n<p align=\"justify\">Antes de intentar responder, analicemos los puntos positivos: las personas \u201cmayores de 30\u201d tienen a su favor el hecho de que <strong>muchos est\u00e1n realizados profesionalmente. <\/strong>Entonces, pueden ofrecer a la pareja cierta estructura material, estabilidad econ\u00f3mica y emocional.<\/p>\n<p align=\"justify\">Tambi\u00e9n probablemente ya tuvieron, por lo menos, una relaci\u00f3n de noviazgo y, <strong>te\u00f3ricamente, deben saber lidiar mejor con las diferencias.<\/p>\n<p align=\"justify\">Preguntas para plantearse<\/strong><\/p>\n<p align=\"justify\">\u00bfTodas\u00a0 las cosas por las cuales has luchado te generan efectos colaterales? \u00bfEst\u00e1s soltero porque <strong>diste prioridad a estructurar tu vida y dejaste un poco de lado el campo afectivo? <\/strong>\u00bfSer\u00e1 que no intercambiaste tu dedicaci\u00f3n y tu tiempo para cultivar buenas amistades y estar con personas parecidas contigo por horas de estudio y trabajo?<\/p>\n<p align=\"justify\">\u00bfDe qu\u00e9 platicas? \u00bfHojas de c\u00e1lculo, mercados o cosas relacionadas con tu profesi\u00f3n? <strong>Hay personas que usan t\u00e9cnicas de coqueteo de la misma manera en que lidian con sus clientes.<\/strong><\/p>\n<p align=\"justify\">\u00bfLa edad, las cosas que aprendiste y hasta las piedras del camino no han hecho que tuvieras <strong>m\u00e1s man\u00edas?<\/strong> Es natural que el tiempo pase y te vuelvas m\u00e1s exigente para involucrarte emocionalmente. La persona exigente busca cualidades que ha buscado para s\u00ed misma, para luego ofrecer algo bueno a su pareja.<\/p>\n<p align=\"justify\">\u00bfEl hecho de tener que llevar a cabo <strong>metas y medios para alcanzar tus objetivos<\/strong> no te hace pensar en tu vida afectiva como algo calculado, planeado? \u00bfEn un <strong>prototipo de mujer u hombre ideal, perfecto? <\/strong>Es bueno dejar claro que <strong>ese tipo de persona no existe.<\/strong><\/p>\n<p align=\"justify\">\u00bfHaces tu parte? <strong>\u00bfInviertes en ti mismo?<\/strong> \u00bfLees libros buenos y <strong>te enriqueces <\/strong>de su contenido? \u00bfDejas de lado las molestias e <strong>intentas ser m\u00e1s simp\u00e1tico, sonre\u00edr m\u00e1s? \u00bfTe has reconciliado con tu pasado, con tus miedos y traumas? \u00bfHas perdonado? \u00bfBuscas entenderte a ti mismo y tus procesos internos?<\/p>\n<p align=\"justify\">Consejos<\/strong><\/p>\n<p align=\"justify\"><strong>D\u00e9jate sorprender por las personas a trav\u00e9s de lo que tienen dentro<\/strong> de s\u00ed. No intentes fabricar otras. Las mayores riquezas y los mayores dones que una persona tiene fluir\u00e1n naturalmente en ella. <strong>Abre tu coraz\u00f3n, sal de casa, haz amistades. Llegar a los 30 a\u00f1os no es el final, sino el inicio de una nueva etapa.<\/strong><\/p>\n<p align=\"justify\">Lo importante es no perder la esperanza, pues \u00e9sta es la certeza de que <strong>Dios tiene siempre lo mejor para nosotros.<\/strong><\/p>\n<p align=\"justify\"><em>Por\u00a0<a target=\"_blank\" href=\"http:\/\/destrave.cancaonova.com\/de-repente-30-e-solteiro\/\">Sandro Arquejada<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: DESTRAVE No es raro, actualmente, encontrar personas que lleguen a los 30 a\u00f1os y a\u00fan est\u00e9n solteras. En algunas generaciones, la mayor\u00eda se casaba alrededor de los 20 o 25 a\u00f1os, probablemente haya sido as\u00ed con nuestros padres. Ya con nuestros abuelos, el matrimonio era a\u00fan m\u00e1s temprano, entre los 15 y los 19 &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/de-repente-30-y-soltero\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abDe repente 30&#8230; y&nbsp;soltero\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-32389","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=32389"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32389\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=32389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=32389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=32389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}