{"id":32393,"date":"2016-06-13T12:04:00","date_gmt":"2016-06-13T17:04:00","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/carta-de-dios-a-un-recien-casado-y-tambien-para-ella-2\/"},"modified":"2016-06-13T12:04:00","modified_gmt":"2016-06-13T17:04:00","slug":"carta-de-dios-a-un-recien-casado-y-tambien-para-ella-2","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/carta-de-dios-a-un-recien-casado-y-tambien-para-ella-2\/","title":{"rendered":"Carta de Dios a un reci\u00e9n casado (y tambi\u00e9n para&nbsp;ella)"},"content":{"rendered":"<p><b>Por: Padre Giordano Muraro<\/b><\/p>\n<p align=\"justify\">La mujer que tienes al lado, emocionada, con traje de novia, es m&iacute;a. Yo la he creado. Yo la he querido desde siempre; antes que tu, y m&aacute;s que tu. Por ella no dud&eacute; en dar mi vida. Tengo grandes proyectos para ella. Te la conf&iacute;o. La tomar&aacute;s de mis manos y ser&aacute;s responsable de ella.<br \/> &nbsp;<br \/> Cuando la conociste, la encontraste bella y te enamoraste. Son mis manos las que plasmaron su belleza, y es mi coraz&oacute;n el que puso dentro de ella la ternura y el amor, es mi sabidur&iacute;a la que form&oacute; su sensibilidad y su inteligencia y todas las buenas cualidades que has encontrado en ella.<br \/> &nbsp;<br \/> Pero no basta con que disfrutes de su fascinaci&oacute;n. Deber&aacute;s empe&ntilde;arte en responder a sus necesidades, a sus deseos. Te dar&aacute;s cuenta de que necesita muchas cosas: necesita casa, vestido, serenidad, alegr&iacute;a, equilibrio ps&iacute;quico, relaciones humanas, afecto, ternura, placer y diversi&oacute;n, presencia humana y di&aacute;logo, relaciones sociales y familiares, satisfacciones laborales, y muchas otras cosas.<br \/> &nbsp;<br \/> Pero tendr&aacute;s que darte cuenta de que me necesita sobre todo a M&iacute;, y todo lo que ayuda y favorece este encuentro conmigo: la paz del coraz&oacute;n, la pureza de esp&iacute;ritu, la oraci&oacute;n, la Palabra, el perd&oacute;n, la esperanza y la confianza en M&iacute;, Mi vida. Soy Yo, y no tu, el principio, el fin, el destino de toda su vida.<br \/> &nbsp;<br \/> Hagamos un pacto entre nosotros: la amaremos juntos. Yo la amo desde siempre. Tu has empezado a amarla desde hace alg&uacute;n a&ntilde;o, desde que te enamoraste. Soy yo el que puse en tu coraz&oacute;n el amor por ella. Ha sido la manera m&aacute;s hermosa para que te fijaras en ella. Quer&iacute;a confiarla a alguien que la cuidara. Pero tambi&eacute;n quer&iacute;a que ella enriqueciese con su belleza y cualidades la vida de un hombre. Y ese hombre eres tu.<br \/> &nbsp;<br \/> Por esto he hecho nacer en tu coraz&oacute;n el amor por ella. Era la forma m&aacute;s hermosa de decirte: \u201caqu&iacute; est&aacute;, te la conf&iacute;o\u201d, y para que tu pudieras disfrutar de su belleza y sus cualidades. Cuando le digas \u201cprometo serte fiel, amarte y respetarte durante toda mi vida\u201d, ser&aacute; como si me dijeras que est&aacute;s contento de acogerla en tu vida y de cuidar de ella. Desde ese momento, seremos dos los que la amemos.<br \/> &nbsp;<br \/> Pero tenemos que ponernos de acuerdo: No es posible que tu la ames de una forma y yo de otra. Debes tener hacia ella un amor parecido al M&iacute;o, y debes desear para ella lo mismo que Yo deseo. No puedes pensar en nada m&aacute;s bello y gozoso para ella.<br \/> &nbsp;<br \/> Si la amas en serio ver&aacute;s que est&aacute;s de acuerdo conmigo en el proyecto que he pensado para ella. Te dar&eacute; a entender poco a poco cu&aacute;l es mi manera de amar, y te revelar&eacute; qu&eacute; vida he solado y querido para esta criatura m&iacute;a que se convertir&aacute; en tu esposa.<br \/> &nbsp;<br \/> Me doy cuenta de que te estoy pidiendo mucho. Cre&iacute;as que esta mujer era tuya y solo tuya, y ahora en cambio tienes la impresi&oacute;n de que te pido que la compartas conmigo. No es as&iacute;. Yo no soy tu rival en el amor. Al contrario, soy Aquel que te ayudar&aacute; a amarla apasionadamente. Por esto deseo que en tu peque&ntilde;o amor est&eacute; mi gran amor.<br \/> &nbsp;<br \/> Con tu amor podr&aacute;s hacer mucho por ella, pero ser&aacute; siempre demasiado poco. Yo en cambio te hago capaz de amar desde Dios. Este es mi regalo de bodas: un suplemento de amor que transforma tu amor de criatura y lo hace capaz de producir las obras de Dios en la mujer que amas.<br \/> &nbsp;<br \/> Son palabras para ti misteriosas, pero las entender&aacute;s poco a poco. Te aseguro que no te dejar&eacute; solo en esta empresa. Ser&eacute; siempre contigo y har&eacute; de ti el instrumento de mi amor, de mi ternura; continuar&eacute; amando a mi criatura, que se ha convertido en tu esposa, a trav&eacute;s de tus gestos de amor, de atenci&oacute;n, de compromiso, de perd&oacute;n, de dedicaci&oacute;n. En una palabra: te har&eacute; capaz de amar como yo amo, porque te dar&eacute; una fuerza nueva para amar, que es mi propio amor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Padre Giordano Muraro La mujer que tienes al lado, emocionada, con traje de novia, es m&iacute;a. Yo la he creado. Yo la he querido desde siempre; antes que tu, y m&aacute;s que tu. Por ella no dud&eacute; en dar mi vida. Tengo grandes proyectos para ella. Te la conf&iacute;o. La tomar&aacute;s de mis manos &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/carta-de-dios-a-un-recien-casado-y-tambien-para-ella-2\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCarta de Dios a un reci\u00e9n casado (y tambi\u00e9n para&nbsp;ella)\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-32393","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=32393"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32393\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=32393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=32393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=32393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}