{"id":32394,"date":"2016-06-13T12:04:02","date_gmt":"2016-06-13T17:04:02","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/8-razones-para-hacer-un-curso-de-preparacion-al-matrimonio\/"},"modified":"2016-06-13T12:04:02","modified_gmt":"2016-06-13T17:04:02","slug":"8-razones-para-hacer-un-curso-de-preparacion-al-matrimonio","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/8-razones-para-hacer-un-curso-de-preparacion-al-matrimonio\/","title":{"rendered":"8 razones para hacer un curso de preparaci\u00f3n al&nbsp;matrimonio"},"content":{"rendered":"<p><b>Por: Por tu matrimonio<\/b><\/p>\n<p align=\"justify\">Aunque la pareja piense que ya est&aacute; lista, es siempre importante que se d&eacute; la oportunidad para dialogar, guiados por expertos, acerca del compromiso que van a asumir y de las condiciones que deben tener como pareja para entregarse el uno al otro y constituir un matrimonio feliz y estable.<\/p>\n<p align=\"justify\"> Tambi&eacute;n la Iglesia, por su parte, siente la <strong>responsabilidad<\/strong> de sellar y validar sacramentalmente una uni&oacute;n s&oacute;lo cuando puede dar testimonio de que quienes celebran dicho sacramento saben lo que van a hacer y son conscientes de las responsabilidades que adquieren el uno para el otro, con la Iglesia, y con la sociedad. Por eso exige que las parejas asistan a los cursos previos al matrimonio, que ella ofrece.<\/p>\n<p align=\"justify\"> Estos curso tienen diferentes nombres, seg&uacute;n la di&oacute;cesis o regi&oacute;n: Pre-Can&aacute;; Retiros Pre-Matrimoniales; Cursillo para Novios: Programa Foccus, etc.<\/p>\n<p align=\"justify\"> Se realizan generalmente en dos etapas y por lo menos con seis meses de anterioridad a la boda, para que la pareja tenga ocasi&oacute;n de asumir los temas abordados y pueda <strong>discernir si realmente est&aacute; ya lista<\/strong>, si debe aplazar la boda y darse m&aacute;s tiempo para conocerse mejor, o definitivamente descubri&oacute; que no son el uno para el otro.<\/p>\n<p align=\"justify\"><strong>Objetivos y temas del curso de preparaci&oacute;n al matrimonio<\/strong><\/p>\n<p align=\"justify\"> Los cursos de preparaci&oacute;n al matrimonio est&aacute;n ya organizados como programas establecidos y revisados, bajo la gu&iacute;a de alguien certificado en este ramo. A trav&eacute;s de estos cursos las parejas tiene oportunidad de:<\/p>\n<p align=\"justify\"> 1.&nbsp;Dialogar sobre los temas esenciales para el conocimiento mutuo, ya que el matrimonio supone la aceptaci&oacute;n de la otra persona tal cual es.<\/p>\n<p align=\"justify\"> 2.&nbsp;Da elementos de discernimiento de la relaci&oacute;n (tests) para que la pareja eval&uacute;e hasta d&oacute;nde est&aacute;n ya listos.<\/p>\n<p align=\"justify\"> 3.&nbsp;Da la ocasi&oacute;n para que la pareja dialogue y llegue a acuerdos esenciales para la convivencia tales como:<br \/> &#8211; Estado financiero de la pareja y modo como manejar&aacute;n las finanzas<br \/> &#8211; Hijos que desean tener, tiempo en que desean tenerlos y m&eacute;todo de planificaci&oacute;n natural que usar&aacute;n para manejar su fertilidad<br \/> &#8211; Roles o funciones que cada uno espera de su pareja, en la vida de pareja, en el manejo de la casa, en el cuidado u educaci&oacute;n de los hijos.<br \/> &#8211; Elaboraci&oacute;n del proyecto u objetivo en com&uacute;n hacia al cual aspiran como personas, como pareja, y como familia.<br \/> &#8211; Forma como manejar&aacute;n las relaciones con las respectivas familias pol&iacute;ticas.<br \/> &#8211; Costumbres y tradiciones culturales o familiares que compartir&aacute;n en com&uacute;n.<br \/> &#8211; C&oacute;mo coordinar&aacute;n el trabajo o estudio que permita el desarrollo profesional o humano de cada c&oacute;nyuge.<\/p>\n<p align=\"justify\"> 4.&nbsp;Ense&ntilde;a herramientas y consejos para la comunicaci&oacute;n y el manejo de las dificultades de entendimiento.<\/p>\n<p align=\"justify\"> 5.&nbsp;Da elementos para que la pareja entienda la grandeza y sentido de la vida sexual dentro del matrimonio y consejos para que su experiencia enriquezca la uni&oacute;n de la pareja.<\/p>\n<p align=\"justify\"> 6.&nbsp;Explica el sentido y prop&oacute;sitos espec&iacute;ficos del Matrimonio y el porqu&eacute; es un Sacramento.<\/p>\n<p align=\"justify\"> 7.&nbsp;Expone los compromisos que como persona y como pareja se adquieren al contraer matrimonio.<\/p>\n<p align=\"justify\"> 8.&nbsp;Introduce al rito del matrimonio y da elementos para que la pareja empiece a preparar, en compa&ntilde;&iacute;a del sacerdote, la celebraci&oacute;n de su sacramento, en el rol de ministros, propio de la pareja dentro del ritual cat&oacute;lico e matrimonios.<\/p>\n<p align=\"justify\"><strong>Una vez concluidas las etapas del curso, la pareja recibir&aacute; in certificado que le es v&aacute;lido por un periodo de tiempo. Este certificado est&aacute; entre los requisitos exigidos para la celebraci&oacute;n del matrimonio.<\/strong><\/p>\n<p align=\"justify\"> Lo ideal es que estos cursos, como todos los que preparan a un sacramento, sean como un catecumenado, es decir un itinerario o camino de fe, que no termine con la celebraci&oacute;n del rito, sino que sea la ocasi&oacute;n para la pareja conozca m&aacute;s de su fe y se integre de manera m&aacute;s consiente a la vida de la Iglesia.<\/p>\n<p align=\"justify\"> Y para esto, nada mejor que integrarse como pareja a un grupo de actividad religiosa dentro de la parroquia. Esto les permitir&aacute; seguirse nutriendo para mantener viva su fe y sus votos de pareja.<\/p>\n<p align=\"justify\"> Para Hacer el test de preparaci&oacute;n al matrimonio que utiliza el Programa Foccus y otros programas de preparaci&oacute;n al matrimonio vea:<\/p>\n<ul>\n<li><a target=\"_blank\" href=\"http:\/\/www.portumatrimonio.org\/prepara\/v\/inventario-pre-cana\/\">Inventario Pre-Can&aacute;<\/a><\/li>\n<li><a target=\"_blank\" href=\"http:\/\/www.portumatrimonio.org\/prepara\/v\/respuestas-al-inventario-pre-matrimonial\/\">Respuestas al Inventario<\/a><\/li>\n<\/ul>\n<p align=\"justify\"><strong>Lecturas complementarias: <\/strong>Luis Valdez Castellanos, S.J., <em>Preparar el coraz&oacute;n<\/em><br \/><em><a target=\"_blank\" href=\"http:\/\/www.portumatrimonio.org\/prepara\/v\/recursos\/\"><strong>Art&iacute;culo<\/strong><\/a>&nbsp;publicado en <\/em>Por tu matrimonio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Por tu matrimonio Aunque la pareja piense que ya est&aacute; lista, es siempre importante que se d&eacute; la oportunidad para dialogar, guiados por expertos, acerca del compromiso que van a asumir y de las condiciones que deben tener como pareja para entregarse el uno al otro y constituir un matrimonio feliz y estable. Tambi&eacute;n &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/8-razones-para-hacer-un-curso-de-preparacion-al-matrimonio\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab8 razones para hacer un curso de preparaci\u00f3n al&nbsp;matrimonio\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-32394","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=32394"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32394\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=32394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=32394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=32394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}