{"id":32410,"date":"2016-06-13T12:04:44","date_gmt":"2016-06-13T17:04:44","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/muchos-esperaban-que-el-papa-francisco-relajara-la-humanae-vitae\/"},"modified":"2016-06-13T12:04:44","modified_gmt":"2016-06-13T17:04:44","slug":"muchos-esperaban-que-el-papa-francisco-relajara-la-humanae-vitae","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/muchos-esperaban-que-el-papa-francisco-relajara-la-humanae-vitae\/","title":{"rendered":"Muchos esperaban que el Papa Francisco &#8220;relajara&#8221; la Humanae&nbsp;Vitae&#8230;"},"content":{"rendered":"<p><b>Por: Miguel Cuartero Samperi<\/b><\/p>\n<p align=\"justify\">El Papa Francisco ha reafirmado de manera clara la importancia, para la familia cristiana, del documento <em>Humanae Vitae<\/em> del Papa Pablo VI. Lo hizo durante su viaje a Filipinas, en el discurso pronunciado en el encuentro con las familias en el <em>Mall Of Asia Arena<\/em> de Manila (<a target=\"_blank\" href=\"http:\/\/w2.vatican.va\/content\/francesco\/es\/speeches\/2015\/january\/documents\/papa-francesco_20150116_srilanka-filippine-incontro-famiglie.html\">aqu&iacute; el discurso competo, &iexcl;no te lo pierdas!<\/a>).<\/p>\n<p align=\"justify\"> La carta enc&iacute;clica escrita por el Papa Montini sobre el tema de la vida humana y el control de natalidad, fue publicada el 25 de julio de 1968, en la as&iacute; llamada plena \u201crevoluci&oacute;n sexual\u201d y provoc&oacute; dentro de la Iglesia Cat&oacute;lica reacciones contrastantes obteniendo inicialmente muchas cr&iacute;ticas y contestaciones por parte de expertos, te&oacute;logos, obispos y enteras conferencias episcopales.<\/p>\n<p align=\"justify\"> El documento no cuenta ciertamente con el gusto popular, no trae un mensaje inmediatamente atractivo ni f&aacute;cil de poner en pr&aacute;ctica pero describe la alta vocaci&oacute;n de la familia y de la paternidad y maternidad responsables. Es por este motivo que, todav&iacute;a hoy, est&aacute; al centro de grandes pol&eacute;micas y es considerado uno de los textos magisteriales m&aacute;s discutidos de los &uacute;ltimos decenios.<\/p>\n<p align=\"justify\"> Por una parte hay quien considera la <em>Humanae Vitae<\/em> un acto de fuerza, solitario y testarudo del Papa Pablo VI contra los pareceres de la comisi&oacute;n de expertos instituida por &eacute;l. Aquellos critican la excesiva dureza y severidad en relaci&oacute;n a las parejas cristianas al prohibir los \u201cm&eacute;todos artificiales\u201d de control de natalidad. Entre aquellos que han contestado la <em>Humanae Vitae<\/em> se elev&oacute; tambi&eacute;n la competente voz del cardenal Martini que nunca escondi&oacute; sus posiciones vanguardistas en materia de moral sexual.<\/p>\n<p align=\"justify\"> En su libro entrevista \u201cDi&aacute;logos nocturnos en Jerusal&eacute;n\u201d, el cardenal defini&oacute; el documento papal \u201cun grave da&ntilde;o\u201d que provoc&oacute; el alejamiento de muchas personas de la Iglesia. As&iacute;, la ense&ntilde;anza moral de Pablo VI fue considerada, por muchos ambientes eclesi&aacute;sticos, retr&oacute;grada, obsoleta y lejana de la mentalidad y los problemas contempor&aacute;neos de los c&oacute;nyuges cristianos.<\/p>\n<p align=\"justify\"> Por otra parte est&aacute;n aquellos que \u2013 fieles al magisterio de Pablo VI \u2013 han subrayado la belleza, la dimensi&oacute;n prof&eacute;tica y la importancia fundamental de la <em>Humanae Vitae<\/em> para la situaci&oacute;n actual de las familias. El primero de todos fue San Juan Pablo II que dedic&oacute; muchos estudios y catequesis a lo que se conoce como la \u201cteolog&iacute;a del cuerpo\u201d (sintetizada de manera clara y precisa en el libro \u201cLa sexualidad seg&uacute;n Juan Pablo II\u201d del periodista franc&eacute;s Yves Semen).<\/p>\n<p align=\"justify\"> En ning&uacute;n momento y bajo ning&uacute;n aspecto el magisterio del papa polaco se alej&oacute; de las indicaciones de Pablo VI. Del mismo modo Benedicto XVI \u2013 a cuarenta a&ntilde;os de la publicaci&oacute;n del documento \u2013 indic&oacute; que \u201cesa ense&ntilde;anza no s&oacute;lo manifiesta inalterada su verdad, sino que revela tambi&eacute;n la prudencia con la cual el problema es enfrentado\u201d.<\/p>\n<p align=\"justify\"> Ahora tambi&eacute;n el Papa Francisco muestra su voluntad de conservar la ense&ntilde;anza de la <em>Humanae Vitae<\/em> como una palabra v&aacute;lida para la Iglesia y para los cristianos de hoy. En el encuentro con las familias filipinas, al hablar de las \u201ccolonizaciones ideol&oacute;gicas que buscan destruir a la familia\u201d, el papa invit&oacute; a no perder de vista \u201cla misi&oacute;n de la familia\u201d y a \u201cdecir no a cualquier colonizaci&oacute;n pol&iacute;tica\u201d con sagacidad, habilidad y fuerza.<\/p>\n<p align=\"justify\"> Entre los grandes desaf&iacute;os que la familia est&aacute; llamada a enfrentar el papa cit&oacute; los desastres naturales, la pobreza y la emigraci&oacute;n: problemas que afligen de manera particular a Filipinas y a los pa&iacute;ses vecinos. Pero, al mismo tiempo, el \u201cmaterialismo\u201d y los \u201cestilos de vida que anulan la vida familiar y las exigencias m&aacute;s fundamentales de la moral cristiana\u201d son el fruto de una verdadera y propia \u201ccolonizaci&oacute;n ideol&oacute;gica\u201d que se catapulta contra la instituci&oacute;n familiar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Miguel Cuartero Samperi El Papa Francisco ha reafirmado de manera clara la importancia, para la familia cristiana, del documento Humanae Vitae del Papa Pablo VI. Lo hizo durante su viaje a Filipinas, en el discurso pronunciado en el encuentro con las familias en el Mall Of Asia Arena de Manila (aqu&iacute; el discurso competo, &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/muchos-esperaban-que-el-papa-francisco-relajara-la-humanae-vitae\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abMuchos esperaban que el Papa Francisco &#8220;relajara&#8221; la Humanae&nbsp;Vitae&#8230;\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-32410","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=32410"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32410\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=32410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=32410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=32410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}