{"id":32421,"date":"2016-06-13T12:05:07","date_gmt":"2016-06-13T17:05:07","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/por-que-la-impotencia-impide-el-matrimonio\/"},"modified":"2016-06-13T12:05:07","modified_gmt":"2016-06-13T17:05:07","slug":"por-que-la-impotencia-impide-el-matrimonio","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/por-que-la-impotencia-impide-el-matrimonio\/","title":{"rendered":"\u00bfPor qu\u00e9 la impotencia impide el&nbsp;matrimonio?"},"content":{"rendered":"<p><b>Por: Toscana Oggi<\/b><\/p>\n<p align=\"justify\"><em>Hace muchos a\u00f1os le\u00ed en el peri\u00f3dico que el obispo de Viterbo neg\u00f3 a una pareja de prometidos la posibilidad de casarse por la Iglesia, despu\u00e9s de que \u00e9l se quedara inv\u00e1lido en un accidente. \u00bfC\u00f3mo se explica una decisi\u00f3n de este tipo? \u00bfEl amor y la voluntad de las personas no deber\u00edan ser superiores a cualquier otra cuesti\u00f3n f\u00edsica? La situaci\u00f3n me deja muy perpleja, pero antes de expresar cualquier tipo de juicio quisiera que alguien me ayudara a entender mejor.<\/em><\/p>\n<p align=\"justify\"><em>Laura \u2013 Florencia<\/em><\/p>\n<p align=\"justify\"><em>Responde el padre Francesco Romano, profesor de Derecho Can\u00f3nico<\/em><\/p>\n<p align=\"justify\">La noticia de que el obispo de Viterbo no haya admitido la celebraci\u00f3n del sacramento del matrimonio de una pareja de prometidos, puesto que el chico qued\u00f3 impotente seguido de una accidente de tr\u00e1nsito que lo dej\u00f3 parapl\u00e9jico, provoc\u00f3 una reacci\u00f3n de indignaci\u00f3n que fue recogida por diversos \u00e1mbitos de la opini\u00f3n p\u00fablica, considerando fr\u00eda y deshumana esta decisi\u00f3n por parte de la autoridad eclesi\u00e1stica.<\/p>\n<p align=\"justify\">Comprendemos, por lo tanto, la perplejidad que nuestra lectora nos ha manifestado.<\/p>\n<p align=\"justify\">Nuestra aclaraci\u00f3n, a petici\u00f3n de la lectora, toma como punto de partida precisamente la motivaci\u00f3n que ella adopt\u00f3 para objetar la acci\u00f3n del obispo de Viterbo: <strong>\u201c\u00bfel amor y la voluntad de las dos personas no deber\u00edan ser superiores a cualquier otra cuesti\u00f3n f\u00edsica?\u201d.<\/strong><\/p>\n<p align=\"justify\">El Concilio Vaticano en la Constituci\u00f3n Pastoral <em>Gaudium et spes (GS),<\/em> define el matrimonio como <em>\u201c<\/em><em>fundada por el Creador y en posesi\u00f3n de sus propias leyes, la \u00edntima comunidad conyugal de vida y amor se establece sobre la alianza de los c\u00f3nyuges, es decir, sobre su consentimiento personal e irrevocable\u201d (GS 48,1).<\/em><\/p>\n<p align=\"justify\">El amor natural que atrae y suscita sentimientos de afecto es una realidad psicol\u00f3gica muy importante, podr\u00edamos decir previa, pero indeterminada, no calificable ni cuantificable.<\/p>\n<p align=\"justify\"><strong>El matrimonio, de hecho, nace y se funda no sobre un gen\u00e9rico sentimiento voluble, sino sobre el consenso como acto de voluntad que dos personas se manifiestan.<\/strong><\/p>\n<p align=\"justify\">Se trata de un pacto irrevocable que tiene por objeto la aceptaci\u00f3n rec\u00edproca y la donaci\u00f3n de los c\u00f3nyuges para constituir el matrimonio (can. 1057).<\/p>\n<p align=\"justify\">En otras palabras, el matrimonio no puede depender s\u00f3lo de un sentimiento natural como el amor, bastante voluble e imprevisible por naturaleza. La voluntad conyugal, en cambio, de la que emana el consentimiento, es el punto l\u00edmite en que el amor natural se especifica en amor conyugal.<\/p>\n<p align=\"justify\">Por eso, el matrimonio sobrevive a la buena y a la mala suerte aunque el amor natural se disolviera totalmente.<\/p>\n<p align=\"justify\">Para los cristianos, adem\u00e1s, este pacto es un sacramento que vuelve a los esposos signo y participaci\u00f3n <em>\u201cdel <\/em><em>misterio de unidad y amor fecundo entre Cristo y la Iglesia<\/em><em>\u201d (can. 1063)<\/em>. La donaci\u00f3n rec\u00edproca de los esposos se vuelve, de esta manera, un acto de rendimiento de culto perfecto.<\/p>\n<p align=\"justify\">A trav\u00e9s del pacto conyugal, los esposos manifiestan su consentimiento, es decir, <em>\u201c<\/em><em>constituyen entre s\u00ed un consorcio de toda la vida, ordenado por su misma \u00edndole natural al bien de los c\u00f3nyuges y a la generaci\u00f3n y educaci\u00f3n de la prole<\/em><em>\u201d (can. 1055).<\/em><\/p>\n<p align=\"justify\">Este \u201cconsorcio\u201d como acto voluntario, que lo distingue de la uni\u00f3n de hecho, no tiene solamente una extensi\u00f3n temporal, sino que expresa el envolvimiento total de los dos c\u00f3nyuges en todas sus dimensiones comunicables, tanto a nivel psicol\u00f3gico como f\u00edsico, hasta volverse \u201cuna sola carne\u201d de manera irreversible hasta la muerte.<\/p>\n<p align=\"justify\">A prop\u00f3sito de la dimensi\u00f3n f\u00edsica del matrimonio, la impotencia copulativa (<em>coeundi<\/em>) es una circunstancia que coloca a la persona en su capacidad de realizar la uni\u00f3n sexual conyugal.<\/p>\n<p align=\"justify\">\u00c9sta se llama tambi\u00e9n ley inhabitable porque declara no capaz para contraer matrimonio a la persona de cualquiera de los sexos que se encuentre en tal situaci\u00f3n, siendo un impedimento dirimente que vuelve nulo el posible matrimonio. As\u00ed est\u00e1 escrito en can. 1084:<\/p>\n<p align=\"justify\"><em>\u201c<\/em><em>La impotencia antecedente y perpetua para realizar el acto conyugal, tanto por parte del hombre como de la mujer, ya absoluta ya relativa, hace nulo el matrimonio por su misma naturaleza<\/em><em>\u201d. <\/em>De esta manera, la c\u00f3pula conyugal, lo define as\u00ed el can. 1061:<em> \u201c()<\/em><em>si los c\u00f3nyuges han realizado de modo humano el acto conyugal apto de por s\u00ed para engendrar la prole, al que el matrimonio se ordena por su misma naturaleza y mediante el cual los c\u00f3nyuges se hacen una sola carne\u201d.<\/em><\/p>\n<p align=\"justify\">Respecto a lo dicho, los esposos no pueden modificar los t\u00e9rminos del contrato, ni la autoridad eclesi\u00e1stica dispensar de aquello que es constitutivo del matrimonio por derecho natural.<\/p>\n<p align=\"justify\"><strong>La c\u00f3pula conyugal, de hecho, es solicitada por la naturaleza misma del matrimonio<\/strong>, el cual como instituci\u00f3n natural vinculada la naturaleza sexuada del hombre<em>,\u201c<\/em><em>fundada por el Creador y en posesi\u00f3n de sus propias leyes<\/em><em>\u201d<\/em> (GS 48,1).<\/p>\n<p align=\"justify\">El significado de la consumaci\u00f3n surge tambi\u00e9n de los efectos que \u00e9sta produce frente al matrimonio rato. Es conocido por todos, de hecho, que s\u00f3lo despu\u00e9s de la consumaci\u00f3n el sacramento del matrimonio no puede ser disuelto por ning\u00fan poder humano, ni por ninguna causa fuera de la muerte (can. 1141).<\/p>\n<p align=\"justify\"><strong>La rec\u00edproca aceptaci\u00f3n y donaci\u00f3n, que es objeto del consenso conyugal, involucra a toda la persona de los esposos en todas sus dimensiones, incluida la sexual<\/strong>, especificando de esa manera la diferencia de cualquier otro tipo de uni\u00f3n que no sea el matrimonio, como consorcio de toda la vida y para el cual ya no son dos, sino \u201cuna sola carne\u201d.<\/p>\n<p align=\"justify\"><strong>La incapacidad de efectuar la c\u00f3pula conyugal impide, adem\u00e1s, asumir los actos id\u00f3neos para la procreaci\u00f3n<\/strong> de la prole a la cual por su naturaleza el matrimonio es ordenado.<\/p>\n<p align=\"justify\">La capacidad de los c\u00f3nyuges de mantener actos verdaderamente conyugales, es decir, de por s\u00ed \u00a0id\u00f3neos a la procreaci\u00f3n, entra en el objeto esencial del consentimiento, no puede recibir dispensa, ni el c\u00f3nyuge tiene la facultad de renunciar a ellos espont\u00e1neamente.<\/p>\n<p align=\"justify\">Una vez que la acci\u00f3n humana ha llevado a cabo la c\u00f3pula conyugal conforme a la naturaleza del matrimonio, su posible \u00e9xito infructuoso depende s\u00f3lo de la acci\u00f3n de la naturaleza y no incide en la idoneidad de los esposos a vivir todas las dimensiones de la vida conyugal.<\/p>\n<p align=\"justify\">Respecto a la procreaci\u00f3n, los c\u00f3nyuges tienen derecho s\u00f3lo a aquellos actos de los cuales normalmente deriva la concepci\u00f3n aunque a veces eso no se verifica por circunstancias independientes de su voluntad.<\/p>\n<p align=\"justify\">Por lo tanto,<strong> a diferencia de la impotencia copulativa, la esterilidad (<em>impotentia generandi<\/em>) no vuelve nulo el matrimonio (can. 1084), a menos que haya sido ocultada al futuro c\u00f3nyuge<\/strong> de manera dolosa (can. 1098).<\/p>\n<p align=\"justify\">As\u00ed lo expresa, de hecho, el Concilio Vaticano II: <em>\u201c<\/em><em>Pero el matrimonio no ha sido instituido solamente para la procreaci\u00f3n, sino que la propia naturaleza del v\u00ednculo indisoluble entre las personas y el bien de la prole requieren que tambi\u00e9n el amor mutuo de los esposos mismos se manifieste, progrese y vaya madurando ordenadamente. Por eso, aunque la descendencia, tan deseada muchas veces, falte, sigue en pie el matrimonio como intimidad y comuni\u00f3n total de la vida y conserva su valor e indisolubilidad\u201d (GS 50,7).<\/em><\/p>\n<p align=\"justify\">Alguien podr\u00eda objetar sobre el matrimonio de los ancianos. Obviamente, sobre este punto se presume que, a pesar de la edad, a\u00fan se conserva la capacidad copulativa.<\/p>\n<p align=\"justify\">Solamente cuando la <em>impotentia coeundi<\/em> resulte cierta el matrimonio no puede ser autorizado (can. 1084), como en el caso de la decisi\u00f3n tomada por el obispo de Viterbo.<\/p>\n<p align=\"justify\">Debido a la duda, en cambio, no puede ser descartada la celebraci\u00f3n del matrimonio, que prevale como derecho natural de que goza toda persona, pero si la duda se transforma en certeza, ese matrimonio es nulo en fuerza de la ley inhabilitante que tiene por objeto la <em>impotentia coeundi<\/em> (can. 1084), que no puede dispensarse por ninguna autoridad humana siendo ley de derecho natural.<\/p>\n<p align=\"justify\">Por lo tanto, <strong>la dimensi\u00f3n f\u00edsica es un componente imprescindible<\/strong> porque entra en la estructura natural del matrimonio y no permite la realizaci\u00f3n seg\u00fan el dise\u00f1o divino, principalmente con respecto al volverse \u201cuna sola carne\u201d a trav\u00e9s de la rec\u00edproca y total donaci\u00f3n y aceptaci\u00f3n de los c\u00f3nyuges.<\/p>\n<p align=\"justify\">Todo esto en sinton\u00eda con el significado del amor conyugal que abraza a toda la persona del c\u00f3nyuge al cual se dirige.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Toscana Oggi Hace muchos a\u00f1os le\u00ed en el peri\u00f3dico que el obispo de Viterbo neg\u00f3 a una pareja de prometidos la posibilidad de casarse por la Iglesia, despu\u00e9s de que \u00e9l se quedara inv\u00e1lido en un accidente. \u00bfC\u00f3mo se explica una decisi\u00f3n de este tipo? \u00bfEl amor y la voluntad de las personas no &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/por-que-la-impotencia-impide-el-matrimonio\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab\u00bfPor qu\u00e9 la impotencia impide el&nbsp;matrimonio?\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-32421","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=32421"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32421\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=32421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=32421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=32421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}