{"id":32422,"date":"2016-06-13T12:05:09","date_gmt":"2016-06-13T17:05:09","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/no-hay-que-tenerle-miedo-a-formar-una-familia\/"},"modified":"2016-06-13T12:05:09","modified_gmt":"2016-06-13T17:05:09","slug":"no-hay-que-tenerle-miedo-a-formar-una-familia","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/no-hay-que-tenerle-miedo-a-formar-una-familia\/","title":{"rendered":"\u201cNo hay que tenerle miedo a formar una&nbsp;familia\u201d"},"content":{"rendered":"<p><b>Por: Conferencia Episcopal de Colombia<\/b><\/p>\n<p align=\"justify\">As&iacute; lo afirm&oacute; monse&ntilde;or Carlos Germ&aacute;n Mesa Ru&iacute;z, al hacer una reflexi&oacute;n acerca del sacramento del matrimonio, en el marco de la fiesta de la Sagrada Familia, que celebran los cat&oacute;licos el 28 de diciembre.<br \/> &nbsp;<br \/> &quot;Las personas que quieren formar una familia necesariamente tienen que definir ese camino y esos ideales (&#8230;) Para fundar una familia hay que hacerlo sobre roca y esa roca es el sacramento del matrimonio&quot;, expres&oacute; el prelado.<br \/> &nbsp;<br \/> Monse&ntilde;or Mesa Ru&iacute;z indic&oacute; que a los hogares de hoy les falta evangelizaci&oacute;n y perder el miedo a ser evangelizados, &quot;ellos prefieren vivir una vida m&aacute;s sin compromiso y que no los sacuda el fundamento de la vida cristiana, principalmente la fe&quot;.<br \/> &nbsp;<br \/> El obispo de Socorro y San Gil record&oacute; como la Iglesia, nos invita hoy, en el d&iacute;a de la Sagrada Familia, a mirar a la Familia de Nazareth, la formada por Jes&uacute;s, Mar&iacute;a y Jos&eacute;, como &quot;maravilloso ejemplo&quot;.<br \/> &nbsp;<br \/> &quot;Que la Sagrada Familia modelo ideal de vida cristiana y de discipulado misionero, sea ese s&iacute;mbolo de uni&oacute;n a imitar en las familias, para adquirir las virtudes que debe tener un padre, una madre y unos hijos&quot;, dijo el jerarca.<br \/> &nbsp;<br \/> Por &uacute;ltimo el obispo reiter&oacute; que &quot;el matrimonio es y sigue siendo un sacramento indisoluble&quot; y que la Iglesia debe acercarse a las parejas en dificultad &quot;con comprensi&oacute;n, perd&oacute;n y misericordia&quot;, por lo que insisti&oacute; en que el reto para esta instituci&oacute;n es continuar trabajando desde el evangelio con las nuevas parejas y ofrecer una formaci&oacute;n s&oacute;lida.<br \/> &nbsp;<br \/><em><a target=\"_blank\" href=\"http:\/\/www.cec.org.co\/noticias\/3812-no-hay-que-tenerle-miedo-a-formar-una-familia\"><strong>Art&iacute;culo<\/strong><\/a> originalmente publicado por Conferencia Episcopal de Colombia<\/em><br \/> &nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Conferencia Episcopal de Colombia As&iacute; lo afirm&oacute; monse&ntilde;or Carlos Germ&aacute;n Mesa Ru&iacute;z, al hacer una reflexi&oacute;n acerca del sacramento del matrimonio, en el marco de la fiesta de la Sagrada Familia, que celebran los cat&oacute;licos el 28 de diciembre. &nbsp; &quot;Las personas que quieren formar una familia necesariamente tienen que definir ese camino y &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/no-hay-que-tenerle-miedo-a-formar-una-familia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab\u201cNo hay que tenerle miedo a formar una&nbsp;familia\u201d\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-32422","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=32422"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32422\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=32422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=32422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=32422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}