{"id":32440,"date":"2016-06-13T12:05:53","date_gmt":"2016-06-13T17:05:53","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/que-es-el-matrimonio\/"},"modified":"2016-06-13T12:05:53","modified_gmt":"2016-06-13T17:05:53","slug":"que-es-el-matrimonio","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/que-es-el-matrimonio\/","title":{"rendered":"\u00bfQu\u00e9 es el&nbsp;Matrimonio?"},"content":{"rendered":"<p><b>Por: Arquidi\u00f3cesis de Le\u00f3n<\/b><\/p>\n<p align=\"justify\">Lo que Dios uni&oacute; que no lo separe el hombre&#8230;<br \/> &nbsp;<br \/> Con estas Palabras que pronuncio Jes&uacute;s, es una forma muy clara de dejar en claro, que el Matrimonio es una alianza que dura toda la vida, y aunque son palabras muy dif&iacute;ciles de pronunciar y de vivir para muchos, en especial en esta &eacute;poca posmoderna, donde el compromiso pasa a segundo plano y se prefiere vivir en la emoci&oacute;n del d&iacute;a y de la supuesta libertad.<br \/> &nbsp;<br \/> Pero el joven y la joven cat&oacute;licos que se quieren comprometer con el sacramento del matrimonio, necesitan de dejarse guiar por Jes&uacute;s, ya que lo &uacute;nico que los mantendr&aacute; unidos en el lazo del Matrimonio es el amor y el respeto que como pareja se merece el uno al otro, y que se supone es lo que se busca y encuentra en el noviazgo antes de tomar la decisi&oacute;n de casarse o no casarse.<br \/> &nbsp;<br \/> Al momento de elegir una pareja es necesario destinar un tiempo suficiente para madurar los sentimientos.<br \/> &nbsp;<br \/> Por lo tanto hay que decir que los bautizados que se unen por el matrimonio han de compartir una misma esperanza, y un mismo deseo y sentimiento de servir a Dios por medio de su entrega total hacia la pareja y santificarse en la comuni&oacute;n del matrimonio.<br \/> &nbsp;<br \/> El sacramento del matrimonio se realiza ante el altar y ante la comunidad de los creyentes. Ah&iacute; los novios dan su consentimiento de amarse y respetarse todos los d&iacute;as de su vida. Y esto que quede entendido, el sacerdote no nos casa, el solo toma la funci&oacute;n de ser testigo de la promesa que los novios est&aacute;n haciendo de una forma libre, ellos son los que pronuncian la formula, donde prometen amor, fidelidad y entrega hasta el final de su vidas.<br \/> &nbsp;<br \/> El consentimiento matrimonial se ha de dar en un acto de total libertad. En &eacute;l los esposos se entregan mutuamente y sin condiciones para amarse, realizar una vida en com&uacute;n y formar su propia familia. El amor entre el hombre y la mujer tiene como fruto el nacimiento de nuevas vidas que aseguran la conservaci&oacute;n de la especie humana, que renueve la sociedad y se manifieste el misterio de la vida.<br \/> &nbsp;<br \/> El sentido m&aacute;s profundo del Matrimonio cristiano radica en que las parejas no s&oacute;lo van a unirse y convivir con el ser elegido y deseado, sino con un hijo o una hija de Dios. Por ello, el amor matrimonial tiene un car&aacute;cter Sagrado y ha servido para simbolizar el amor que tiene Dios hacia el alma humana y el amor de Cristo a su Iglesia.<br \/> &nbsp;<br \/> Y lo dice de una manera muy clara san Pablo en su carta a los Efesios 5,25 ss.<br \/> &nbsp;<br \/> \u201cUstedes Maridos amen a sus mujeres, como Cristo am&oacute; a su Iglesia y se entrego por ella para santificarla. El que ama a su mujer, a s&iacute; mismo se ama y nadie aborrece su propia carne, sino que la alimenta y abriga como Cristo a su Iglesia, porque somos miembros de su cuerpo. Por esto el hombre dejar&aacute; a su padre y su madre para unirse a su esposa, y los dos llegaran a ser como uno solo.\u201d<br \/> &nbsp;<br \/> Por lo tanto el matrimonio es:<br \/> &nbsp;<br \/> v Comunidad de vida y amor<br \/> &nbsp;<br \/> v Comunidad sacramental<br \/> &nbsp;<br \/> v Comunidad de ayuda e integraci&oacute;n mutua<br \/> &nbsp;<br \/> v Comunidad paternal de procreaci&oacute;n y educaci&oacute;n<br \/> &nbsp;<br \/> v Comunidad apost&oacute;lica<br \/> &nbsp;<br \/> &nbsp;<br \/> &nbsp;<br \/><em><a target=\"_blank\" href=\"http:\/\/arquideleon.org\/index.php\/formacion-cristiana\/formacion-en-general\/268-ique-es-el-matrimonio\"><strong>Art&iacute;culo<\/strong><\/a> originalmente publicado por Arquidi&oacute;cesis de Le&oacute;n<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Arquidi\u00f3cesis de Le\u00f3n Lo que Dios uni&oacute; que no lo separe el hombre&#8230; &nbsp; Con estas Palabras que pronuncio Jes&uacute;s, es una forma muy clara de dejar en claro, que el Matrimonio es una alianza que dura toda la vida, y aunque son palabras muy dif&iacute;ciles de pronunciar y de vivir para muchos, en &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/que-es-el-matrimonio\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab\u00bfQu\u00e9 es el&nbsp;Matrimonio?\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-32440","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=32440"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32440\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=32440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=32440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=32440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}