{"id":32466,"date":"2016-06-13T12:06:53","date_gmt":"2016-06-13T17:06:53","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/cuando-las-familias-se-separan-mucho-tiempo-terminan-dividiendose\/"},"modified":"2016-06-13T12:06:53","modified_gmt":"2016-06-13T17:06:53","slug":"cuando-las-familias-se-separan-mucho-tiempo-terminan-dividiendose","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/cuando-las-familias-se-separan-mucho-tiempo-terminan-dividiendose\/","title":{"rendered":"\u201cCuando las familias se separan mucho tiempo terminan&nbsp;dividi\u00e9ndose\u201d"},"content":{"rendered":"<p><b>Por: Aciprensa<\/b><\/p>\n<p align=\"justify\">Para afrontar los nuevos retos a los que la familia se enfrenta hoy d&iacute;a, la Iglesia en Am&eacute;rica Latina necesita trabajar m&aacute;s a fondo en \u201cpreparar a las familias\u201d, destac&oacute; el obispo de Juigalpa (Nicaragua), monse&ntilde;or&nbsp;S&oacute;crates Ren&eacute; S&aacute;ndigo Jir&oacute;n.<br \/> &nbsp;<br \/> Desde la ciudad de Roma, donde participa en el S&iacute;nodo de los obispos para la familia del 5 al 19 de octubre, monse&ntilde;or S&aacute;ndigo explic&oacute; a ACI Prensa que \u201ces interesante ver que <strong>no se trata de volver a costumbres del pasado, sino preparar a las familias para que enfrenten los nuevos retos<\/strong>, las nuevas formas de vida\u201d.<br \/> &nbsp;<br \/> El prelado afirm&oacute; que <strong>en Nicaragua, las leyes \u201cpor no estar bien formuladas y con una buena inducci&oacute;n m&aacute;s bien han intensificado y engrandecido la violencia en la familia\u201d.<\/strong><\/p>\n<p align=\"justify\"> \u201cConsiderando que nosotros tenemos que acompa&ntilde;ar m&aacute;s a la familia, creo que es obvio que un obispo de Nicaragua hable de <strong>las afectaciones externas contra la familia: la pobreza, la migraci&oacute;n, la violencia, producto todav&iacute;a de esa cultura machista<\/strong>\u201d, insisti&oacute;.<br \/> &nbsp;<br \/> Nicaragua ha sido un pa&iacute;s de <strong>migraci&oacute;n<\/strong> continua. Tiempo atr&aacute;s sus migrantes se dirig&iacute;an hacia los Estados Unidos, pero hoy d&iacute;a, hacia los pa&iacute;ses vecinos, y de manera particular hacia Costa Rica. \u201cEsto ha tra&iacute;do como consecuencia que <strong>cuando las familias se separan por mucho tiempo terminan dividi&eacute;ndose y destruy&eacute;ndose, porque est&aacute; la parte de familia que se queda, y la que se fue, que muchas veces crea una nueva familia<\/strong>\u201d, dijo.<br \/> &nbsp;<br \/> \u201cLas consecuencias de esto son <strong>hijos sin padres, y en muchos casos, si tienen padres sustitutos han habido violaciones y abusos de menores\u2026<\/strong> entonces, para nosotros, ese es un reto pastoral que tratamos de enfrentar dando un <strong>acompa&ntilde;amiento a las familias<\/strong>. Y en esta l&iacute;nea, hemos creado un plan pastoral declarando el a&ntilde;o 2014 como el a&ntilde;o de la familia, desarrollando acciones nacionales, diocesanas, parroquiales, para fortalecer esta instituci&oacute;n\u201d.<br \/> &nbsp;<br \/> Para monse&ntilde;or S&aacute;ndigo, <strong>la transmisi&oacute;n de la fe en la familia es un eslab&oacute;n fundamental para la construcci&oacute;n de la sociedad<\/strong>, por eso destaca una <strong>problem&aacute;tica que afecta a los j&oacute;venes de hoy d&iacute;a: el miedo al compromiso.<\/strong><br \/> &nbsp;<br \/> \u201cOtro fen&oacute;meno que nos afecta es la <strong>inestabilidad<\/strong> de las familias producto del temor que hay al Sacramento del matrimonio, hay p&aacute;nico a la continuidad. <strong>El hombre nicarag&uuml;ense no se arriesga, porque en su cultura ha transcurrido de generaci&oacute;n en generaci&oacute;n una costumbre de tener varias mujeres, una oficial y otra m&aacute;s. Y eso se convierte para m&iacute; en un gran reto<\/strong>\u201d, se&ntilde;al&oacute;.<br \/> &nbsp;<br \/> Por &uacute;ltimo, el obispo lament&oacute; la tragedia de los <strong>migrantes<\/strong> latinoamericanos que viajan a los Estados Unidos en busca de un futuro mejor y a menudo caen en las <strong>mafias, abusos sexuales y el tr&aacute;fico de &oacute;rganos<\/strong>. De manera especial lament&oacute; la <strong>tendencia de las familias centroamericanas de enviar a sus hijos peque&ntilde;os a la frontera solos<\/strong>.<br \/> &nbsp;<br \/> \u201cEs un fen&oacute;meno, porque mientras en Honduras y El Salvador se habla de miles de ni&ntilde;os, las estad&iacute;sticas arrojaron que de Nicaragua fueron solo 52 ni&ntilde;os. Es parad&oacute;jico, porque el nicarag&uuml;ense no est&aacute; emigrando mucho a Estados Unidos, es m&aacute;s a Costa Rica. Por ende, un nicarag&uuml;ense de clase pobre, con necesidades que va en b&uacute;squeda de trabajo\u201d, concluy&oacute;.<br \/> &nbsp;<br \/><em>&nbsp;<br \/> <a target=\"_blank\" href=\"https:\/\/www.aciprensa.com\/noticias\/cuando-las-familias-se-separan-mucho-tiempo-terminan-dividiendose-y-destruyendose-18878\/\"><strong>Art&iacute;culo<\/strong><\/a> originalmente publicado por Aciprensa<\/em><br \/> &nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Aciprensa Para afrontar los nuevos retos a los que la familia se enfrenta hoy d&iacute;a, la Iglesia en Am&eacute;rica Latina necesita trabajar m&aacute;s a fondo en \u201cpreparar a las familias\u201d, destac&oacute; el obispo de Juigalpa (Nicaragua), monse&ntilde;or&nbsp;S&oacute;crates Ren&eacute; S&aacute;ndigo Jir&oacute;n. &nbsp; Desde la ciudad de Roma, donde participa en el S&iacute;nodo de los obispos &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/cuando-las-familias-se-separan-mucho-tiempo-terminan-dividiendose\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab\u201cCuando las familias se separan mucho tiempo terminan&nbsp;dividi\u00e9ndose\u201d\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-32466","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=32466"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32466\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=32466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=32466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=32466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}