{"id":32468,"date":"2016-06-13T12:07:00","date_gmt":"2016-06-13T17:07:00","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/hijos-el-don-mas-precioso-del-matrimonio\/"},"modified":"2016-06-13T12:07:00","modified_gmt":"2016-06-13T17:07:00","slug":"hijos-el-don-mas-precioso-del-matrimonio","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/hijos-el-don-mas-precioso-del-matrimonio\/","title":{"rendered":"Hijos, el don m\u00e1s precioso del&nbsp;matrimonio"},"content":{"rendered":"<p><b>Por: Clarissa Oliveira<\/b><\/p>\n<p align=\"justify\"> En la ma&ntilde;ana de este martes, 7 de octubre, en el Vaticano, los padre sinodales dieron continuidad a las intervenciones en el S&iacute;nodo sobre la familia. En estos dos primeros d&iacute;as 70 padres sinodales hablaron durante las conferencias y las intervenciones.<\/p>\n<p align=\"justify\"> La tercera Congregaci&oacute;n general prosigui&oacute; con el tema previsto seg&uacute;n el orden del Instrumentum laboris: \u201cEvangelio de la familia y ley natural\u201d (1 parte, Cap 3) y \u201cLa familia y la vocaci&oacute;n de la persona en Cristo\u201d (1 parte, Cap 4).<\/p>\n<p align=\"justify\"> Al inicio de la Congregaci&oacute;n, el cardenal Sodano, por designaci&oacute;n del Papa Francisco, anunci&oacute; que el Consistorio convocado por el Papa para el pr&oacute;ximo d&iacute;a 20 de octubre ser&aacute; dedicado a la situaci&oacute;n de Medio Oriente, con base en los resultados de la reuni&oacute;n de algunos representantes pontificios y de los superiores de los dicasterios competentes, en la &uacute;ltima semana. El tema del Consistorio ser&aacute; representado por el cardenal Pietro Parolin, Secretario de Estado, y contar&aacute; con la presencia de seis patriarcas orientales y por el Patriarca Latino de Jerusal&eacute;n, S.S. Fouad Twal.<\/p>\n<p align=\"justify\"> La cuesti&oacute;n de las dificultades de las familias de Medio Oriente, frente a la realidad del conflicto, fue el tema de las intervenciones de los padres sinodales. Esas familias viven en situaciones dram&aacute;ticas por el hecho de defender y vivir la fe, hecho que se ve reflejado en sus vidas. Una de las propuestas de los interlocutores fue que el S&iacute;nodo sea un mensaje de proximidad a esas familias.<\/p>\n<p align=\"justify\"> Algunos puntos que se destacaron de las intervenciones fueron presentados en el <em>briefing <\/em>de hoy.<\/p>\n<p align=\"justify\"> Es necesario un abordaje progresivo donde exista un camino por donde el fiel se aproxime al ideal de la familia cristiana y al matrimonio cristiano. El tema del abordaje progresivo fue tocado con consideraciones profundizadas, en particular la analog&iacute;a con la que el Concilio Vaticano II dice que existen elementos importantes y preciosos para la santificaci&oacute;n tambi&eacute;n fuera de la Iglesia Cat&oacute;lica.<\/p>\n<p align=\"justify\"> Una persona puede entender que existe una visi&oacute;n plena e ideal del <strong>matrimonio<\/strong> y de la familia cristiana, pero tambi&eacute;n existen elementos v&aacute;lidos e importantes de santificaci&oacute;n y amor verdadero incluso cuando no se alcaza ese ideal.<br \/> &nbsp;<br \/><strong>Catequesis matrimonial<\/strong><\/p>\n<p align=\"justify\"> Es importante tener conocimiento del <strong>Magisterio de la Iglesia<\/strong>, siendo relevante la preparaci&oacute;n en la catequesis para el matrimonio. Surge tambi&eacute;n la preocupaci&oacute;n de dar continuidad a las etapas de la vida cristiana, con el objetivo de que exista una coherencia. Una evangelizaci&oacute;n con continuidad y no epis&oacute;dica.<\/p>\n<p align=\"justify\"> Los temas importantes del d&iacute;a de hoy est&aacute;n vinculados y profundizados en la cuesti&oacute;n exeg&eacute;tica, lectura de los pasajes del Evangelio sobre el <strong>matrimonio<\/strong>, de esta forma no se pone en duda la voluntad de Jes&uacute;s, sino que se encuentran tambi&eacute;n momentos de dificultad en aquella &eacute;poca, mostrando que era necesario luchar para alcanzar la voluntad de Jes&uacute;s. La problem&aacute;tica de poner en pr&aacute;ctica las exigencias radicales del Evangelio acompa&ntilde;a toda la historia de la Iglesia.<br \/> &nbsp;<br \/><strong>Posici&oacute;n de la Iglesia<\/strong><\/p>\n<p align=\"justify\"> Muchos padres sinodales dieron ejemplos de modelos de pastorales familiares con servicios de preparaci&oacute;n para la <strong>familia<\/strong>. Fue propuesto tambi&eacute;n como tema el acompa&ntilde;amiento de aquellos que se encuentran en dificultad, con el objetivo de que se sientan amados y tengan la atenci&oacute;n de la Iglesia.<\/p>\n<p align=\"justify\"> Una intervenci&oacute;n significativa fue la preocupaci&oacute;n de verificarse con mayor precisi&oacute;n la existencia de la disposici&oacute;n para el matrimonio. O sea, la Iglesia debe ser m&aacute;s exigente al aceptar a las parejas que se presentan con la intenci&oacute;n de casarse. Este hecho busca disminuir los problemas posteriores dentro de las familias, como las crisis y hasta la misma ruptura por medio del divorcio.<\/p>\n<div class=\"multipage_separator\"><\/div>\n<div class=\"multipage_separator\"><\/div>\n<p align=\"justify\"> &nbsp;<br \/><strong>La familia<\/strong><\/p>\n<p align=\"justify\"> La cuesti&oacute;n de la misi&oacute;n de la familia, el anuncio del Evangelio a otros, dando testimonio y ayudando a aquellos que se encuentran en dificultad, fue un punto referencial. En esta cuesti&oacute;n fueron recordados los movimientos y tantos otros que, como familia, ayudan en la evangelizaci&oacute;n, raz&oacute;n por la cual los padres sinodales manifestaron gran gratitud.<\/p>\n<p align=\"justify\"> Uno de los padres sinodales dijo que \u201clos hijos son el testimonio permanente de la donaci&oacute;n rec&iacute;proca de los padres y el don m&aacute;s precioso del matrimonio. Si la Iglesia se centra en este don, la familia puede aprender a caminar junto a la Iglesia\u201d. La sociedad, a su vez, nos propone el individualismo que nos lleva al ego&iacute;smo.<\/p>\n<p align=\"justify\"> Fue propuesto el rescate del valor de la sexualidad. Se habla tanto, de forma cr&iacute;tica, de la sexualidad fuera del matrimonio, que la sexualidad conyugal parece casi la concesi&oacute;n a una imperfecci&oacute;n. La sexualidad dentro del matrimonio tiene su valor. No debemos luchar contra el sexo, sino proponer una aut&eacute;ntica sexualidad que sea camino de santificaci&oacute;n, en este camino es necesario ser paciente.<\/p>\n<p align=\"justify\"> El sacramento del matrimonio es un camino y el objetivo final es ser m&aacute;s aut&eacute;ntico en amar, ser m&aacute;s humano en llegar a la santidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Clarissa Oliveira En la ma&ntilde;ana de este martes, 7 de octubre, en el Vaticano, los padre sinodales dieron continuidad a las intervenciones en el S&iacute;nodo sobre la familia. En estos dos primeros d&iacute;as 70 padres sinodales hablaron durante las conferencias y las intervenciones. La tercera Congregaci&oacute;n general prosigui&oacute; con el tema previsto seg&uacute;n el &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/hijos-el-don-mas-precioso-del-matrimonio\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abHijos, el don m\u00e1s precioso del&nbsp;matrimonio\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-32468","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=32468"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32468\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=32468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=32468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=32468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}