{"id":32485,"date":"2016-06-13T12:07:39","date_gmt":"2016-06-13T17:07:39","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/%e2%80%8bes-un-contrasentido-casar-a-parejas-que-ya-conviven\/"},"modified":"2016-06-13T12:07:39","modified_gmt":"2016-06-13T17:07:39","slug":"%e2%80%8bes-un-contrasentido-casar-a-parejas-que-ya-conviven","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/%e2%80%8bes-un-contrasentido-casar-a-parejas-que-ya-conviven\/","title":{"rendered":"\u200b\u00bfEs un contrasentido casar a parejas que ya&nbsp;conviven?"},"content":{"rendered":"<p><b>Por: Henry Vargas Holgu\u00edn<\/b><\/p>\n<p align=\"justify\">Hay diferentes tipolog&iacute;as de convivencia entre un hombre y una mujer. Entre estas est&aacute;n las llamadas relaciones de concubinato o las uniones de hecho o las uniones \u201clibres\u201d o, seg&uacute;n el Concilio Vaticano II, el amor libre (pongo la palabra libre entre comillas porque la verdadera uni&oacute;n libre es el matrimonio sacramental).<br \/> &nbsp;<br \/> El Concilio Vaticano II dice: \u201cLa dignidad de esta instituci&oacute;n (del matrimonio) no brilla en todas partes con el mismo esplendor, puesto que est&aacute; oscurecida por la poligamia, la epidemia del divorcio, el llamado amor libre y otras deformaciones; es m&aacute;s, el amor matrimonial queda frecuentemente profanado por el ego&iacute;smo, el hedonismo y los usos il&iacute;citos contra la generaci&oacute;n\u201d (GS, 47).<br \/> &nbsp;<br \/> En la primitiva Iglesia, a los que viv&iacute;an una relaci&oacute;n de concubinato se les llamaba la atenci&oacute;n sobre su situaci&oacute;n anticristiana y si no obedec&iacute;an a la recomendaci&oacute;n, se les sacaba de la comuni&oacute;n de la Iglesia, no permiti&eacute;ndoles que participaran en la liturgia, ya que se les trataba como excomulgados.<br \/> &nbsp;<br \/> El problema de la cohabitaci&oacute;n es muy complejo, porque pueden intervenir muchos elementos, de diversa &iacute;ndole. \u201cEn efecto, algunos se consideran como obligados por dif&iacute;ciles situaciones \u2014econ&oacute;micas, culturales y religiosas\u2014 en cuanto que, contrayendo matrimonio regular, quedar&iacute;an expuestos a da&ntilde;os, a la p&eacute;rdida de ventajas econ&oacute;micas, a discriminaciones, etc.<br \/> &nbsp;<br \/> En otros, por el contrario, se encuentra una actitud de desprecio, contestaci&oacute;n o rechazo de la sociedad, de la instituci&oacute;n familiar, de la organizaci&oacute;n socio-pol&iacute;tica o de la mera b&uacute;squeda del placer.<br \/> &nbsp;<br \/> Otros, finalmente, son empujados por la extrema ignorancia y pobreza, a veces por condicionamientos debidos a situaciones de verdadera injusticia, o tambi&eacute;n por una cierta inmadurez psicol&oacute;gica que les hace sentir la incertidumbre o el temor de atarse con un v&iacute;nculo estable y definitivo.<br \/> &nbsp;<br \/> En algunos pa&iacute;ses las costumbres tradicionales prev&eacute;n el matrimonio verdadero y propio&nbsp;solamente despu&eacute;s de un per&iacute;odo de cohabitaci&oacute;n y despu&eacute;s del nacimiento del primer hijo\u201d (Exhortaci&oacute;n apost&oacute;lica del Papa Juan Pablo II,&nbsp;<em>Familiaris consortio<\/em>, n&ordm; 81).<br \/> &nbsp;<br \/> Hay que distinguir entre las relaciones de concubinato y las relaciones de adulterio; &eacute;stas &uacute;ltimas son relaciones extramatrimoniales estando casados el hombre o la mujer o ambos.<br \/> &nbsp;<br \/> El problema m&aacute;s dif&iacute;cil es cuando no pueden contraer un matrimonio religioso porque o los dos est&aacute;n casados por la Iglesia o uno de ellos, de tal modo que no pueden contraer matrimonio porque el anterior, en principio, ser&iacute;a v&aacute;lido.<br \/> &nbsp;<br \/> Tanto en un caso como en el otro, las relaciones sexuales que se den al interior son lo que el catecismo llama \u201cfornicaci&oacute;n\u201d. Aunque las relaciones de concubinato tengan el reconocimiento por parte de un Estado (el matrimonio civil o las uniones de hecho), ante Dios y la Iglesia no dejan de ser pecado; y los concubinos, solteros en situaci&oacute;n irregular.<br \/> &nbsp;<br \/> \u201cCada uno de estos elementos (del concubinato) pone a la Iglesia serios problemas pastorales, por las graves consecuencias religiosas y morales que de ellos derivan (p&eacute;rdida del sentido religioso del matrimonio visto a la luz de la Alianza de Dios con su pueblo, privaci&oacute;n de la gracia del sacramento, grave esc&aacute;ndalo), as&iacute; como tambi&eacute;n por las consecuencias sociales (destrucci&oacute;n del concepto de familia, atenuaci&oacute;n del sentido de fidelidad incluso hacia la sociedad, posibles traumas psicol&oacute;gicos en los hijos y afirmaci&oacute;n del ego&iacute;smo)\u201d, se&ntilde;ala la&nbsp;<em>Familiaris Consortio<\/em>&nbsp;(81).<br \/> &nbsp;<br \/> Las parejas que est&aacute;n conviviendo sin haberse casado por la Iglesia no s&oacute;lo se pueden casar sino que la Iglesia les anima a ello, si quieren, obviamente, que la relaci&oacute;n de pareja sea bendecida por Dios, sea camino de santificaci&oacute;n y d&eacute; frutos de vida eterna.<\/p>\n<div class=\"multipage_separator\"><\/div>\n<p align=\"justify\"> &nbsp;<br \/> Su relaci&oacute;n se puede formalizar, perfeccionar y santificar en el matrimonio sacramental. Hay un dicho que dice: \u201cRectificar es de sabios\u201d; y hay otro que dice: \u201cErrar es humano, pero inhumano permanecer en el error\u201d.<br \/> &nbsp;<br \/> Por tanto, las uniones de hecho o las personas que mantienen una relaci&oacute;n de concubinato, si quieren enmendar esta situaci&oacute;n, &iexcl;felicidades! Claro que se puede rectificar el camino. Busquen a un sacerdote que los gu&iacute;e. Acudan al sacramento de la reconciliaci&oacute;n, fortal&eacute;zcanse con la comuni&oacute;n y la oraci&oacute;n.<br \/> &nbsp;<br \/> Dentro de las relaciones de concubinato hay tres clases de parejas: las constituidas por personas que no tienen un v&iacute;nculo anterior, las que han contra&iacute;do matrimonio solamente civil y las constituidas por las personas que han enviudado. El arreglo que se pide o se contempla es igual en todo caso; la recomendaci&oacute;n para que puedan recibir los sacramentos es: o que se separen o que se casen.<br \/> &nbsp;<br \/> \u201cLos pastores y la comunidad eclesial\u2026 se acercar&aacute;n a los que conviven, con discreci&oacute;n y respeto;\u2026 para que puedan allanarles el camino hacia la regularizaci&oacute;n de su situaci&oacute;n\u2026 haci&eacute;ndoles comprender la rica realidad humana y sobrenatural del matrimonio-sacramento\u201d, destaca la&nbsp;<em>Familiaris consortio<\/em>&nbsp;(81).<\/p>\n<p align=\"justify\"> La fe fortalece la relaci&oacute;n y da paso al matrimonio, y casarse por la Iglesia no s&oacute;lo&nbsp;es apostar por un matrimonio para toda la vida, sino por un matrimonio de calidad en el que se respeta al otro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Henry Vargas Holgu\u00edn Hay diferentes tipolog&iacute;as de convivencia entre un hombre y una mujer. Entre estas est&aacute;n las llamadas relaciones de concubinato o las uniones de hecho o las uniones \u201clibres\u201d o, seg&uacute;n el Concilio Vaticano II, el amor libre (pongo la palabra libre entre comillas porque la verdadera uni&oacute;n libre es el matrimonio &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/%e2%80%8bes-un-contrasentido-casar-a-parejas-que-ya-conviven\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab\u200b\u00bfEs un contrasentido casar a parejas que ya&nbsp;conviven?\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-32485","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=32485"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32485\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=32485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=32485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=32485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}