{"id":32510,"date":"2016-06-13T12:08:25","date_gmt":"2016-06-13T17:08:25","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/en-europa-el-matrimonio-se-entiende-como-union-de-varon-y-mujer\/"},"modified":"2016-06-13T12:08:25","modified_gmt":"2016-06-13T17:08:25","slug":"en-europa-el-matrimonio-se-entiende-como-union-de-varon-y-mujer","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/en-europa-el-matrimonio-se-entiende-como-union-de-varon-y-mujer\/","title":{"rendered":"En Europa, el matrimonio se entiende como uni\u00f3n de var\u00f3n y&nbsp;mujer"},"content":{"rendered":"<p><b>Por: AICA<\/b><\/p>\n<p align=\"justify\"> La Corte Europea de Derechos Humanos afirm&oacute; que negar a las uniones homosexuales el car&aacute;cter de \u201cmatrimonio\u201d no supone una violaci&oacute;n de los Derechos Humanos. El Tribunal se&ntilde;al&oacute; que mientras \u201calgunos estados miembro han extendido el matrimonio a parejas del mismo sexo\u201d, la ley europea establece que el derecho de hombres y mujeres a casarse libremente \u201cno puede construirse como una imposici&oacute;n de una obligaci&oacute;n sobre los estados miembro para permitirle el acceso a las parejas del mismo sexo\u201d.<\/p>\n<p align=\"justify\"> La sentencia se da luego que un demandante finland&eacute;s acusara a su pa&iacute;s de no querer reconocer su cambio de sexo, de hombre a mujer, realizado en 2009. Finlandia, que no reconoce las uniones gay, se&ntilde;al&oacute; que no pod&iacute;a reconocer el cambio de sexo del demandante que estaba v&aacute;lidamente casado con una mujer. En todo caso, explicaron, solo pod&iacute;a reconocer la nueva identidad si el matrimonio con la esposa se disolv&iacute;a mediante el divorcio o su transformaci&oacute;n en una sociedad civil.<\/p>\n<p align=\"justify\"> El demandante indic&oacute; que el rechazo de aceptar el \u201cmatrimonio\u201d de dos \u201cmujeres\u201d y su impacto en el reconocimiento de su nueva identidad eran una violaci&oacute;n de sus derechos humanos, pero el m&aacute;ximo tribunal europeo para los Derechos Humanos determin&oacute; el 16 de julio que no hab&iacute;a violaci&oacute;n alguna, y afirm&oacute; que la inexistencia de amparo jur&iacute;dico a las uniones gay en aqu&eacute;l pa&iacute;s no constituye una violaci&oacute;n a la Convenci&oacute;n Europea de Derechos Humanos.<\/p>\n<p align=\"justify\"> La Corte precis&oacute; que, si bien las personas tienen el derecho a \u201ccasarse y tener una familia\u201d, esto no puede interpretarse de modo tal que se acepte el matrimonio gay. El alto tribunal explic&oacute; que la Convenci&oacute;n Europea de Derechos Humanos \u201cconsagra el concepto tradicional de matrimonio como el formado por un var&oacute;n y una mujer\u201d.<\/p>\n<p align=\"justify\"> La Corte tambi&eacute;n resalt&oacute; que el demandante no puede alegar que \u201cexiste un consenso europeo para permitir el matrimonio del mismo sexo\u201d dado que solo diez estados-miembro lo reconocen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: AICA La Corte Europea de Derechos Humanos afirm&oacute; que negar a las uniones homosexuales el car&aacute;cter de \u201cmatrimonio\u201d no supone una violaci&oacute;n de los Derechos Humanos. El Tribunal se&ntilde;al&oacute; que mientras \u201calgunos estados miembro han extendido el matrimonio a parejas del mismo sexo\u201d, la ley europea establece que el derecho de hombres y mujeres &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/en-europa-el-matrimonio-se-entiende-como-union-de-varon-y-mujer\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEn Europa, el matrimonio se entiende como uni\u00f3n de var\u00f3n y&nbsp;mujer\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-32510","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=32510"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32510\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=32510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=32510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=32510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}