{"id":32513,"date":"2016-06-13T12:08:29","date_gmt":"2016-06-13T17:08:29","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/cohabitacion-union-libre-y-matrimonio\/"},"modified":"2016-06-13T12:08:29","modified_gmt":"2016-06-13T17:08:29","slug":"cohabitacion-union-libre-y-matrimonio","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/cohabitacion-union-libre-y-matrimonio\/","title":{"rendered":"Cohabitaci\u00f3n, uni\u00f3n libre y&nbsp;matrimonio"},"content":{"rendered":"<p><b>Por: Por tu matrimonio<\/b><\/p>\n<p align=\"justify\">La cohabitaci&oacute;n&nbsp;o uni&oacute;n libre&nbsp;es el tipo de relaci&oacute;n que establece una pareja cuando&nbsp;<strong>sin estar casada<\/strong>&nbsp;por la Iglesia o por lo civil y sin tener intenci&oacute;n definitiva de casarse, <strong>comparten techo y cama<\/strong>. La uni&oacute;n libre &quot;de hecho&quot; es cuando una pareja vive como matrimonio estable, sin haberse casado. La diferencia entre la cohabitaci&oacute;n y la uni&oacute;n libre de hecho es que la primera carece de todo compromiso e institucionalidad (matrimonio a prueba), mientras que en las segundas hay intenci&oacute;n de permanecer viviendo as&iacute;.<\/p>\n<p align=\"justify\">Con todo, tanto la <strong>cohabitaci&oacute;n <\/strong>como la <strong>uni&oacute;n libre de hecho<\/strong>, se caracterizan por su <strong>inestabilidad y falta de compromiso<\/strong> de la pareja entre s&iacute;, ante la sociedad y frente a los hijos que puedan surgir de la relaci&oacute;n. Por eso, la Iglesia Cat&oacute;lica advierte repetidas veces a sus fieles sobre el gran peligro de <strong>arriesgar sus vidas emotivas<\/strong> dentro de este tipo de relaci&oacute;n e invita a las parejas a que consideren los <strong>beneficios<\/strong> de un <strong>verdadero matrimonio<\/strong>:<\/p>\n<ul type=\"disc\">\n<li>Al entregar sus cuerpo y compartir el mismo espacio vital, lo piensen o no, las personas est&aacute;n dando mucho de s&iacute; y poniendo en juego su intimidad, su futuro, su emotividad y el futuro de una posible creatura, sin que se ofrezca ninguna garant&iacute;a de ser aceptado, amado y respetado \u201cpara siempre\u201d (indisolubilidad) como lo ofrece en cambio un compromiso matrimonial.<\/li>\n<li>En muchos casos, la uni&oacute;n libre se toma como una forma de \u201censayar\u201d o \u201cprobar\u201d si la relaci&oacute;n puede o no funcionar. Se parte por tanto del hecho que en cualquier momento me van a dejar o puedo dejar a la otra persona. Por eso, se pregunta el Catecismo de la Iglesia Cat&oacute;lica, &iquest;<em>qu&eacute; puede significar una uni&oacute;n en la que las personas no se comprometen entre s&iacute; y testimonian con ello una falta de confianza en el otro, en s&iacute; mismo, o en el porvenir<\/em>? (CIC 2390).<\/li>\n<li>La gran mayor&iacute;a de las uniones libres terminan acab&aacute;ndose en los primeros 5 a&ntilde;os y entre las que parecen \u201cestables\u201d hay m&aacute;s divorcios que entre los casados.<\/li>\n<li>Son muchas menos las parejas que despu&eacute;s de convivir se casan que las que deciden casarse sin haber convivido antes.<\/li>\n<li>Los problemas de salud (causado generalmente por abuso de alcohol, droga y tabaco), los malos tratos, el desempleo y los problemas con los hijos son mucho m&aacute;s frecuentes entre personas que viven en uni&oacute;n libre.<\/li>\n<li>La vida sexual que en s&iacute; misma es \u201cla entrega m&aacute;s &iacute;ntima\u201d entre un hombre y una mujer, se ve contradictoriamente afectada en la uni&oacute;n libre dada la falta de entrega y compromiso real en que se vive. De ah&iacute; el dolor y efectos psicol&oacute;gicos que padecen quienes terminan siendo \u201cdejados\u201d, pues se sienten enga&ntilde;ados, frustrados y ofendidos en su dignidad y confianza en el amor del otro. A este da&ntilde;o se agrega el hecho que quienes viven en uni&oacute;n libre no desean tampoco el compromiso de un hijo. Por eso su entrega est&aacute; marcada por la falta de generosidad que supone el estar abiertos a la vida. En pocas palabras, como lo ense&ntilde;a la Iglesia, la entrega sexual supone el compromiso matrimonial. De otro modo se transforma en un acto ego&iacute;sta y profundamente da&ntilde;ino y por eso es pecaminoso.<\/li>\n<li>Un alto porcentaje de j&oacute;venes hispanos comienzan a cohabitar y reproducirse desde muy temprana edad. Como consecuencia, estos j&oacute;venes, especialmente la madre, posee menores estudios y menores posibilidades de trabajo e ingresos. Se produce as&iacute; una consolidaci&oacute;n y profundizaci&oacute;n de la pobreza.<\/li>\n<li>En familias de precaria constituci&oacute;n, como lo son las que cohabitan, hay mayores <strong>&iacute;ndices de violencia<\/strong><strong>.<\/strong><\/li>\n<li>Los hijos de convivientes tienen menores &iacute;ndices de escolaridad.<\/li>\n<li>La primera escuela del amor es la familia. Pero, &iquest;qu&eacute; clase de relaci&oacute;n pueden ense&ntilde;ar quienes no fundan sus relaciones en la responsabilidad y el compromiso incondicional?<\/li>\n<\/ul>\n<p align=\"justify\">Tampoco<strong> el m<\/strong><strong>atrimonio civil<\/strong><strong> re&uacute;ne las caracter&iacute;sticas necesarias de una <\/strong><strong>uni&oacute;n para siempre<\/strong> ni est&aacute; basado, como el matrimonio cat&oacute;lico, en el amor de Dios que trasciende los impulsos humanos e invita por tanto a una entrega a imitaci&oacute;n de Cristo en la Cruz.<\/p>\n<h3><strong>&iquest;C&oacute;mo puede una pareja que lleva muchos a&ntilde;os de uni&oacute;n libre casarse en el templo parroquial?<\/strong><\/h3>\n<p align=\"justify\">Lo m&aacute;s pr&aacute;ctico es hablar con el p&aacute;rroco o el di&aacute;cono de la Iglesia donde se van a casar. Este tipo de matrimonio se conoce tambi&eacute;n como <strong>\u201cconvalidaci&oacute;n<\/strong>\u201d y por eso, si se estima conveniente, el p&aacute;rroco exime a los contrayentes del requisito del curso pre-matrimonial y organiza para ellos <strong>ceremonias privadas<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Por tu matrimonio La cohabitaci&oacute;n&nbsp;o uni&oacute;n libre&nbsp;es el tipo de relaci&oacute;n que establece una pareja cuando&nbsp;sin estar casada&nbsp;por la Iglesia o por lo civil y sin tener intenci&oacute;n definitiva de casarse, comparten techo y cama. La uni&oacute;n libre &quot;de hecho&quot; es cuando una pareja vive como matrimonio estable, sin haberse casado. La diferencia entre &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/cohabitacion-union-libre-y-matrimonio\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCohabitaci\u00f3n, uni\u00f3n libre y&nbsp;matrimonio\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-32513","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=32513"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32513\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=32513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=32513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=32513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}