{"id":32515,"date":"2016-06-13T12:08:31","date_gmt":"2016-06-13T17:08:31","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/opciones-para-la-liturgia-de-matrimonios\/"},"modified":"2016-06-13T12:08:31","modified_gmt":"2016-06-13T17:08:31","slug":"opciones-para-la-liturgia-de-matrimonios","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/opciones-para-la-liturgia-de-matrimonios\/","title":{"rendered":"Opciones para la liturgia de&nbsp;matrimonios"},"content":{"rendered":"<p><b>Por: Por tu matrimonio<\/b><\/p>\n<p align=\"justify\">De todos los sacramentos de la Iglesia Cat&oacute;lica, el que tiene <strong>m&aacute;s flexibilidad<\/strong> y opciones para su celebraci&oacute;n y validez es el sacramento del matrimonio. El derecho de la Iglesia prescribe que <strong>para que sea v&aacute;lido<\/strong> un matrimonio debe de tener tres elementos b&aacute;sicos: <strong><em>el consentimiento, la bendici&oacute;n e intercambio de los anillos, y la bendici&oacute;n nupcial<\/em><\/strong>.<\/p>\n<p align=\"justify\"> <strong>Los dem&aacute;s s&iacute;mbolos<\/strong> se pueden incluir o excluir <strong>dependiendo<\/strong> de las <strong>circunstancias <\/strong>y el <strong>gusto de los novios<\/strong>, como lo son <strong>las arras<\/strong>, <strong>el lazo<\/strong>, <strong>libro y rosario,<\/strong> el ramo de <strong>flores para la Virgen,<\/strong> <strong>el velo<\/strong>, etc. Otra opci&oacute;n para la celebraci&oacute;n del matrimonio es realizarlo <strong>dentro o fuera de la Misa<\/strong>, y en el caso de un matrimonio entre una persona cat&oacute;lica y una no bautizada, la ceremonia se celebra fuera de la Misa.<\/p>\n<p align=\"justify\"><strong>El Intercambio de las Arras<\/strong><\/p>\n<p align=\"justify\">Antes de la introducci&oacute;n de los anillos en la celebraci&oacute;n del matrimonio en Espa&ntilde;a por el rito romano s&oacute;lo exist&iacute;an las arras como signo de intercambio de promesas. Una vez que las arras se reemplazaron por los anillos, estas quedaron en el rito como <strong>signo de ayuda mutua<\/strong> entre los nuevos esposos. En el pasado ha sido una constante que el marido trabaje fuera del hogar y sea el proveedor financiero de la familia, y la mujer tradicionalmente ha sido la que trabaja en el hogar y la que ha cuidado de que los bienes del hogar sean bien administrados. Por lo tanto el rito de las entrega de las arras consiste en lo siguiente: el esposo toma las arras del celebrante y las entrega a la esposa diciendo:<\/p>\n<p align=\"justify\"> N. recibe tambi&eacute;n estas arras:<br \/> son prenda del cuidado que tendr&eacute;<br \/> de que no falte lo necesario<br \/> en nuestro hogar.<\/p>\n<p align=\"justify\"> La esposa contesta recibiendo las arras:<\/p>\n<p align=\"justify\"> Yo las recibo<br \/> en se&ntilde;al del cuidado que tendr&eacute;<br \/> de que todo se aproveche<br \/> en nuestro hogar.<\/p>\n<p align=\"justify\"> En el presente, entre los hogares hispanos en los Estados Unidos, es cada d&iacute;a&nbsp; m&aacute;s com&uacute;n&nbsp; que el marido y la mujer trabajen fuera del hogar para contribuir los dos al mantenimiento econ&oacute;mico del hogar. De esta manera el formulario de arriba podr&iacute;a quedar obsoleto ya que no expresar&iacute;a la realidad de la familia actual. Por lo tanto el libro <em>Don y Promesa<\/em> hace varias sugerencias para adaptar este rito a las circunstancias presentes. Una posibilidad es que la entrega de las arras sea mutua:<\/p>\n<p align=\"justify\"> El novio entrega las arras a la novia diciendo: N. \u201cEstas arras te doy en se&ntilde;al de matrimonio\u201d.<\/p>\n<p align=\"justify\"> La novia responde: \u201cYo las recibo\u201d.<\/p>\n<p align=\"justify\"> Luego en viceversa se repite el rito, la novia entrega las arras y el novio las recibe.<\/p>\n<p align=\"justify\"> La otra sugerencia es que el novio entregue las arras despu&eacute;s de haberlas recibido del celebrante diciendo: \u201cRecibe estas arras como prenda del esfuerzo que haremos para vivir sencillamente en imitaci&oacute;n de Cristo y del Evangelio\u201d.<\/p>\n<p align=\"justify\"> La novia dice: \u201cLas recibo como se&ntilde;al del cuidado que tendremos de que nuestros bienes se compartan con los m&aacute;s pobres que encontremos por el camino\u201d( V&eacute;ase, Gomez, Ra&uacute;l, Lucatero, Heliodoro y S&aacute;nchez, Sylvia. <em>Don y Promesa: Costumbres y tradiciones en los ritos matrimoniales hispanos<\/em>. Segunda Edici&oacute;n. Instituto Nacional Hispano de Liturgia y Oregon Catholic Press: P&oacute;rtland, 2005, pp. 12-4.)<\/p>\n<p align=\"justify\"><strong>El Lazo<\/strong><\/p>\n<p align=\"justify\">El lazo s<strong>imboliza<\/strong> en la nueva pareja la <strong>uni&oacute;n indisoluble<\/strong> del matrimonio y tiene sus or&iacute;genes en la antig&uuml;edad y la Edad Media. El lazo es descrito por San Isidoro de Sevilla como una <strong>guirnalda de color blanco y p&uacute;rpura<\/strong> que se coloca sobre los hombros de los novios; el blanco simbolizando la <strong>pureza del matrimonio<\/strong> y el <strong>p&uacute;rpura la sangre de la futura generaci&oacute;<\/strong>n. (V&eacute;ase, &nbsp;Searle, Mark and Stevenson, Kenneth. <em>Documents of the Marriage Liturgy<\/em>. Collegeville, MN: The Liturgical Press, A Pueblo Book, 1992, p. 125.)<\/p>\n<p align=\"justify\"> Hace a&ntilde;os el lazo m&aacute;s com&uacute;n era una guirnalda de azares con dos c&iacute;rculos unidos por una cruz, pero <strong>ahora <\/strong>es m&aacute;s com&uacute;n <strong>dos guirnaldas en forma de rosario<\/strong>, tambi&eacute;n, unidas por una cruzo crucifijo. El lazo se coloca com&uacute;nmente despu&eacute;s del rito del matrimonio y una vez que los novios se pongan de rodillas. <strong>En Cuba y Puerto Rico<\/strong>, en lugar del lazo, <strong>se acostumbra la mantilla<\/strong> que se coloca sobre los hombros de los novios, tambi&eacute;n, en <strong>se&ntilde;al de uni&oacute;n.<\/strong>&nbsp;&nbsp;<\/p>\n<p align=\"justify\"><strong>Libro y Rosario<\/strong><\/p>\n<p align=\"justify\">En los Estados Unidos los <strong>hispanos de origen mexicano<\/strong> tienen la costumbre de entregar a los novios, despu&eacute;s del intercambio de anillos y arras, <strong>el libro y el rosario<\/strong>, que simbolizan la vida de oraci&oacute;n de los nuevos esposos. El libro suele ser un tipo de misal peque&ntilde;o; aunque hoy d&iacute;a se acostumbra m&aacute;s darles una Biblia ya que el misal no se usa m&aacute;s. Sin embargo se invita cada d&iacute;a m&aacute;s a que las familias tengan en su hogar las Sagradas Escrituras para que lean con frecuencia la Palabra de Dios en familia.<\/p>\n<p align=\"justify\"><strong>El Ramo de Flores para la Virgen<\/strong><\/p>\n<p align=\"justify\">En la Sagrada Familia, la <strong>Virgen Mar&iacute;a<\/strong> se nos presenta como <strong>modelo de esposa y madre;<\/strong> de ah&iacute; que exista la costumbre de que los nuevos esposos presenten a la Virgen un ramo de flores, no solamente para reconocerla como modelo de esposa y madre, sino tambi&eacute;n como <strong>intercesora del bienestar y &eacute;xito<\/strong> de la nueva pareja de esposos.<br \/> &nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Por tu matrimonio De todos los sacramentos de la Iglesia Cat&oacute;lica, el que tiene m&aacute;s flexibilidad y opciones para su celebraci&oacute;n y validez es el sacramento del matrimonio. El derecho de la Iglesia prescribe que para que sea v&aacute;lido un matrimonio debe de tener tres elementos b&aacute;sicos: el consentimiento, la bendici&oacute;n e intercambio de &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/opciones-para-la-liturgia-de-matrimonios\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abOpciones para la liturgia de&nbsp;matrimonios\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-32515","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=32515"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32515\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=32515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=32515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=32515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}