{"id":32531,"date":"2016-06-13T12:08:58","date_gmt":"2016-06-13T17:08:58","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/tener-un-hijo-o-mejor-un-perrito\/"},"modified":"2016-06-13T12:08:58","modified_gmt":"2016-06-13T17:08:58","slug":"tener-un-hijo-o-mejor-un-perrito","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/tener-un-hijo-o-mejor-un-perrito\/","title":{"rendered":"\u00bfTener un hijo? O mejor, un&nbsp;perrito"},"content":{"rendered":"<p><b>Por: LaFamilia.info<\/b><\/p>\n<p align=\"justify\"> Lo que antes era un anhelo de los reci&eacute;n casados, hoy ya no es su prioridad; nacen as&iacute; los denominados \u2018childfree\u2018 o \u2018dinks\u2019 (\u2018double income, no kids\u2019 que se traduce a: doble ingreso, no ni&ntilde;os) son parejas de nivel socio econ&oacute;mico medio-alto, que han decidido como proyecto de vida no tener hijos e invertir sus ingresos en ellos mismos.<\/p>\n<p align=\"justify\"> A esta realidad se refiri&oacute; el Papa Francisco hace pocos d&iacute;as: \u201cEsta cultura del bienestar de hace diez a&ntilde;os nos ha convencido: \u2018&iexcl;Es mejor no tener hijos! &iexcl;Es mejor! As&iacute; puedes ir de vacaciones, a conocer el mundo, puedes tener una casa en el campo&#8230; Est&aacute;s tranquilo\u2019. Pero quiz&aacute; sea mejor, m&aacute;s c&oacute;modo, tener un perrito, dos gatos, y el amor va a los dos gatos y al perrito. Y al final este matrimonio llega a la vejez en la soledad\u201d.<\/p>\n<p align=\"justify\"> Tener hijos es una de las decisiones m&aacute;s cruciales, y no es para menos, est&aacute; en juego una nueva vida, que ha de ser un proyecto educativo por varios a&ntilde;os. Es una gran responsabilidad, que si bien, siempre se ha reconocido as&iacute;, ahora algunos matrimonios prefieren dejarla de asumir, &iquest;por qu&eacute;? Ego&iacute;smo, egocentrismo, comodidad, materialismo, pueden ser algunas de las razones.<\/p>\n<p align=\"justify\"> Lo cierto es que no nos detendremos en las causas, sino que nos ocuparemos en destacar las bondades de tener hijos.<\/p>\n<p align=\"justify\"><strong>Bondades de tener hijos<\/strong><\/p>\n<p align=\"justify\"> Tener hijos es una de las decisiones m&aacute;s importantes de la vida y en ning&uacute;n caso se debe tomar a la ligera, ni por presi&oacute;n, ni por moda, ni por intereses particulares; s&oacute;lo hay una raz&oacute;n para traer un hijo al mundo: el amor. Amor que nace en un hombre y una mujer cuando se unen en el matrimonio. Las siguientes son algunas bondades:<br \/> &nbsp;<\/p>\n<ul>\n<li><strong>Los hijos le dan sentido a la vida,<\/strong> se convierten en el motor, en la raz&oacute;n para levantarse cada d&iacute;a, luchar por lo que se quiere y salir adelante sin importar las circunstancias.<\/li>\n<li><strong>Los hijos son la luz de los hogares,<\/strong> llegan a las familias a alegrarles la vida, a ense&ntilde;arles c&oacute;mo se debe vivir y c&oacute;mo se debe amar.<\/li>\n<li><strong>Los hijos hacen mejores personas a sus padres.<\/strong> Los ni&ntilde;os son la mejor escuela de humanidad para los adultos.<\/li>\n<li><strong>Los hijos evitan la rutina en la relaci&oacute;n conyugal.<\/strong> La convivencia se hace m&aacute;s grata, le dan felicidad a la pareja, mantienen vivo el amor entre los esposos, los hijos son la esperanza del matrimonio.<\/li>\n<li><strong>Los hijos son una motivaci&oacute;n<\/strong> <strong>permanente <\/strong>en la construcci&oacute;n de la relaci&oacute;n de pareja.<\/li>\n<li><strong>Los hijos fortalecen la uni&oacute;n matrimonial,<\/strong> en el sentido que trabajan unidos por un proyecto de vida, donde los hijos son pieza fundamental para el desarrollo del mismo.<\/li>\n<li><strong>Los hijos despiertan un amor nuevo y verdadero.<\/strong> La mayor&iacute;a de los padres aseguran sentir que el amor por un hijo es incomparable y creen que es el verdadero amor.<\/li>\n<li><strong>Los hijos hacen abuelos a sus padres.<\/strong> Los nietos son uno de los mayores regalos de la vida.<\/li>\n<li><strong>Los hijos son el soporte en la vejez.<\/strong> Los hijos son las &uacute;nicas personas que estar&aacute;n ah&iacute; para la vejez, es una de las situaciones m&aacute;s bellas, pues en esos momentos la familia cobra su raz&oacute;n de ser.<\/li>\n<\/ul>\n<p align=\"justify\"> Podr&iacute;an ser muchas m&aacute;s y seguramente detr&aacute;s de cada hijo hay una historia, y m&aacute;s que una historia, una misi&oacute;n por la cual ha llegado a este mundo.<br \/> &nbsp;&nbsp;<br \/> &nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: LaFamilia.info Lo que antes era un anhelo de los reci&eacute;n casados, hoy ya no es su prioridad; nacen as&iacute; los denominados \u2018childfree\u2018 o \u2018dinks\u2019 (\u2018double income, no kids\u2019 que se traduce a: doble ingreso, no ni&ntilde;os) son parejas de nivel socio econ&oacute;mico medio-alto, que han decidido como proyecto de vida no tener hijos e &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/tener-un-hijo-o-mejor-un-perrito\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab\u00bfTener un hijo? O mejor, un&nbsp;perrito\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-32531","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=32531"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/32531\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=32531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=32531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=32531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}