{"id":33741,"date":"2016-06-13T18:01:31","date_gmt":"2016-06-13T23:01:31","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/fue-a-buscar-a-las-prostitutas-para-decirles-dios-te-ama\/"},"modified":"2016-06-13T18:01:31","modified_gmt":"2016-06-13T23:01:31","slug":"fue-a-buscar-a-las-prostitutas-para-decirles-dios-te-ama","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/fue-a-buscar-a-las-prostitutas-para-decirles-dios-te-ama\/","title":{"rendered":"Fue a buscar a las prostitutas para decirles &#8220;Dios te&nbsp;ama&#8221;"},"content":{"rendered":"<p><b>Por: Claudio de Castro<\/b><\/p>\n<p align=\"justify\">No tengo no oro ni mirra ni incienso para darle al peque\u00f1o Jes\u00fas, pero encontr\u00e9 algo mejor. Lo descubr\u00ed en la Biblia. Fue incre\u00edble<em>: &#8220;<\/em><em>Id y aprended lo que significa: Misericordia quiero y no sacrificios; pues no he venido a llamar a los justos, sino a los pecadores&#8221;. (Mt 9, 13)<\/em><\/p>\n<p align=\"justify\"><em>&#8220;Misericordia quiero&#8221;&#8230; <\/em>Un amigo reflexion\u00f3 en estas palabras y sali\u00f3 una noche tratando de descubrir su significado. Fue a un barrio donde las prostitutas se paran cada noche. Y se detuvo a conversar con cada una. Sencillamente les dec\u00eda: &#8220;Dios te ama&#8221;, y les obsequiaba un libro sobre el perd\u00f3n y la misericordia de Dios.<\/p>\n<p align=\"justify\">Casi al final de su recorrido, pas\u00f3 lo inesperado. Se acerc\u00f3 a una mujer mayor que se ocultaba en la oscuridad.<\/p>\n<p align=\"justify\">&#8220;Dios te ama&#8221;, le dijo mi amigo sonri\u00e9ndole. La mujer sorprendida, se acerc\u00f3 a \u00e9l y cuando lo vio rompi\u00f3 a llorar.<\/p>\n<p align=\"justify\">&#8220;\u00bfDios me ama?&#8221;, preguntaba entre sollozos sin poder contenerse&#8230; &#8220;\u00bfA pesar de lo que soy?&#8221;.<\/p>\n<p align=\"justify\"><strong>&#8220;S\u00ed, Dios te ama&#8221;.<\/strong><\/p>\n<p align=\"justify\">Hoy har\u00e9 mi mejor esfuerzo para no juzgar a nadie, ni pensar mal de otro.<\/p>\n<p align=\"justify\">Ser\u00e9 misericordioso y llevar\u00e9 una palabra de consuelo a los que encuentre en el camino.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Claudio de Castro No tengo no oro ni mirra ni incienso para darle al peque\u00f1o Jes\u00fas, pero encontr\u00e9 algo mejor. Lo descubr\u00ed en la Biblia. Fue incre\u00edble: &#8220;Id y aprended lo que significa: Misericordia quiero y no sacrificios; pues no he venido a llamar a los justos, sino a los pecadores&#8221;. (Mt 9, 13) &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/fue-a-buscar-a-las-prostitutas-para-decirles-dios-te-ama\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abFue a buscar a las prostitutas para decirles &#8220;Dios te&nbsp;ama&#8221;\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-33741","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/33741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=33741"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/33741\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=33741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=33741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=33741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}