{"id":41463,"date":"2016-10-07T23:33:41","date_gmt":"2016-10-08T04:33:41","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/lc-6-6-11-curacion-en-sabado-del-hombre-de-la-mano-paralizada\/"},"modified":"2016-10-07T23:33:41","modified_gmt":"2016-10-08T04:33:41","slug":"lc-6-6-11-curacion-en-sabado-del-hombre-de-la-mano-paralizada","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/lc-6-6-11-curacion-en-sabado-del-hombre-de-la-mano-paralizada\/","title":{"rendered":"Lc 6, 6-11: Curaci\u00f3n en s\u00e1bado del hombre de la mano paralizada"},"content":{"rendered":"<div class=\"textoBiblia\">\n<p><span class=\"versiculo\">6<\/span> Otro s\u00e1bado, entr\u00f3 \u00e9l en la sinagoga y se puso a ense\u00f1ar. Hab\u00eda all\u00ed un hombre que ten\u00eda la mano derecha paralizada. <span class=\"versiculo\">7<\/span> Los escribas y los fariseos estaban al acecho para ver si curaba en s\u00e1bado, y encontrar de qu\u00e9 acusarlo. <span class=\"versiculo\">8<\/span> Pero \u00e9l conoc\u00eda sus pensamientos y dijo al hombre de la mano atrofiada: \u00abLev\u00e1ntate y ponte en medio\u00bb. Y, levant\u00e1ndose, se qued\u00f3 en pie.<br \/> <span class=\"versiculo\">9<\/span> Jes\u00fas les dijo: \u00abOs voy a hacer una pregunta: \u00bfQu\u00e9 est\u00e1 permitido en s\u00e1bado?, \u00bfhacer el bien o el mal, salvar una vida o destruirla?\u00bb. <span class=\"versiculo\">10<\/span> Y, echando en torno una mirada a todos, le dijo: \u00abExtiende tu mano\u00bb. \u00c9l lo hizo y su mano qued\u00f3 restablecida. <span class=\"versiculo\">11<\/span> Pero ellos, ciegos por la c\u00f3lera, discut\u00edan qu\u00e9 hab\u00eda que hacer con Jes\u00fas. <\/p>\n<\/div>\n<p style=\"text-align: right; margin-right:25px; font-size: 0.8em;\"><a href=\"http:\/\/www.deiverbum.org\/biblias.html\" target=\"_blank\" rel=\"nofollow\">Sagrada Biblia<\/a>, Versi\u00f3n oficial de la Conferencia Episcopal Espa\u00f1ola (2012)<\/p>\n<hr class=\"cambio-seccion\">\n<h1><span id=\"Homilias_comentarios_meditaciones_desde_la_Tradicion_de_la_Iglesia\">Homil\u00edas, comentarios, meditaciones desde la Tradici\u00f3n de la Iglesia<\/span><\/h1>\n<h2><span id=\"San_Ambrosio_obispo_y_doctor_de_la_Iglesia\">San Ambrosio, obispo y doctor de la Iglesia<\/span><\/h2>\n<h3><span id=\"Comentario_Es_el_mal_el_que_no_debe_trabajar\">Comentario: Es el mal el que no debe trabajar.<\/span><\/h3>\n<p class=\"refHomilia\">Comentario al evangelio de Lucas, V, 39.<\/p>\n<p class=\"subTitulo\">\u00abHab\u00eda all\u00ed un hombre que ten\u00eda par\u00e1lisis en el brazo derecho\u00bb ().<\/p>\n<p>La mano que Ad\u00e1n hab\u00eda alargado para coger el fruto del \u00e1rbol prohibido, el Se\u00f1or la impregn\u00f3 de la savia saludable de las buenas obras, a fin de que, secada por la falta, fuera curada por las buenas obras. En esta ocasi\u00f3n Jes\u00fas acusa a sus adversarios que, con su falsas interpretaciones, violaban los preceptos de la Ley; ellos defend\u00edan que en d\u00eda de s\u00e1bado era preciso no hacer ni tan s\u00f3lo buenas obras, siendo as\u00ed que la Ley, que prefiguraba en el presente lo que deb\u00eda ser en el futuro, dice, ciertamente, que es el mal el que no debe trabajar, pero no el bien&#8230;<\/p>\n<p>Has o\u00eddo las palabras del Se\u00f1or: \u00abExtiende el brazo\u00bb. Este es el remedio para todos. Y t\u00fa que crees tener sana la mano, vigila la avaricia, vigila que el sacrilegio no la paralice. Exti\u00e9ndela a menudo: exti\u00e9ndela hacia el pobre que te suplica, exti\u00e9ndela para ayudar al pr\u00f3jimo, para socorrer a la viuda, para arrancar de la injusticia al que ves sometido a una vejaci\u00f3n inmerecida; exti\u00e9ndela hacia Dios por tus pecados. Es de esta manera que se extiende la mano; es de esta manera que sana.<\/p>\n<h2><span id=\"San_Atanasio_obispo_de_Alejandria_doctor_de_la_Iglesia\">San Atanasio, obispo de Alejandr\u00eda, doctor de la Iglesia<\/span><\/h2>\n<h3><span id=\"Obras_Una_curacion_el_sabado_senal_de_la_consumacion_de_la_creacion\">Obras: Una curaci\u00f3n el s\u00e1bado: se\u00f1al de la consumaci\u00f3n de la creaci\u00f3n.<\/span><\/h3>\n<p class=\"refHomilia\">Contra los paganos : SC 18, 190.<\/p>\n<p class=\"subTitulo\">\u00ab\u00bfQu\u00e9 est\u00e1 permitido en s\u00e1bado?, \u00bfhacer el bien o el mal, salvar una vida o destruirla?\u00bb (Lc 6,9).<\/p>\n<p>Este mundo es bueno, tal como est\u00e1 hecho y tal como le vemos, porque Dios lo quiere as\u00ed. Nadie tiene duda de ello. Si la creaci\u00f3n fuera desordenada, si el universo evolucionara por azar, uno podr\u00eda poner en duda esta afirmaci\u00f3n. Pero como el mundo ha sido hecho con sabidur\u00eda y ciencia, de manera razonable, ya que est\u00e1 ataviado de toda belleza, no puede ser otro el que lo preside y lo organiz\u00f3 que la Palabra de Dios, su Verbo&#8230;<\/p>\n<p>Siendo la Palabra buena por ser de Dios bueno, esta Palabra ha dispuesto el orden de todas las cosas, ha reunido los contrarios con los contrarios para formar una \u00fanica armon\u00eda. Es ella \u201cpoder de Dios y sabidur\u00eda de Dios\u201d (cf 1Cor 1,24) que hace moverse el cielo y que suspende la tierra sin que repose en lugar alguno. (Hb 1,3) El sol ilumina la tierra por la luz que recibe de la Palabra y la luna recibe su medida de esa luz. Por ella, el agua queda suspendida en las nubes, las lluvias riegan la tierra, el mar guarda sus l\u00edmites, la tierra se cubre de plantas de toda especie (cf Sal 103)&#8230;<\/p>\n<p>La raz\u00f3n por la que esta Palabra de Dios ha venido hasta las criaturas es realmente admirable&#8230; La naturaleza de les seres creados es pasajera, d\u00e9bil, mortal. Pero como Dios, por naturaleza, es bueno y magn\u00edfico y ama a los hombres&#8230;, viendo, pues, que la creaci\u00f3n, por ella misma, se disuelve y se escurre, para evitarlo y para que el universo no vuelva a la nada&#8230;, Dios no la abandona a las fluctuaciones de su naturaleza. En su bondad, por su Palabra, Dios gobierna y mantiene toda la creaci\u00f3n&#8230; Por eso, no corre la suerte de la aniquilaci\u00f3n que ser\u00eda la suya si la Palabra no la guardara. \u201cCristo es la imagen de Dios invisible, el primog\u00e9nito de toda criatura. En \u00e9l fueron creadas todas las cosas, las del cielo y las de la tierra, las visibles y las invisibles: tronos, dominaciones, principados, potestades, todo lo ha creado Dios por \u00e9l y para \u00e9l&#8230;\u00c9l es tambi\u00e9n la cabeza del cuerpo, que es la Iglesia.\u201d<\/p>\n<h2><span id=\"San_Cesareo_de_Arles_obispo\">San Ces\u00e1reo de Arl\u00e9s, obispo<\/span><\/h2>\n<h3><span id=\"Sermon_Cristo_cura_las_heridas_del_pecado\">Serm\u00f3n: Cristo cura las heridas del pecado.<\/span><\/h3>\n<p class=\"refHomilia\">Sermones al pueblo, n\u00b0 57,4.<\/p>\n<p class=\"subTitulo\">\u00abLos escribas y fariseos le espiaban&#8230;con el fin de encontrar un motivo para acusarlo\u00bb (Lc 6,7).<\/p>\n<p>El Se\u00f1or dir\u00e1 a los que han menospreciado su misericordia : \u00abHombre, soy yo quien con mis manos te he formado del barro, soy yo quien con mi aliento he puesto el esp\u00edritu en tu cuerpo de tierra, soy yo quien se ha dignado darte nuestra imagen y semejanza, soy yo quien te ha puesto en el centro de las delicias del Para\u00edso. Pero t\u00fa, menospreciando los mandamientos de vida, has preferido seguir al seductor antes que al Se\u00f1or&#8230;<\/p>\n<p>\u00abLuego, cuando has sido expulsado del Para\u00edso y, por el pecado, retenido por las ataduras de la muerte, conmovido por la misericordia, para venir al mundo he entrado en un seno virginal, sin perjuicio de su virginidad . He sido recostado en un pesebre, envuelto en pa\u00f1ales; he soportado las dificultades de la infancia y los sufrimientos humanos, a trav\u00e9s de los cuales me he hecho semejante a ti con la \u00fanica finalidad de hacerte semejante a m\u00ed. He soportado las bofetadas y salivazos de los que se burlaban de m\u00ed, he bebido vinagre mezclado con hiel. Azotado con varas, coronado de espinas, clavado en la cruz, traspasado por la lanza, en medio de los tormentos he entregado mi alma para arrancarte a ti de la muerte. Puedes ver las se\u00f1ales de los clavos de los que he sido suspendido ; puedes ver mi costado traspasado lleno de heridas. He soportado los sufrimientos que eran para ti a fin de poder darte mi gloria; he sufrido tu muerte para que t\u00fa vivas por toda la eternidad. He descansado, encerrado en el sepulcro, para que tu puedas reinar en el cielo.<\/p>\n<p>\u00ab\u00bfPor qu\u00e9 has perdido lo que he sufrido por ti ? \u00bfPor qu\u00e9 has renunciado a las gracias de tu redenci\u00f3n ?&#8230; Devu\u00e9lveme tu vida, por la que he dado la m\u00eda ; devu\u00e9lveme tu vida que, sin cesar, has destruido por las heridas de tus pecados.\u00bb <\/p>\n<h2><span id=\"San_Francisco_de_Sales\">San Francisco de Sales<\/span><\/h2>\n<h3><span id=\"Obras_Dos_maneras_de_amar_a_Dios\">Obras: Dos maneras de amar a Dios.<\/span><\/h3>\n<p class=\"refHomilia\">Tratado del Amor de Dios, Libro VI, 1. IV, 301.<\/p>\n<p class=\"subTitulo\">\u00abJes\u00fas, ense\u00f1aba en una sinagoga en S\u00e1bado. Los escribas y fariseos le observaban&#8230; Jes\u00fas conoc\u00eda sus pensamientos&#8230;\u00bb (Lc 6,7-8).<\/p>\n<p>Tenemos dos principales maneras de amar a Nuestro Dios: una afectiva, la obra efectiva, o como dice San Bernardo, activa. Por la primera, amamos a Dios y todo lo que El ama; y por la segunda, servimos a Dios y hacemos lo que nos ordena: Aqu\u00e9lla nos une con la bondad de Dios y \u00e9sta nos hace ejecutar su voluntad.<\/p>\n<p>La una nos llena de complacencia, de benevolencia, de fervor y de deseos; la otra nos da la s\u00f3lida resoluci\u00f3n, la firmeza de valor y la inviolable obediencia que se requiere para cumplir lo que manda la voluntad de Dios, y para sufrir, aceptar, aprobar y abrazar todo lo que proviene del benepl\u00e1cito divino.<\/p>\n<p>La una nos hace gozar de Dios y la otra, que le agrademos. Por la una concebimos y por la otra producimos. Con la una ponemos a Dios en nuestro coraz\u00f3n y por la otra lo llevamos en nuestros brazos.<\/p>\n<p>El primer ejercicio consiste principalmente en la oraci\u00f3n; en ella pasan tantos movimientos interiores que es imposible expresarlos todos; no s\u00f3lo porque son muchos en cantidad sino tambi\u00e9n por su calidad que, como es espiritual, no es f\u00e1cil perfilarla y es casi imperceptible a nuestro entendimiento.<\/p>\n<p>Dios es el \u00fanico que, por su infinita ciencia, ve, sondea y penetra todas las vueltas y revueltas de nuestro esp\u00edritu; entiende de lejos nuestros pensamientos, sabe todos nuestros senderos, astucias y sutilezas. Su ciencia es admirable, prev\u00e9 por encima de nuestra capacidad y no podemos alcanzarla.<\/p>\n<p>Si nuestros esp\u00edritus quisieran hacerse una introspecci\u00f3n reflexionando sobre los repliegues de sus acciones, se meter\u00edan en un laberinto en el que se perder\u00edan. Y ser\u00eda insoportable saber cu\u00e1les son nuestros pensamientos, considerar nuestras consideraciones, discernir lo que discernimos, recordar que nos acordamos: resultar\u00eda un embrollo imposible de deshacer.<\/p>\n<p>La oraci\u00f3n es cosa secreta, Te\u00f3timo; hay que confi\u00e1rsela solamente a Dios.<\/p>\n<h2><span id=\"Meliton_de_Sardes_obispo\">Melit\u00f3n de Sardes, obispo<\/span><\/h2>\n<h3><span id=\"Homilia_Venid_recibid_el_perdon_de_vuestros_pecados\">Homil\u00eda: Venid, recibid el perd\u00f3n de vuestros pecados.<\/span><\/h3>\n<p class=\"refHomilia\">Homil\u00eda pascual<\/p>\n<p class=\"subTitulo\">\u00abEl Se\u00f1or me ayuda, por eso soportaba los ultrajes, por eso endurec\u00ed mi rostro como el pedernal, sabiendo que no quedar\u00e9 defraudado&#8230;\u00bb (Is 50, 7-8).<\/p>\n<p>Cristo era Dios y se revisti\u00f3 de la condici\u00f3n humana. Sufri\u00f3 por el que sufre, fue arrestado por el que es vencido, fue juzgado por el que es condenado y fue enterrado por quien es enterrado, y resucita de entre los muertos. Os anuncia estas palabras: \u201c\u00bfqui\u00e9n me quiere denunciar? \u00a1Comparezcamos juntos!\u201d (Is 50,8) Soy yo quien libera al condenado, soy yo quien resucita a los muertos, yo quien saco del sepulcro. \u00bfQui\u00e9n me replica? Soy yo, dice Cristo, soy yo quien he abolido la muerte, quien ha vencido al enemigo, quien ha pisado el infierno y ligado al maligno (cf Lc 11,22). Yo he exaltado al hombre m\u00e1s all\u00e1 de los cielos, yo, Cristo.<\/p>\n<p>\u201cVenid, pues, todos los pueblos de los hombres que est\u00e1is metidos en el mal, recibid el perd\u00f3n de vuestros pecados. Yo soy vuestro perd\u00f3n, yo soy la Pascua de la salvaci\u00f3n, yo soy el cordero inmolado por vosotros, o soy el agua que os purifica, yo soy vuestra luz, yo vuestro Salvador, vuestra resurrecci\u00f3n, vuestro rey. Os llevo conmigo al cielo, os mostrar\u00e9 al Padre celestial, os resucitar\u00e9 con mi derecha.\u201d<\/p>\n<p>Este es el que hizo el cielo y la tierra, que form\u00f3 al hombre al inicio de la creaci\u00f3n, que se anunci\u00f3 en la Ley y los profetas, el que tom\u00f3 carne de la Virgen, que fue colgado en un madero, puesto en un sepulcro y resucit\u00f3 de entre los muertos, que est\u00e1 sentado a la derecha del Padre y tiene poder de juzgarlo todo y de salvar todo. Por \u00e9l, el Padre cre\u00f3 todo lo que existe desde los or\u00edgenes hasta la eternidad. El es el alfa y la omega, el principio y el fin, \u00e9l es el Cristo&#8230; A \u00e9l la gloria y el poder por los siglos. Am\u00e9n.<\/p>\n<h2><span id=\"Epistola_llamada_de_Bernabe\">Ep\u00edstola llamada de Bernab\u00e9<\/span><\/h2>\n<p class=\"refHomilia\">130, \u00a715.<\/p>\n<p class=\"subTitulo\">\u00abSu mano qued\u00f3 restablecida\u00bb (Lc 6,10).<\/p>\n<p>Pasando a otro punto, tambi\u00e9n acerca del s\u00e1bado, se escribe en el dec\u00e1logo, es decir, en las diez palabras que habl\u00f3 Dios en el monte Sina\u00ed a Mois\u00e9s cara a cara: \u00abY santificad el s\u00e1bado del Se\u00f1or con manos limpias y coraz\u00f3n puro\u00bb. Y en otro lugar dice: \u00abSi mis hijos guardaren el s\u00e1bado, entonces pondr\u00e9 sobre ellos mi misericordia\u00bb. (cf. Ex 20,8; Sal 23,4).\u00a0\u00a0Del s\u00e1bado habla al principio de la creaci\u00f3n: \u00abE hizo Dios en seis d\u00edas las obras de sus manos y acab\u00f3las en el d\u00eda s\u00e9ptimo, y descans\u00f3 en \u00e9l y lo santific\u00f3\u00bb. (Gn 2,2-3).\u00a0\u00a0Atended, hijos, qu\u00e9 quiere decir lo de:\u00abAcab\u00f3los en seis d\u00edas\u00bb. Esto significa que en seis mil a\u00f1os consumar\u00e1 todas las cosas el Se\u00f1or, pues un d\u00eda es para \u00c9l mil a\u00f1os. Lo cual, \u00c9l mismo lo atestigua, diciendo: \u00abHe aqu\u00ed que el d\u00eda del Se\u00f1or ser\u00e1 como mil a\u00f1os\u00bb. Por lo tanto, hijos, en seis d\u00edas, es decir, en los seis mil a\u00f1os, se consumar\u00e1n todas las cosas. \u00abY descans\u00f3 en el d\u00eda s\u00e9ptimo\u00bb. Esto quiere decir: Cuando venga su hijo y destruya el siglo del inicuo y juzgue a los imp\u00edos y mudare el sol, la luna y las estrellas, entonces descansar\u00e1 de verdad en el d\u00eda s\u00e9ptimo.<\/p>\n<p>Y tambi\u00e9n dice: \u00abLo santificar\u00e1s con manos limpias y coraz\u00f3n puro\u00bb.<\/p>\n<p>Ahora, pues, si pensamos que pueda nadie santificar, sin ser puro de coraz\u00f3n, el d\u00eda que santific\u00f3 Dios mismo, nos equivocamos de todo en todo&#8230;\u00a0\u00a0consiguientemente, entonces por nuestro descanso lo santificaremos de verdad, cuando, justificados nosotros mismos y en posesi\u00f3n ya de la promesa, seremos capaces de santificarlo; es decir, cuando ya no exista la iniquidad, sino que nos hayamos vuelto todos nuevos por el Se\u00f1or, entonces, si, santificados primero nosotros, podremos santificar el d\u00eda s\u00e9ptimo.<\/p>\n<h2><span id=\"San_Elredo_de_Rievaulx_monje_cisterciense\">San Elredo de Rievaulx, monje cisterciense<\/span><\/h2>\n<h3><span id=\"Obras_Entrar_en_la_verdadera_paz_del_sabado\">Obras: Entrar en la verdadera paz del \u201cs\u00e1bado\u201d.<\/span><\/h3>\n<p class=\"refHomilia\">El Espejo de la caridad, III 3-6.<\/p>\n<p class=\"subTitulo\">\u00abSu mano qued\u00f3 restablecida\u00bb (Lc 6,10).<\/p>\n<p>Cuando el hombre, apart\u00e1ndose del bullicio exterior, se ha recogido en el secreto de su coraz\u00f3n, ha cerrado la puerta a la muchedumbre ruidosa de las vanidades\u2026, cuando en \u00e9l no queda nada de agitaci\u00f3n ni de desordenado, nada que le atraiga, nada que le atenace\u2026, est\u00e1 en la gozosa celebraci\u00f3n de un primer \u201cs\u00e1bado\u201d\u2026 Pero se puede salir de esta c\u00e1mara \u00edntima en la que se alberga su coraz\u00f3n\u2026, para entrar en el descanso gozoso y pac\u00edfico de la dulzura del amor fraterno. Est\u00e1 en el segundo \u201cs\u00e1bado\u201d, el de la caridad fraterna\u2026<\/p>\n<p>Una vez purificado por estas dos formas de amor [a s\u00ed misma y a su pr\u00f3jimo], el alma aspira tanto m\u00e1s ardientemente los gozos del abrazo divino cuanto m\u00e1s asegurada est\u00e1. Ardiendo en un deseo extremo, su mirada va m\u00e1s all\u00e1 del velo de la carne y, entrando en el santuario (Hb 10,20) en que Cristo es esp\u00edritu ante su rostro, queda totalmente absorbida por una luz indecible y de dulzura no habitual. Habi\u00e9ndose hecho el silencio en relaci\u00f3n a todo lo que es corporal, sensible, cambiante, con una mirada penetrante se fija en Lo que Es, Lo que siempre permanece, id\u00e9ntico a s\u00ed mismo, Lo que es Uno. Libre para ver que el mismo Se\u00f1or es Dios (Sal 45,11), celebra sin ninguna duda el \u201cs\u00e1bado de los s\u00e1bados\u201d en los dulces abrazos de la misma Caridad.<\/p>\n<hr class=\"cambio-seccion\" \/>\n<h1><span id=\"Comentarios_exegeticos\">Comentarios exeg\u00e9ticos<\/span><\/h1>\n<p>Pr\u00f3ximamente&#8230; no puedo hacerse ahora por falta de tiempo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>6 Otro s\u00e1bado, entr\u00f3 \u00e9l en la sinagoga y se puso a ense\u00f1ar. Hab\u00eda all\u00ed un hombre que ten\u00eda la mano derecha paralizada. 7 Los escribas y los fariseos estaban al acecho para ver si curaba en s\u00e1bado, y encontrar de qu\u00e9 acusarlo. 8 Pero \u00e9l conoc\u00eda sus pensamientos y dijo al hombre de la &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/lc-6-6-11-curacion-en-sabado-del-hombre-de-la-mano-paralizada\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLc 6, 6-11: Curaci\u00f3n en s\u00e1bado del hombre de la mano paralizada\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-41463","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/41463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=41463"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/41463\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=41463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=41463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=41463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}