{"id":5629,"date":"2016-02-08T19:11:18","date_gmt":"2016-02-09T00:11:18","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/el-fenmeno-de-toronto-2\/"},"modified":"2016-02-08T19:11:18","modified_gmt":"2016-02-09T00:11:18","slug":"el-fenmeno-de-toronto-2","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/el-fenmeno-de-toronto-2\/","title":{"rendered":"El Fen&#243;meno de Toronto"},"content":{"rendered":"<div><b>Introducci&#243;n<\/b><\/p>\n<p>Me han preguntado, verbalmente en p&#250;blico tanto como por muchas cartas, si creo que el fen&#243;meno de Toronto es verdaderamente una obra de Dios. Francamente, el hecho que tantos creyentes siquiera preguntan eso muestra cuan lejos el mundo evang&#233;lico ha ido de la Palabra de Dios. Esta desviaci&#243;n lleva \u00abpor doquiera de todo viento de doctrina\u00bb. Mi observaci&#243;n es que durante los &#250;ltimos 10-15 a&#241;os, m&#225;s y m&#225;s creyentes se est&#225;n volviendo b&#237;blicamente ignorantes; tal ignorancia le lleva a buscar nuevas experiencias espirituales, sin importar de donde vienen, y a la falta de conocimiento de las Escrituras para poder evaluar esas experiencias b&#237;blicamente. La iglesia, s&#237;, ha llegado a un estado pobre y el libro, &#8216;Cristianismo en Crisis&#8217;, ha sido bien nombrado.<\/p><\/div>\n<div style=\"text-align:justify; color:#3d3d3d;\">&#191;Es un asunto Carism&#225;tico vs. No-carism&#225;tico?<\/p>\n<p>Yo s&#233; que hay gente que al leer este art&#237;culo dejar&#225; todo apoyo que han estado dando a los Ministerios Ariel o al Seminario Chafer. En este sentido, no conviene ni a mi ministerio, Ariel, o al Seminario Chafer que lo escribiera, y ser&#237;a m&#225;s redituable mantenerme o neutral o mudo en cuanto a este tema. Pero ser&#237;a yo desobediente a mi llamado como maestro de la Palabra, y traicionar&#237;a mi don de ense&#241;ar si me mantuviera mudo en cuanto a un enga&#241;o y una falsa ilusi&#243;n tan terrible que se postula al mundo cristiano hoy en d&#237;a.<\/p>\n<p>Antes de tratar con el asunto, creo que otro punto se debe clarificar. Cuando me critican los defensores del fen&#243;meno de Toronto por mi cr&#237;tica del mismo, la idea com&#250;n es que el &#250;nico motivo por oponerme es que no soy ni \u00ablleno del Esp&#237;ritu\u00bb, ni \u00abPentecostal\u00bb, ni \u00abCarism&#225;tico\u00bb. Es verdad que no soy ni Pentecostal ni Carism&#225;tico como se han definido estos t&#233;rminos, aunque s&#237; creo que soy lleno del Esp&#237;ritu como se define por la Biblia. Sin embargo, rehuso dejar que llegue a ser un argumento de Carism&#225;tico\/Pentecostal vs. No-carism&#225;tico\/No-pentecostal. De hecho, este asunto ha dividido m&#225;s iglesias Pentecostal\/Carism&#225;ticas que ning&#250;n otro tipo. Tengo en mi posesi&#243;n una gran cantidad de cr&#237;ticas del fen&#243;meno de Toronto. Acerca de la mitad vienen de fuentes no-carism&#225;ticas\/no-pentecostales, pero por lo menos la mitad, si no es m&#225;s, vienen de fuentes carism&#225;ticas\/pentecostales. En realidad, dos conocidos m&#237;os, carism&#225;ticos, que han sido carism&#225;ticos por muchos a&#241;os, me han escrito a decir que hab&#237;an asistido una reuni&#243;n tipo Toronto en una iglesia de California del Sur donde el predicador invitado fue el pastor del Vineyard de Toronto. Se&#241;alaron que muchas de las cosas que vieron en esa reuni&#243;n &#8211; cosas que se llaman ahora evidencia de ser lleno del Esp&#237;ritu y hechos divinos y supernaturales de Dios &#8211; fueron en otro tiempo considerado demoniacos. Y los que hacen esas cosas, como re&#237;rse en una manera descontrolada o hacer sonidos de animales, hubieran sido considerados como demonizados; de hecho, estos dos conocidos hab&#237;an anteriormente echado fuera demonios de personas tales como esas. Lo que una vez fue considerado demoniaco ha llegado a ser normal en ciertos c&#237;rculos. Otra vez, esto muestra que no se trata de pentecostal\/carism&#225;tico y\/o no-pentecostal\/no-carism&#225;tico.<\/p>\n<p><b>El Libro de Los Hechos<\/b><\/p>\n<p>Lo que enfatizan las Escrituras es que la autoridad final debe ser las Escrituras, la Palabra escrita de Dios, no la experiencia de nadie. Ciertamente, los ap&#243;stoles pudieran haber relatado muchos de sus experiencias con Jes&#250;s tratando de defender su predicaci&#243;n acerca de Jes&#250;s. Una cosa que vuelve a recalcar vez tras vez es que Pablo, Silas y los otros siempre se basaron en la Palabra de Dios como autoridad final y no en sus propias experiencias, aunque por la gracia de Dios sus experiencias fueron incre&#237;bles.<\/p>\n<p>\u00abPasando por Anf&#237;polis y Apolonia, llegaron a Tesal&#243;nica, donde hab&#237;a una sinagoga de los jud&#237;os. Y Pablo, como acostumbraba, fue a ellos, y por tres d&#237;as de reposo discuti&#243; con ellos, declarando y exponiendo por medio de las Escrituras, que era necesario que el Cristo padeciese, y resucitase de los muertos; y que Jes&#250;s, a quien yo os anuncio, dec&#237;a &#233;l, es el Cristo. Y algunos de ellos creyeron, y se juntaron con Pablo y con Silas; y de los griegos piadosos gran n&#250;mero, y mujeres nobles no pocas.\u00bb (Hechos 17:1-4)<\/p>\n<p>Mayormente, no encontramos que Pablo usa sus experiencias personales, especialmente la experiencia clave que tuvo en el camino a Damasco, como herramientas para evangelizar. Para Pablo, la autoridad final tuvo que ser las Escrituras y no su propia experiencia ni testimonio, as&#237; que esa fue el enfoque de su evidencia y lo que convenci&#243; a tantos. Los que creyeron (17:4) no creyeron por se&#241;ales y prodigios que vieron hacer a Pablo, sino por su exposici&#243;n de las Escrituras y porque mostr&#243; que Jes&#250;s cumpli&#243; las Escrituras necesarias.<\/p>\n<p>Las dos instancias en que Pablo s&#237; relata su testimonio de hacerse creyente en el camino a Damasco fueron como en defensa propia en el juicio. No le encontramos us&#225;ndolo cuando su meta es evangelizaci&#243;n. Quiero que sea claro que no me opongo los testimonios personales y que comparto mi propio testimonio frecuentemente. Lo que estoy diciendo es que mi testimonio no puede ser jam&#225;s una autoridad final, ni puede el de ninguna otra persona.<\/p>\n<p>Adem&#225;s, la gente que se ha convertido a otras religiones &#8211; sea mormonismo, Testigos de Jehov&#225;, o la ciencia cristiana &#8211; pueden tambi&#233;n dar poderosos testimonios de c&#243;mo sus vidas han sido cambiadas. Por eso, otra vez, la autoridad y el criterio final tiene que ser la Palabra escrita de Dios. Los testimonios, creo yo, tienen su valor mayormente en el &#225;nimo y edificaci&#243;n de los hermanos creyentes, pero nunca pueden ser la evidencia final de la autenticidad de las afirmaciones y creencias de uno.<\/p>\n<p>Otro ejemplo es Hechos 18:28: \u00abporque con gran vehemencia refutaba p&#250;blicamente a los jud&#237;os, demostrando por las Escrituras que Jes&#250;s era el Cristo.\u00bb Esto habla de Apolos y que todo lo que ten&#237;a que decir fue basado en lo escrito. La refutaci&#243;n a los no creyentes no se basaba en se&#241;ales y prodigios sino en las Escrituras. Un ejemplo m&#225;s se encuentra en Hechos 28:23-24: \u00abY habi&#233;ndole se&#241;alado un d&#237;a, vinieron a &#233;l muchos a la posada, a los cuales les declaraba y les testificaba el reino de Dios desde la ma&#241;ana hasta la tarde, persuadi&#233;ndoles acerca de Jes&#250;s, tanto por la ley de Mois&#233;s como por los profetas. Y algunos asent&#237;an a lo que se dec&#237;a, pero otros no cre&#237;an.\u00bb Aqu&#237;, otra vez, lo que usaba Pablo no fue experiencia ni se&#241;ales y prodigios. Lo que usaba fue las Escrituras. Su enfoque total fue la Ley y los Profetas, las Escrituras del d&#237;a, para autenticar lo que ense&#241;aba y predicaba. La respuesta fue que algunos creyeron y otros no creyeron, pero los que s&#237; creyeron lo hicieron por la exposici&#243;n de las Palabra escrita de Dios. <\/p>\n<p><b>El Ap&#243;stol Pedro<\/b><\/p>\n<p>Adem&#225;s de lo que vemos en el libro de los Hechos, un buen ejemplo de basarse en las Escrituras y no en la experiencia es lo que dice Pedro: \u00abPorque no os hemos dado a conocer el poder y la venida de nuestro Se&#241;or Jesucristo siguiendo f&#225;bulas artificiosas, sino como habiendo visto con nuestros propios ojos su majestad. Pues cuando &#233;l recibi&#243; de Dios Padre honra y gloria, le fue enviada desde la magn&#237;fica gloria una voz que dec&#237;a: Este es mi Hijo amado, en el cual tengo complacencia. Y nosotros o&#237;mos esta voz enviada del cielo, cuando est&#225;bamos con &#233;l en el monte santo. Tenemos tambi&#233;n la palabra prof&#233;tica m&#225;s segura, a la cual hac&#233;is bien en estar atentos como a una antorcha que alumbra en lugar oscuro, hasta que el d&#237;a esclarezca y el lucero de la ma&#241;ana salga en vuestros corazones; entendiendo primero esto, que ninguna profec&#237;a de la Escritura es de interpretaci&#243;n privada, porque nunca la profec&#237;a fue tra&#237;da por voluntad humana, sino que los santos hombres de Dios hablaron siendo inspirados por el Esp&#237;ritu Santo.\u00bb (2 P 1:16-21)<\/p>\n<p>Pedro describe su experiencia en la Transfiguraci&#243;n cuando vio el resplandor de la Gloria Shechinah (\u00abshekaina\u00bb) manifiesta por Cristo y oy&#243; la voz desde el cielo decir, \u00abEste es mi Hijo amado, en el cual tengo complacencia.\u00bb (1:16-18) Es cierto que la experiencia de Pedro en la Monte de la Transfiguraci&#243;n fue uno de los momentos m&#225;s destacados de ese periodo de su vida con Jes&#250;s como disc&#237;pulo. Aunque la experiencia fue muy convincente para &#233;l, sin embargo Pedro se&#241;ala una base fidedigna m&#225;s segura para creer que Jes&#250;s fue el Mes&#237;as que no fue &#8216;f&#225;bulas artificiosas&#8217; sino las Escrituras. (1:19-21) Por lo tanto, las Escrituras mismas fueron lo que hicieron &#8216;m&#225;s segura&#8217; la fe de Pedro. Pedro no les anima a sus lectores a enfocar en su experiencia en la Transfiguraci&#243;n, sino en la Palabra de Dios. Y son las Escrituras, dice, que &#8216;a la cual hac&#233;is bien en estar atentos como a una antorcha que alumbra en lugar oscuro&#8217;. Lo que hace a las Escrituras la autoridad final y la base de doctrina &#8216;m&#225;s segura&#8217; que la experiencia es el hecho que no se produjeron por la voluntad de hombre, sino que son el producto del Esp&#237;ritu Santo quien movi&#243; a los escritores a escribir exactamente lo que quer&#237;a &#233;l que escribieran. La Palabra escrita de Dios siendo &#250;ltimamente el producto del Esp&#237;ritu Santo, \u00abla palabra prof&#233;tica\u00bb est&#225; hecha \u00abm&#225;s segura\u00bb. Ni la experiencia de Pedro en el Monte de la Transfiguraci&#243;n ni la gran experiencia de Pablo en el camino a Damasco jam&#225;s llegaron a ser la autoridad final para la fe de ninguno de los dos. El asunto final para los dos hombres era la Palabra escrita de Dios. <\/p>\n<p><b>&#191;Qu&#233; de Se&#241;ales y Prodigios?<\/b><\/p>\n<p>La respuesta de algunos es: &#191;No es la manifestaci&#243;n del supernatural la evidencia que esta es una obra de Dios, aunque no se encuentra en las Escrituras? Y &#191;No son los se&#241;ales y prodigios las evidencias de las obras de Dios, aunque los se&#241;ales y prodigios espec&#237;ficos no se encuentran en las Escrituras? Aqu&#237;, otra vez, la respuesta es definitivamente que &#8216;no&#8217;, como muestran los siguientes dos pasajes. El primero es Mateo 7:22-23: \u00abMuchos me dir&#225;n en aquel d&#237;a: Se&#241;or, Se&#241;or, no profetizamos en tu nombre, y en tu nombre echamos fuera demonios, y en tu nombre hicimos muchos milagros? Y entonces les declarar&#233;: Nunca os conoc&#237;; apartaos de m&#237;, hacedores de maldad.\u00bb Se debe notar lo que esos maestros falsos fueron capaces de hacer en el nombre de un Jes&#250;s falso. Obviamente, cuando dicen que lo hicieron \u00aben tu nombre\u00bb, significa que s&#237; usaron el nombre de Jes&#250;s y que probablemente lo usaron frecuentemente. Sin duda, fue su muy frecuente uso del nombre de Jes&#250;s que enga&#241;&#243; a mucha gente. Adem&#225;s, fueron capaces a hacer tres cosas espec&#237;ficas: &#8216;profetizar&#8217; eventos que se realizaron; &#8216;echar fuera demonios&#8217;; y &#8216;hacer muchos milagros&#8217;, tales como sanidades milagrosas y otros. Pero &#8216;entonces&#8217; Jes&#250;s les dir&#225;, &#8216;Nunca os conoc&#237;&#8217;. He aqu&#237;, tienes todos los ingredientes de algunos de las cosas que est&#225;n pasando en Toronto, Kansas City, y en otras partes. El nombre de Jes&#250;s se usa mucho en estilo casi ritual-mantra, toda clase de se&#241;ales y prodigios se dicen ocurrir, y aun, estas cosas, por s&#237; solas, no prueban nada porque Satan&#225;s las puede duplicar. Otra vez, es importante volver a la Palabra escrita de Dios como el criterio final, la fuente final de la autoridad, y la base final para todo asunto de fe y de pr&#225;ctica. <\/p>\n<p><b>La Serpiente Enga&#241;osa<\/b><\/p>\n<p>Otro ejemplo de esto es 2 Corintios 11:3-4 y 13-15: \u00abPero temo que como la serpiente con su astucia enga&#241;&#243; a Eva, vuestros sentidos sean de alguna manera extraviados de la sincera fidelidad a Cristo. Porque si viene alguno predicando a otro Jes&#250;s que el que os hemos predicado, o si recib&#237;s otro esp&#237;ritu que el que hab&#233;is recibido, u otro evangelio que el que hab&#233;is aceptado, bien lo toler&#225;is;\u00bb &#8230;. \u00abPorque &#233;stos son falsos ap&#243;stoles, obreros fraudulentos, que se disfrazan como ap&#243;stoles de Cristo. Y no es maravilla, porque el mismo Satan&#225;s se disfraza como &#225;ngel de luz. As&#237; que, no es extra&#241;o si tambi&#233;n sus ministros se disfrazan como ministros de justicia; cuyo fin ser&#225; conforme a sus obras.\u00bb<\/p>\n<p>Pablo enfatiza el hecho que as&#237; como Satan&#225;s pudo enga&#241;ar a Eva, aun los creyentes de la iglesia corintia se pod&#237;an tambi&#233;n enga&#241;ar por &#233;l, tal vez no directamente como a Eva, pero ciertamente por sus ministros (11:3). Se debe mantener presente que la iglesia corintia estaba contundentemente involucrada en sensacionalismo, se&#241;ales y prodigios, y lo experimental. Por basarse mucho en la experiencia y el supernatural, estaban abiertos al enga&#241;o por falsos maestros. Pablo pone a tres palabras el adjetivo &#8216;otro&#8217; (11:4): &#8216;otro Jes&#250;s; otro evangelio; otro esp&#237;ritu&#8217;. En el griego se usan dos palabras distintas que significan &#8216;otro&#8217;, pero las dos tienen diferentes matices de significado. El primero significa &#8216;otro del mismo tipo&#8217;, y el segundo significa &#8216;otro de tipo diferente&#8217;. Si traducimos vers&#237;culo cuatro m&#225;s literalmente, dir&#237;a el siguiente:<\/p>\n<p>\u00abPorque si viene alguno predicando a otro Jes&#250;s del mismo tipo que el que os hemos predicado, o si recib&#237;s otro esp&#237;ritu tipo diferente que el que hab&#233;is recibido, u otro evangelio tipo diferente que el que hab&#233;is aceptado, bien lo toler&#225;is;\u00bb<\/p>\n<p>Lo que Pablo est&#225; diciendo es que el evangelio que se present&#243; fue otro evangelio &#8216;tipo diferente&#8217;. Pero el Jes&#250;s que se present&#243; fue otro Jes&#250;s &#8216;del mismo tipo&#8217;; un Jes&#250;s que parec&#237;a al Jes&#250;s del Nuevo Testamento, pero fue en realidad un Jes&#250;s falso bien disfrazado. Se deber&#237;a notar que el nombre usado para fomentar el trabajo de enga&#241;o es el de Jes&#250;s. Es un Jes&#250;s falso, pero es un bien disfrazado falso para que se enga&#241;e f&#225;cilmente el que no juzga las cosas por la Palabra de Dios. Pablo lo hace claro que los que propagan a otro Jes&#250;s son \u00abfalsos ap&#243;stoles\u00bb (11:13); sin embargo, no parecen falsos porque se forman para parecer verdaderos ministros de Cristo. As&#237; haciendo, reflejan a su verdadero amo, a Satan&#225;s, quien es el &#225;ngel de &#8216;estas tinieblas&#8217; <Efesios 6:12> y que se disfraza como &#225;ngel de luz (11:14). Pablo dice que esto no deber&#237;a sorprender porque si Satan&#225;s se forma para parecer un &#225;ngel de luz, ciertamente sus ministros se van a parecer como ministros de justicia; pero, al final, recibir&#225;n su juicio (11:15). Otra vez, Satan&#225;s no tendr&#237;a mucho &#233;xito en su obra de enga&#241;o, especialmente con los creyentes, si sus ministros fueran claramente y sin duda \u00abfuera de la cancha\u00bb. Y para hacer la obra de enga&#241;o, ciertamente tienen que enfocar en el nombre de Jes&#250;s y no en alg&#250;n otro nombre. Pero el mero uso del nombre \u00abJes&#250;s\u00bb, aun en el contexto de palabras como &#8216;alabar&#8217;, &#8216;gloria&#8217;, etc., no autentica el ministerio de nadie ni deber&#237;a hacerlo. De nuevo, la autoridad final debe ser las Escrituras, no experiencia, se&#241;ales, prodigios, actividades inusuales, ni sonidos extra&#241;os. <\/p>\n<p><b>Esp&#237;ritus Enga&#241;adores<\/b><\/p>\n<p>El fen&#243;meno de hoy en d&#237;a, tal como de Toronto, no debiera haber sorprendido a nadie que se basa en la Palabra, pues en 1 Tim 4:1, Pablo declara: \u00abPero el Esp&#237;ritu dice claramente que en los postreros tiempos algunos apostatar&#225;n de la fe, escuchando a esp&#237;ritus enga&#241;adores y a doctrinas de demonios.\u00bb Hay, por supuesto, doctrina b&#237;blica; pero aqu&#237;, Pablo habla del hecho que Satan&#225;s tiene su propio sistema de doctrina &#8211; que se refiere como \u00abdoctrinas de demonios\u00bb. Aquel que se enamora de \u00abdoctrinas de demonios\u00bb acaban \u00bb escuchando a esp&#237;ritus enga&#241;adores\u00bb. &#191;Qu&#233; lo que son esas doctrinas de demonios? Son tales doctrinas que est&#225;n saliendo de Toronto y de otras partes, que no tienen su base en la Palabra escrita de Dios. Est&#225;n basados en que algunos maestros pretenden haber recibido revelaci&#243;n especial y divina de Dios que, por lo tanto, hay que aceptar como verdad nueva. El que se involucra en tales \u00abdoctrinas de demonios\u00bb acaba enga&#241;ado por esp&#237;ritus demoniacos. S&#237;, hay algunos que defender&#225;n estas cosas bas&#225;ndose en que se sienten feliz, bueno, o gozoso, presumiendo que tales sentimientos buenos deben ser del Se&#241;or. Pero esto solamente muestra que han sido, en realidad, enga&#241;ados por demonios. Otra vez, Satan&#225;s no tendr&#237;a mucho &#233;xito en su programa de enga&#241;o si su estrategia le hiciera sentir mal a la gente. Eso no atrae mucho p&#250;blico. Lo que s&#237; atrae a muchos es gente que les puede hacer sentir bien, aunque el sentimiento sea nada m&#225;s que un escape de emociones. Pero si el sentimiento se puede atribuir a una obra supernatural de Dios, el que lo experimenta ha sido enga&#241;ado. <\/p>\n<p><b>L&#237;mites B&#237;blicos<\/b><\/p>\n<p>La Biblia misma nos da una admonici&#243;n mayor por la cual debemos juzgar todo que afirma ser del Se&#241;or: La Palabra escrita de Dios. Concluyendo este estudio, veremos dos pasajes claves. El primero es 1 Corintios 4:6:<\/p>\n<p>\u00abPero esto, hermanos, lo he presentado como ejemplo en m&#237; y en Apolos por amor de vosotros, para que en nosotros aprend&#225;is a no pensar m&#225;s de lo que est&#225; escrito, no sea que por causa de uno, os envanezc&#225;is unos contra otros.\u00bb<\/p>\n<p>Enfatizo que Pablo dice esto a una iglesia que ten&#237;a una fuerte tendencia a moverse hac&#237;a sensacionalismo y lo experimental. Cap&#237;tulos 12-14 hacen claro que la iglesia corintia fue, sin lugar a dudas, la m&#225;s Pentecostal\/carism&#225;tica de todas las iglesias del Nuevo Testamento. Enfatizaron, ciertamente, los dones del Esp&#237;ritu de una manera que no vemos en las ep&#237;stolas a las otras iglesias. El enfoque en lo experimental mostr&#243; que no fueron espirituales sino carnales (1 Co 3:1-3). Pablo le amonesta especialmente a una iglesia de esa naturaleza que \u00abno fueran m&#225;s all&#225; que las cosas escritas\u00bb. Las cosas escritas, por supuesto, son las Sagradas Escrituras. Para cualquier manifestaci&#243;n o fen&#243;meno, hay que volver y probarlo por la Palabra de Dios. La verdad es que los fen&#243;menos de risa y de sonidos de animales no se encuentran en ninguna parte de las Escrituras. Son cosas que van m&#225;s all&#225; de las cosas escritas y se deben rechazar rotundamente. No hay que viajar por avi&#243;n a Toronto para experimentar si algo es o no es de Dios. Es suficiente saber que no est&#225; en las Escrituras; han ido m&#225;s all&#225; de lo escrito y, por lo tanto, es evidente que esas cosas no son de Dios. Y &#191;qu&#233; pasa con ellos que van m&#225;s all&#225; de lo escrito? Pablo declara que \u00abse envanecen unos contra otros\u00bb. Desarrollan un orgullo espiritual que es evidente cuando dicen tener una medida m&#225;s grande del Esp&#237;ritu Santo que otros creyentes. Como resultado, dividen a los creyentes en dos categor&#237;as: ellos que &#8216;lo tienen&#8217; y ellos que &#8216;no lo tienen&#8217;. Supongo que soy uno que &#8216;no lo tiene&#8217;. Por eso, me alegro, porque &#8216;lo que tienen&#8217; no se encuentra en las Escrituras. Despu&#233;s de observar y hablar con muchos que se dicen &#8216;tenerlo&#8217;, no me provoca celo para tenerlo de ninguna forma. Estoy contento con la espiritualidad descrito en las Escrituras &#8211; trato de lograrla usando la Palabra de Dios y nada m&#225;s.<\/p>\n<p>Hay una Escritura m&#225;s que se trata de esta discusi&#243;n, y es 2 Tim 3:12-4:4:<\/p>\n<p>\u00abY tambi&#233;n todos los que quieren vivir piadosamente en Cristo Jes&#250;s padecer&#225;n persecuci&#243;n; mas los malos hombres y los enga&#241;adores ir&#225;n de mal en peor, enga&#241;ando y siendo enga&#241;ados. Pero persiste t&#250; en lo que has aprendido y te persuadiste, sabiendo de qui&#233;n has aprendido; y que desde la ni&#241;ez has sabido las Sagradas Escrituras, las cuales te pueden hacer sabio para la salvaci&#243;n por la fe que es en Cristo Jes&#250;s. Toda la Escritura es inspirada por Dios, y &#250;til par ense&#241;ar, par redarguir, para corregir, para instruir en justicia, a fin de que el hombre de Dios sea perfecto, enteramente preparado para toda buena obra. Te encarezco delante de Dios y del Se&#241;or Jesucristo, que juzgar&#225; a los vivos y a los muertos en su manifestaci&#243;n y en su reino, que prediques la palabra; que instes a tiempo y fuera de tiempo; redarguye, reprende, exhorta con toda paciencia y doctrina. Porque vendr&#225; tiempo cuando no sufrir&#225;n la sana doctrina, sino que teniendo comez&#243;n de o&#237;r, se amontonar&#225;n maestros conforme a sus propias concupiscencias, y apartar&#225;n de la verdad el o&#237;do y se volver&#225;n a las f&#225;bulas.\u00bb<\/p>\n<p>Pablo da un mensaje sencillo que no se toma en cuenta por muchos de los movimientos modernos hoy en d&#237;a: que los que buscan vivir piadosamente en este mundo padecer&#225;n persecuci&#243;n (3:12). En la predicaci&#243;n corriente de \u00abnombrarlo y reclamarlo\u00bb y el evangelio de \u00absanidad y prosperidad\u00bb, no se escucha a los predicadores que los que realmente quieren tener vidas espirituales y piadosas conforme a las Escrituras padecer&#225;n persecuci&#243;n. La verdad es que no son sanidad y prosperidad se&#241;ales de favor divino ni de espiritualidad. Mas ser perseguido para la fe que es la se&#241;al de una persona realmente piadosa.<\/p>\n<p>Entonces, Pablo advierta que, pasando el tiempo, habr&#225;n m&#225;s y m&#225;s maestros falsos, impostores, muchos de ellos mismos enga&#241;ados, que andan enga&#241;ando a otros (3:13). Tal vez creen que son los \u00abungidos de Dios\u00bb y lo repiten a los que les critiquen, pero el hecho es que han llegado a ser enga&#241;ados ellos mismos y, por lo tanto, proceden a enga&#241;ar a otros tambi&#233;n.<\/p>\n<p>As&#237; que &#191;qu&#233; le proteger&#225; a Timoteo de ser enga&#241;ado por los falsos maestros? Pablo contesta eso en 3:14-17. Anima a Timoteo a continuar en lo que ha aprendido (3:14) y en lo que ha sido entrenado desde su ni&#241;ez de &#8216;las Sagradas Escrituras&#8217; (3:15). N&#243;tese que aqu&#237; vemos el mismo &#233;nfasis que se ve en 1 Co 4:6: la Palabra escrita de Dios, &#8216;las Sagradas Escrituras\u00bb. Son dos cosas que salvar&#225;n a Timoteo de ser enga&#241;ado: su conocimiento de las sagradas escrituras y que &#233;l permanezca en ellas. El significado b&#225;sico de la palabra &#8216;permanecer&#8217; es \u00abhacer tu hogar\u00bb. Que hiciera su hogar en las escrituras sagradas. Su enfoque no debiera ser las experiencias personales, por lo m&#225;s que sean supernaturales. Como vimos en Mateo 7:22-23, no deber&#237;a enfocarse en se&#241;ales y prodigios que le pueden llevar al enga&#241;o, sino debe permanecer en la Palabra escrita de Dios. Lo que dijo Pedro en 2 Pedro 1:20-21, Pablo dice en 2 Tim 3:16: que las Escrituras son la Palabra inspirada por Dios y, por lo tanto, son &#250;tiles en toda &#225;rea de la vida. Y &#191;cuan &#250;tiles son? Pablo contesta diciendo que la Escrituras hacen al hombre de Dios perfecto, o completo, y tambi&#233;n, &#8216;enteramente preparado para toda buena obra&#8217;. (3:17) Lo que ense&#241;a este vers&#237;culo no debemos perder. Las Escrituras son suficiente para hacerle a uno enteramente completo. No es necesario buscar un rayo supernatural que cae del mundo de los esp&#237;ritus. No hay que gastar dinero en viajar a Toronto a que alguien te impusiera las manos hasta que te caigas en risa descontrolada o hicieras sonidos de animal. La Palabra escrita es enteramente capaz de completarte, o perfeccionarte, y prepararte para cada obra que necesitas hacer. Te puedes hacer espiritual y maduro en la fe por las puras Escrituras. Sin embargo, por eso necesitas la disciplina de estudiar la Palabra de Dios, pasando horas, d&#237;as, semanas, a&#241;os de una vida para comprender m&#225;s y m&#225;s de la Palabra de Dios. Pero en esta edad tecnol&#243;gica, la gente se ha puesto perezosa y busca llegar a la espiritualidad por el camino del &#8216;desayuno instant&#225;neo&#8217;, buscando una &#8216;experiencia rayo&#8217; para &#8216;tenerlo&#8217;, y hasta sentirse dioses ellos mismos. Por la autoridad de este pasaje yo puedo declarar que tales experiencias no le llevan a uno a la espiritualidad, sino al ser enga&#241;ado y, luego, a enga&#241;ar a otros tambi&#233;n. Porque Timoteo es entendido en las Escrituras, y porque las Escrituras son completamente capaces de prepararle enteramente para toda buena obra, Pablo entonces le anima a Timoteo que hiciera no m&#225;s la obra del ministerio &#8211; redarguyendo, reprendiendo, exhortando y ense&#241;ando (4:1-2). Pero su ense&#241;ar no se hace por alguna \u00abpalabra de ciencia\u00bb o una revelaci&#243;n divina que no viene de las Escrituras; sino, se hace por la Palabra escrita de Dios como ya dijo Pablo en 3:16. Entonces, Pablo de nuevo declara lo que pasar&#225; en los postreros d&#237;as y, desafortunadamente, lo que describe Pablo, de hecho, ha pasado finalmente (4:3-4). Dice que vendr&#225; tiempo cuando los creyentes \u00abno sufrir&#225;n la sana doctrina\u00bb (4:3). Y &#191;qu&#233; lo que es \u00abla sana doctrina\u00bb? En contraste a las \u00abdoctrinas de demonios\u00bb (1 Tim 4:1), que son doctrinas basadas en lo experimental y lo supernatural que van m&#225;s all&#225; de lo escrito, la sana doctrina es aquella que es basada en y viene de \u00ablas Sagradas Escrituras\u00bb. De hecho, vivimos en un tiempo cuando la mayor&#237;a de los creyentes en nuestras iglesias simplemente no pueden soportar \u00abla sana doctrina\u00bb. La televisi&#243;n, habiendo ayudado a rendirle papilla a la mayor&#237;a de las mentes de los no creyentes, ha hecho la misma cosa para los creyentes, como los programas cristianos s&#243;lo imitan a los seculares. En lugar de exposici&#243;n de la Palabra por ense&#241;ar, hay entretenci&#243;n cristiana y programas de entrevistas que llevan poca, si es que hay algo de sustancia doctrinal. Un orador carism&#225;tico que causa que la gente se ponga hist&#233;rica, o portarse como animales, o caerse al suelo, puede llenar estadios con miles de gente, a la cual le pide, eventualmente, que vac&#237;e sus bolsillos para la ofrenda. Pero uno que expone la Palabra de Dios para impartir un entendimiento de las Escrituras y la sana doctrina atraer&#225; una audiencia relativamente peque&#241;a. De hecho, el tiempo ha llegado cuando los hombres no pueden \u00absufrir la sana doctrina\u00bb.<\/p>\n<p>Y &#191;c&#243;mo satisfar&#225;n su necesidad espiritual? Pablo explica que \u00abse amontonar&#225;n maestros conforme a sus propias concupiscencias.\u00bb En otras palabras, buscar&#225;n maestros que les dir&#225;n lo que quieren escuchar (y estar perseguido por vivir piadosamente no es algo que los creyentes quieren o&#237;r). Seguir&#225;n a maestros que les prometen sanidad y prosperidad por meramente usar una f&#243;rmula de nombrarlo y reclamarlo; maestros que prometen materialismo en un paquete envuelto en espiritualidad son los que seguir&#225;n. Pero evitar&#225;n tener que aguantar una profunda ense&#241;anza de la Palabra de Dios. Ese d&#237;a, s&#237;, ha llegado. Pablo nos cuenta el resultado de no sufrir la sana doctrina y seguir falsos maestros (4:4): primero, \u00abapartar&#225;n de la verdad el o&#237;do\u00bb, y, segundo, \u00abse volver&#225;n a las f&#225;bulas\u00bb. &#191;Qu&#233; lo que son las f&#225;bulas? De nuevo, son ense&#241;anzas y doctrinas fuera de las Escrituras. Como vimos ya, Pedro dijo que no segu&#237;a las \u00abf&#225;bulas artificiosas\u00bb porque lo que ense&#241;aba y predicaba se basaba en la Palabra escrita de Dios, inspirado por el Esp&#237;ritu Santo. Timoteo no ser&#225; arrancado para seguir f&#225;bulas porque se basan, su vida, su ense&#241;anza y su ministerio, en \u00ablas Sagradas Escrituras\u00bb. Aquellos que van m&#225;s all&#225; que las cosas escritas se acaban siguiendo f&#225;bulas. Otra vez, las f&#225;bulas son ense&#241;anzas que no encontramos en las Escrituras y, por lo tanto, se originan o con el hombre o con el mundo demoniaco y, as&#237;, se vuelven en doctrina de demonios. F&#225;bulas son las falsas premisas de experiencias y acciones que no se encuentran en las Escrituras. <\/p>\n<p><b>Conclusi&#243;n<\/b><\/p>\n<p>El Fen&#243;meno de Toronto es una f&#225;bula porque va m&#225;s all&#225; que las cosa escritas. Tenemos que rechazarlo porque no se basa en las Sagradas Escrituras y, por lo tanto, no se puede aprobar como \u00absana doctrina\u00bb. Bas&#225;ndome en la Palabra escrita de Dios, insto a todos los que se han sido agarrados por este fen&#243;meno que dejen que se parafrasear 2 Timoteo 4:4 as&#237; en sus vidas: Ap&#225;rtense de las f&#225;bulas, y vuelven a la verdad.<\/p>\n<p>Arnold Fruchtenbaum recibi&#243; un B.A. de Cedarville College (Universidad de Cedarville), un Th.M. de Dallas Theological Seminary, y un Ph.D. de New York University. &#201;l es fundador y co-director de Ministerios Ariel, Tustin, CA, un ministerio a la gente jud&#237;a alrededor del mundo. Tambi&#233;n es profesor adjunto en el Seminario Teol&#243;gico Chafer y da conferencias b&#237;blicas en todo el mundo.<\/p>\n<p>Por Arnold G. Fruchtenbaum, Ph. D.<\/p>\n<p>Seminario Teol&#243;gico Chafer (Chafer Theological Seminary)<\/p>\n<p>Traducido por Ellen Cabral<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Introducci&#243;n Me han preguntado, verbalmente en p&#250;blico tanto como por muchas cartas, si creo que el fen&#243;meno de Toronto es verdaderamente una obra de Dios. Francamente, el hecho que tantos creyentes siquiera preguntan eso muestra cuan lejos el mundo evang&#233;lico ha ido de la Palabra de Dios. Esta desviaci&#243;n lleva \u00abpor doquiera de todo viento &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/el-fenmeno-de-toronto-2\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEl Fen&#243;meno de Toronto\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5629","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/5629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=5629"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/5629\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=5629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=5629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=5629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}