{"id":5652,"date":"2016-02-08T19:11:34","date_gmt":"2016-02-09T00:11:34","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/la-epstola-de-efesios\/"},"modified":"2016-02-08T19:11:34","modified_gmt":"2016-02-09T00:11:34","slug":"la-epstola-de-efesios","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/la-epstola-de-efesios\/","title":{"rendered":"La Ep&#237;stola de Efesios"},"content":{"rendered":"<div>Introducci&#243;n a la Ep&#237;stola<\/p>\n<p>Texto B&#225;sico. Efe. 1:1-2<\/p>\n<p>A fin de iniciar este estudio con provecho, es conveniente tener una visi&#243;n preliminar respecto de la tem&#225;tica que nos presenta Pablo en esta carta, toda vez que, de esta forma conseguiremos una aproximaci&#243;n a la totalidad de las ideas que se desarrollan en la ep&#237;stola. A esto le seguir&#225;n aquellas caracter&#237;sticas &#8211; las m&#225;s importantes- que nos ayudaran a entender su ense&#241;anza.<\/p><\/div>\n<div style=\"text-align:justify; color:#3d3d3d;\">Salutaci&#243;n Inicial.- (1:1-2)<\/p>\n<p>Al nombre del remitente y el de los destinatarios, le sigue la bendici&#243;n que aquel pronuncia sobre aquellos (1:3), y tambi&#233;n &#8220;el cuerpo de la carta&#8221; la cual finaliza con una observaci&#243;n respecto del mensajero (6:1ss). En su final encontramos (6:23ss) la bendici&#243;n del Ap&#243;stol que, probablemente la escribi&#243; de su pu&#241;o y letra igual que en 1. Cor. 16:21; Col. 4:18; 2. Tes. 3:17.<\/p>\n<p>El cuerpo de la carta est&#225; claramente dividido en dos partes que tienen, aproximadamente, la misma extensi&#243;n. La tem&#225;tica es, en general, la realizaci&#243;n divina del misterio de Jesucristo en aquella iglesia integrada por jud&#237;os y gentiles (3:6) y tambi&#233;n &#8220;la realizaci&#243;n de la plenitud de los tiempos&#8221; (1:10). Adem&#225;s, en la primera parte que va desde 1:3 a 3:21, dentro de una bendici&#243;n y una doxolog&#237;a se expresa el ruego del Ap&#243;stol para que aquellos cristianos procedentes del gentilismo consigan captar la magnitud del misterio de su vocaci&#243;n en el Cuerpo de Cristo, que es la iglesia. La segunda parte (4:1 a 6:22) exhorta a vivir en conformidad al dicho misterio de su vocaci&#243;n mediante una vida &#8220;digna&#8221;.<\/p>\n<p>La primera parte de la Carta ( 1:3 &#8211; 3:21) se inicia alabando las bendiciones que Dios ha concedido en Cristo a los miembros de la iglesia (1:3-14) la bendici&#243;n de ser predestinados a ser hechos hijos de Dios, la de su redenci&#243;n por la remisi&#243;n de sus pecados, la de la iluminaci&#243;n mediante el conocimiento de la obra salvadora de Dios (1:3-10) Y, en todo ello han participado tanto jud&#237;os como gentiles (1:11-14).<\/p>\n<p>El contenido de la segunda sesi&#243;n de esta primera parte (1:15-23) es el deseo de que los cristianos de origen gentil entiendan cada vez mas, y con el coraz&#243;n plenamente iluminado, la nueva esperanza de la cual se habla en la citada bendici&#243;n: esperanza en aquello que ella es y las razones en que se fundamenta.<\/p>\n<p>En la tercera y cuarta secciones, el Ap&#243;stol les aclara, una vez m&#225;s, cual ser&#225; su propia historia como gentiles: ellos que estaban muertos a causa de sus pecados, en los que hab&#237;an vivido siguiendo la voluntad de la carne y del presente e&#243;n, fueron despertados por gracia, a la vida de Jesucristo y en la nueva creaci&#243;n trasladados a los cielos (2:1-10).<\/p>\n<p>Ellos, que estaban lejos de Dios y de sus promesas, sin Dios ni esperanza, vinieron a ser reconciliados con Dios, junto con Israel mediante el Cuerpo de Cristo llegando a ser el hombre nuevo, siendo conjuntamente edificados como el templo de Dios (2:11-22) Semblante realizaci&#243;n de la gracia de Dios &#8211; como se dice en la quinta sesi&#243;n- se realiz&#243; mediante el ministerio fundamentado en la Revelaci&#243;n del misterio de Cristo a los ap&#243;stoles y profetas entre los cuales est&#225; Pablo, y que consiste en la proclamaci&#243;n del mencionado misterio, que es el cuerpo (pueblo) formado por jud&#237;os y gentiles.<\/p>\n<p>La sexta secci&#243;n recoge nuevamente la petici&#243;n de 1:1ss y concluye con ella. En 3:14-19 Pablo dice &#8211; resumi&#233;ndolo- que ojal&#225; Dios quiera que los cristianos entiendan la dimensi&#243;n del ser celestial, que es lo que son, la dimensi&#243;n de la cruz y de su gloria, y que conozcan &#237;ntimamente el amor de Cristo a fin de que entren en la plenitud de Dios.<\/p>\n<p>Con una doxolog&#237;a &#8211; en la s&#233;ptima secci&#243;n- finaliza la primera parte de la carta (3:20-21)<\/p>\n<p>La Segunda Parte de la Carta (de 4:1 a 6:22) habla a los cristianos procedentes del mundo gentil y que hace poco que han comenzado a ser instruidos con respecto a su nueva realidad, y les exhorta que en su nueva vida conserven y demuestren lo que ahora son por la gracia del Se&#241;or. As&#237;, la primera recomendaci&#243;n es la de conservar con humildad la unidad del Cuerpo de Cristo que es la iglesia que ha sido creada y conservada por el Esp&#237;ritu en &#201;feso, y a tener una plena conciencia del servicio que impone el misterio de la gracia para la construcci&#243;n de dicho cuerpo (4:1-16)<\/p>\n<p>Seguidamente les conjura a no recaer en su anterior conducta pagana puesto que les destruir&#237;a, sino que tengan siempre presente la caracter&#237;stica fundamental de la vida cristiana; desnudarse del hombre viejo para revestirse del nuevo (4:7-24).<\/p>\n<p>Las siguientes exhortaciones, que son una clara referencia con respecto a la nueva vida, tienen un objetivo muy claro, en la tercera secci&#243;n, y es que demuestren de una manera eficiente el amor como &#8220;imitaci&#243;n&#8221; del de Dios y del sacrificio de Cristo, que fue realizado por amor (4:25-5:2)<\/p>\n<p>En la cuarta secci&#243;n, se refiere a una conducta pura y luminosa que refleje la luz de Cristo y que toma como s&#237;mbolo el bautismo toda vez que es como morir a la vieja vida para surgir a la nueva (5:3-14)<\/p>\n<p>En la quinta secci&#243;n hay una referencia a la necesaria abstenci&#243;n de la embriaguez mediante el vino (o sus derivados alcoh&#243;licos) que, sin duda, provocan euforia, pero la euforia del cristiano debe ser producida por el Esp&#237;ritu Santo en cuanto que &#233;sta jam&#225;s provoca la anulaci&#243;n del control de los sentidos como ocurre con la embriaguez alcoh&#243;lica. (Llenos del Esp&#237;ritu, s&#237;. P&#233;rdida del control emocional, no) (5:18-20)<\/p>\n<p>La sexta secci&#243;n, muy larga por cierto, tiene por tema el &#8220;hogar cristiano&#8221; y les recuerda cuales tienen que ser sus actitudes respecto a hombre mujer, padres he hijos, amos y esclavos: actitudes que requieren obediencia y amor (5:21-6:9)<\/p>\n<p>Finalmente, el Ap&#243;stol, exhorta de una forma muy encarecida (s&#233;ptima secci&#243;n) que todos se revistan de la armadura de Dios, que la &#250;nica que permite resistir cualquier eventualidad y que ser&#225; la que les conducir&#225; hasta la victoria en el d&#237;a de la tribulaci&#243;n suprema (6:10-20)<\/p>\n<p>Conclusi&#243;n<\/p>\n<p>Como veis hemos repasado la tem&#225;tica general de la Carta y, precisamente, como todas las de Pablo, contiene la esencia del verdadero cristianismo, tanto en el aspecto doctrinal como con aquello que tiene que ver con el comportamiento.<\/p>\n<p>Os resultar&#225; sorprendente comprobar que, a pesar de que sus ense&#241;anzas fueron expresadas en unos usos y costumbres conforme a una distinta cultura, en su esencia, nos son comunes.<\/p>\n<p>Otro aspecto a descubrir es que, tanto en la cultura pagana como en la jud&#237;a, la mayor&#237;a de los conceptos ense&#241;ados por Pablo fueron de una novedad extraordinaria, una aut&#233;ntica revoluci&#243;n y a&#250;n lo son. Por ello es que, aquellos que se permiten opinar que el cristianismo tiene poca cosa que decir, les ser&#237;a bueno estudiar esta Ep&#237;stola de Pablo.<\/p>\n<p>&#161;Que el Se&#241;or bendiga tanto los estudios como a los estudiantes. AMEN <\/p>\n<p>Estudios de la ep&#237;stola a los efesios<\/p>\n<p>Estudio II<\/p>\n<p>Introducci&#243;n del autor<\/p>\n<p>Despu&#233;s de la visi&#243;n preliminar de toda la Carta que vimos en la primera aportaci&#243;n; seguidamente iniciaremos el estudio de la Ep&#237;stola paso a paso a fin de captar aquellas ense&#241;anzas que nos ofrece. Es obvio se&#241;alar la necesidad de tener abierto ante nuestros ojos el texto de la carta que estemos comentando. Tambi&#233;n es aconsejable un buen esp&#237;ritu cr&#237;tico a fin de evitar el tomarse las ense&#241;anzas que se vierten en estos estudios como doctrina &#8220;dogm&#225;tica&#8221;. Dicho en otras palabras: Permitir que sea el Esp&#237;ritu el que nos gu&#237;e a toda verdad puesto que &#8220;la verdad&#8221; tiene una gran variedad de matices y solamente &#201;l nos puede guiar hacia aquellos que sean mas apropiados a nuestra personal necesidad espiritual.<\/p>\n<p>____________________________________________<\/p>\n<p>Como en el resto de sus Cartas, la que Pablo envi&#243; a los efesios, se inicia indicando quien es el remitente y los destinatarios, a&#241;adiendo una frase de salutaci&#243;n y bendici&#243;n. Esta forma de encabezado con dos frases, sigue las normas y costumbres de todas las cartas orientales. En el Nuevo Testamento encontramos semejantes encabezamientos no solo en las carta de Pablo sino tambi&#233;n en 1&#170;.Pedro 1:1ss. As&#237;, pues, Pablo usa la forma corriente de escribir una carta, la forma del epistolario que era usado en las cartas oficiales y de car&#225;cter p&#250;blico, los llamados &#8220;mandatos&#8221; comunes en el mundo hel&#233;nico. De esta manera el Ap&#243;stol da a entender que sus cartas no son privadas, no son cartas personales, sino que son de asuntos p&#250;blicos.<\/p>\n<p>Para indicar al remitente da su nombre en griego, Pablo, en vez del hebreo Saulo, que repite nuevamente en 3:1 y a&#241;adiendo una titulaci&#243;n relativamente breve: &#8220;Ap&#243;stol de Jesucristo por la voluntad de Dios&#8221;. Con eso recalca una vez mas el car&#225;cter &#8220;oficial&#8221; de la carta. Tambi&#233;n queda claro que, tanto por el contenido del t&#237;tulo como por su ampliaci&#243;n se detecta que la suya es una oficialidad especial. Mediante otras de sus cartas sabemos el significado del t&#237;tulo &#8220;Ap&#243;stol de Jesucristo&#8221; que designa a Pablo como mensajero &#8220;&#225;ngel&#8221; de Cristo, legitimado y autorizado por Cristo Jes&#250;s. Entre otras cosas es administrador de la &#8220;gracia&#8221; que Dios le ha dado &#8220;como di&#225;cono (servidor) del evangelio&#8221; (3:7), fue como iniciado por revelaci&#243;n del misterio de Jesucristo (junto con los otros ap&#243;stoles y profetas) del fundamento del templo espiritual que es la iglesia, de la cual Cristo es la piedra angular (2:2ss).<\/p>\n<p>La mayor&#237;a de las caracter&#237;sticas del Ap&#243;stol aparecen en sus cartas anteriores a la de Efesios: Rom. 1:5; 1&#170;. Cor. 12:28ss. Pero en esta son objeto de una meditaci&#243;n mucho m&#225;s intensa ya que Pablo se identifica con los &#8220;santos ap&#243;stoles y profetas&#8221; (3:5) toda vez que tambi&#233;n Pablo ha sido enviado por Jesucristo con poderes concedidos para el ministerio entre los gentiles. Ahora bien, &#233;l es Ap&#243;stol de Cristo &#8220;por voluntad de Dios&#8221; (3:7). Es muy necesario tener en cuenta el papel que tiene en esta carta la delema Deou (voluntad de Dios) que, aplicada a 1:5 donde nos dice que, por amor, nos predestin&#243; a ser adoptados como hijos suyos. Seg&#250;n nos dice en 1:11 fue su voluntad la que predestin&#243; a Israel y tambi&#233;n la que se impuso en la universalidad de sus obras. As&#237;, la voluntad de Dios es dar al universo una Cabeza en la persona de Cristo (1:9-10) Consecuentemente, su voluntad es la que ha decretado la historia de la salvaci&#243;n de Israel, el destino eterno de cada uno de los creyentes y el destino escatol&#243;gico de ielos y tierra, Todo eso ya se ha puesto en marcha toda vez que se ha iniciado con la iglesia. Su voluntad es la voluntad salvadora eterna y providencial. Dicha voluntad tambi&#233;n se deja captar por el hecho de que Pablo haya llegado a ser Ap&#243;stol de Cristo Jes&#250;s; y, por supuesto, mediante el profundo sentido del como entiende &#233;l su apostolado. Es una sola voluntad que lo abarca todo, a la que se deben todas las cosas, y de ella y por ella es que deben todas las cosas, y de su cumplimiento depende todo, incluso el que nosotros, a quien quiere desde la eternidad, le escuchemos a &#233;l obrando consecuentemente. (5:17. 6:6) Por esta causa es que el apostolado no se fundamenta en voluntades individuales aisladas o de grupos hist&#243;ricos, sino que es la expresi&#243;n de la voluntad de Dios. Esta voluntad la encontraremos bien expresada estudiando la Carta que Pablo dirigi&#243; a la iglesia de los efesios.<\/p>\n<p>Psemos a otra consideraci&#243;n de la carta: se trata de saber a quien fue dirigida. En todas las traducciones que tenemos a nuestro alcance. Se dice: &#8220;A los santos y fieles en Cristo Jes&#250;s que est&#225;n en Efeso&#8221;. Pero en las reproducciones m&#225;s antiguas y en su idioma original, en griego, dice as&#237;: tois alioi tois ousin kai pistois en Cristo Ih sou, es decir, falta Efesious. despu&#233;s de santos y fieles se omiti&#243; una designaci&#243;n de lugar. &#191;Cu&#225;l puede ser el significado de dicha omisi&#243;n? La falta de una indicaci&#243;n de lugar en los textos m&#225;s antiguos de la carta lo hemos de entender en el sentido de que el mencionado texto fue omitido a fin de que se insertara posteriormente el nombre de sus destinatarios en la copia que se hiciese para la comunidad correspondiente. Entonces nuestra carta a los Efesios no fue una carta especialmente dirigida a una sola comunidad, como por ejemplo la carta a los colosenses, ni una carta circular en un sentido t&#233;cnico, sino sencillamente una carta destinada a diversas comunidades que ten&#237;a v&#237;nculos entre s&#237;. En el lugar en que fuese le&#237;da por primera vez, se har&#237;an reproducciones de la misma para el resto de iglesias vinculadas. Lo que ignoramos, ni tenemos manera de averiguar, es el c&#243;mo desde sus principios apareci&#243; la titulaci&#243;n &#8220;a los efesios&#8221;. Tal vez mediante T&#237;tico (2. Tim. 4:12) Entonces se pudo incluir el nombre de los destinatarios: &#8220;a los Efesios&#8221;. Al coleccionar las cartas paulinas y por el hecho de no poseerse ninguna indicaci&#243;n de direcci&#243;n, esta fue incorporada a la Carta y, de esta manera, la carta de Pablo a las iglesias de la Frigia se convirti&#243; en carta dirigida a los santos en Efeso. la<\/p>\n<p>Pablo escribe &#8220;a los santos y fieles en Cristo Jes&#250;s&#8221;. As&#237;, pues, todos los miembros de la iglesia son santos. Hay que tener en cuenta que el adjetivo &#8220;santo&#8221; no tiene nada que ver con la perfecci&#243;n &#233;tico- moral. Cuando las Escrituras dicen que Dios es Santo no se refiere a su condici&#243;n moral, sin la expresi&#243;n de una &#8220;separaci&#243;n&#8221;. Es un Ser separado de nuestro ser en cuanto goza de una distinta naturaleza. As&#237;, los que han sido incorporados al Cuerpo de Cristo, que es la iglesia, han sido separados del mundo. La iglesia como comunidad de fieles a Cristo forma una nueva sociedad que anhela algo distinto de la sociedad humana. Sus apetencias se dirigen al Reino de Dios y su justicia. Un Reino que no es de este mundo, tal como dijo con toda claridad el mismo Jes&#250;s.<\/p>\n<p>Como conclusi&#243;n cabe remarcar que la primera oraci&#243;n de la carta se conforma a los usos y costumbres usuales a la &#233;poca. Quien la escribi&#243; fue un hombre llamado Pablo, un hombre que fue iniciado por Cristo en el misterio de la voluntad de Dios y que recibi&#243; plenos poderes; que fue enviado a proclamar dicho misterio y a representarle a &#233;l. Es uno de los &#8220;santos ap&#243;stoles&#8221;. Cuando su carta sea le&#237;da p&#250;blicamente en la comunidad cristiana a la cual fue remitida, escuchar&#225;n el mensaje de Cristo mediante los labios de un enviado suyo. Aquellos a quien escribe el mensajero de Dios y de Cristo son unos cuantos habitantes de peque&#241;as ciudades de la Frigia en el valle del r&#237;o Licus, que celebran sus reuniones en diversas casas. Y les dice que son &#8220;santos&#8221;. Lo son por haber llegado a la fe. Lo son &#8220;en Cristo&#8221;. En &#233;l tienen su fundamento por medio de la fe. Les es necesario leer la carta una y otra vez a fin de captar sus profundidades. Eso es lo que tambi&#233;n nosotros procuraremos hacer al divulgar estos estudios mediant la asistencia del Esp&#237;ritu de Dios que, en definitiva, fue quien la inspir&#243;. AMEN <\/p>\n<p>Estudios en la carta (III)<\/p>\n<p>Primera Parte: 1:3 &#8211; 3:21<\/p>\n<p>El misterio de la vocaci&#243;n de los gentiles en el cuerpo de Cristo.<\/p>\n<p>Introducci&#243;n.-<\/p>\n<p>Esta primera parte de la Carta se inicia con una alabanza a Dios y despu&#233;s de una breve y tradicional menci&#243;n de acci&#243;n de gracias por la fe y amor de los destinatarios (1:15-16), pasa a expresar una oraci&#243;n con el prop&#243;sito de que adquieran esp&#237;ritu de sabidur&#237;a. Seguidamente, y en un doble curso de pensamiento que va desde 2:2-10 y 2.11-22, se describe el acto de salvaci&#243;n que se ha realizado a favor de dichos destinatarios.<\/p>\n<p>Cuerpo del Estudio.-<\/p>\n<p>En el original griego este pasaje que va desde el v. 3 al 14 es una sola oraci&#243;n. Es tan largo porque adem&#225;s de un enunciado es tambi&#233;n una eulogia (alabanza), es decir, un l&#237;rico canto de alabanza. Parece ser que la mente de Pablo desarrolla su pensamiento no mediante la l&#243;gica, sino m&#225;s bien teniendo en cuenta los dones y maravillas de Dios que penetraron en su mente cuando fue escogido por Jesucristo como su ap&#243;stol en pro de los gentiles.<\/p>\n<p>En este pasaje Pablo piensa en los cristianos como el pueblo escogido de Dios. Ahora bien en nuestra cultura el concepto de pueblo es distinto del significado que tenia &#8211; y tiene- entre los jud&#237;os, los cuales lo entienden como &#8220;creaci&#243;n de Dios&#8221;. Un pueblo, en sus distintas dimensiones, son una agrupaci&#243;n social que se forma por diversos intereses que ayudan a su integraci&#243;n. El &#8220;pueblo de Dios&#8221; debe su integraci&#243;n a la acci&#243;n divina. Es la respuesta de unas determinadas personas que, &#8211; aun teniendo intereses sociales distintos; cultura, ubicaci&#243;n geogr&#225;fica, lengua, estado social, etc.- dieron una respuesta positiva al llamado de Dios para formarlo. As&#237;, pues, es &#8220;creaci&#243;n de Dios&#8221;, toda vez que &#233;l ha escogido y seleccionado a todos aquellos que lo conforman. La comunidad eclesial de Efeso estaba formada por jud&#237;os y gentiles, es decir, diversa cultura y mentalidad y solo Dios tiene la capacidad de hacer de ambos un solo pueblo. Este es, sin duda, el sentido de edificar la iglesia que cita Mat. 16:18 de lo cual se deduce que la iglesia est&#225; en constante construcci&#243;n y esta no acabar&#225; hasta el fin de los tiempos. Ser&#225; entonces cuando la iglesia ser&#225; aut&#233;nticamente &#8220;santa&#8221; (en el sentido de perfecci&#243;n &#233;tica, es decir, sin mancha). Pero mientras sus miembros (1:3) han sido bendecidos hasta las ra&#237;ces de su existencia y, en medio de los abismos de la trascendencia de los poderes c&#243;smicos, nos hallamos seguros en Cristo Jes&#250;s. (Rom. 8:32-39)<\/p>\n<p>En el v. 1:4 Pablo comienza a definir en qu&#233; consiste dicha bendici&#243;n. La inicia con un kadoz , que significa &#8220;seg&#250;n&#8221;, &#8220;por cuanto&#8221; se desarrolla y aplica esta acci&#243;n de Dios de la que nos presenta tres aspectos:<\/p>\n<p>&#8211; Escogidos desde antes de la fundaci&#243;n del mundo,<\/p>\n<p>&#8211; para que fu&#233;semos santos y sin mancha delante de Dios<\/p>\n<p>&#8211; y en amor habi&#233;ndonos predestinado para ser adoptados hijos suyos por medio de Jesucristo.<\/p>\n<p>Pablo con estas palabras est&#225; intercalando tiempo y eternidad. Debemos tener presente que el tiempo es una propiedad de nuestro universo y que fuera de &#233;l el tiempo no existe. El tiempo es un fluir constante desde un pasado hacia un futuro y en el que no hay presente debido a &#233;ste constante fluir, en cambio eternidad es un presente absoluto donde no hay pasado ni futuro. Entonces Dios, desde este presente absoluto escogi&#243; a aquellos que se realizar&#237;an en el tiempo. En el tiempo oir&#237;an su llamada y la respuesta a dicha llamada se convertir&#237;a en su vocaci&#243;n la vocaci&#243;n de ser&#8230; santos y sin mancha delante de Dios, es decir, en la eternidad puesto que fueron predestinados &#8211; en la eternidad o fuera del tiempo- a ser adoptados hijos suyos por medio de Jesucristo. De aqu&#237; que la salvaci&#243;n sea un don de Dios y la seguridad de dicha salvaci&#243;n est&#225; en que ya ha sido realizada. Si la condici&#243;n fuesen nuestras obras entonces se tendr&#237;a que realizar en el tiempo y no en la eternidad. Pablo lo define como pro katabolh s kosmou (antes de la fundaci&#243;n del cosmos) y le a&#241;ade que fue hecho en Cristw (en Cristo) 1.3. Consecuentemente nosotros, los creyentes y santos, nunca dejamos de estar en Cristo, seg&#250;n la voluntad de Dios. Como cristiano, que significa ser bendito en Cristo, soy ahora lo que he sido siempre, y antes que todas las cosas, por la elecci&#243;n divina. &#8220;Ser&#8221; para el cristiano que est&#225; en Cristo, no significa simplemente ser en el mundo, o ser una mera criatura, sino haber sido elegido desde siempre por Dios. El mismo pensamiento lo encontramos en Rom. 8:28-30.<\/p>\n<p>Otro prop&#243;sito de esta elecci&#243;n es el que se cita en el segundo enunciado &#8220;para que fu&#233;semos santos y sin mancha delante de Dios&#8221; En el original griego de esta frase Pablo usa dos vocablos agios que significa santos y amomos (perfecto, sin mancha) pero amomos tiene tambi&#233;n una connotaci&#243;n cultual, amomos ten&#237;a que ser el animal escogido para un sacrificio, aunque tambi&#233;n se utilizaba en el sentido general de irreprochable, sin tacha.<\/p>\n<p>El tercer enunciado afirma que todo eso ha sido motivado por amor. Eso elimina cualquier otra explicaci&#243;n teol&#243;gica respecto al obrar de Dios. Con eso hago una referencia a quienes tienen una concepto err&#243;neo de la predestinaci&#243;n que atribuyen a la soberan&#237;a de Dios, si se les pregunta que quienes no han sido predestinados para salvaci&#243;n lo habr&#225;n sido para condenaci&#243;n. A eso siempre responden que era un atributo de la soberan&#237;a de Dios. Si Dios obra por amor, en amor nadie puede ser predestinado para condenaci&#243;n. Comprendo que no es f&#225;cil entender como aquello que el hombre decide en el tiempo tiene efectos en la eternidad, fuera del tiempo. Solo se nos da saber el resultado y el resultado es que Dios sabe desde la eternidad, desde un presente absoluto, cual ser&#225; la libre decisi&#243;n de un determinado ser humano en su tiempo. Hay una frase en la oraci&#243;n que Jes&#250;s ense&#241;&#243; a sus disc&#237;pulos que clarifica lo que estamos diciendo, est&#225; en Mat. 6:10 &#8220;venga tu reino&#8221;. El creyente que pronuncia esta frase est&#225; diciendo que es partidario del Reino de Dios y su Justicia. Que desea vivamente el Reino de Dios por encima de cualquier otro reino. Entonces, si tenemos en cuenta que este reino, Dios lo ofrece gratuitamente como un don que viene de &#201;l y solo de &#201;l y que no obliga a nadie a aceptarlo, nos damos perfecta cuenta que la elecci&#243;n en el tiempo depende exclusivamente de cada uno de nosotros. Ahora bien, Dios conoce perfectamente la mente humana, conoce nuestras dudas (y las posibles dudas de los efesios) y de aqu&#237; que, para eliminar cualquier duda, les asegure que aquello que ellos &#8211; y nosotros- hemos aceptado en el tiempo tambi&#233;n ha sido rubricado en la eternidad. Es decir, aquello que ahora nosotros tenemos como una esperanza ya se ha realizado en la eternidad. Pablo lo afirma de esta manera en 1:18-23.<\/p>\n<p>Esta elecci&#243;n personal Pablo la define en 1:13 donde escribe: &#8220;En &#233;l tambi&#233;n vosotros, habiendo o&#237;do la palabra de verdad, el evangelio de vuestra salvaci&#243;n&#8230; (lo entenderemos mucho mejor traduciendo la palabra evangelio ya que entonces dir&#237;a; &#8220;la buena nueva de vuestra salvaci&#243;n&#8221;) Rehagamos la frase la cual seria de esta manera: &#8220;En &#233;l tambi&#233;n vosotros, habiendo o&#237;do la palabra de verdad, la buena nueva de vuestra salvaci&#243;n, y habiendo cre&#237;do en &#233;l, fuisteis sellados con el Esp&#237;ritu Santo de la promesa, que es las arras de nuestra herencia hasta la redenci&#243;n de la posesi&#243;n adquirida, para alabanza de su gloria&#8221;. <\/p>\n<p>\nELECCI&#211;N ETERNA EN CRISTO<\/p>\n<p>Estudio IV.-<\/p>\n<p>Texto B&#225;sico. Efe. 1:5-6.-<\/p>\n<p>Introducci&#243;n.-<\/p>\n<p>Como dijimos en el pasado estudio, somos hijos de Dios mediante Jesucristo, cosa que fue determinada por Dios desde la eternidad, es decir, antes de la creaci&#243;n del mundo. Eso quiere decir que previamente fue determinado por Dios. En Rom. 8:14-16 y en G&#225;l. 4:4-6 se nos dice que somos hijos de Dios por la acci&#243;n salvadora de Cristo y por la recepci&#243;n del Esp&#237;ritu Santo. Tambi&#233;n lo podemos definir en el sentido de haber accedido a la condici&#243;n de hijos toda vez que hemos sido part&#237;cipes de la filiaci&#243;n divina de Jesucristo a quien hemos sido incorporados.<\/p>\n<p>Cuerpo del Estudio.-<\/p>\n<p>No cabe duda que, la referencia a Jesucristo, por quien somos hijos de Dios, remarca el car&#225;cter de gracia &#8211; o de pura gracia- de Aquel que Dios destin&#243; a nuestro favor desde la eternidad. Este ser hijos no nos corresponde desde la perspectiva de nuestra naturaleza, sino que &#8211; mediante Jesucristo- hemos sido liberados de nuestro funesto d&#233;bito de culpa. Tampoco se debe mediante una procedencia de &#8220;pueblo santo&#8221; ni por nuestro cumplimiento de la ley &#8211; como los jud&#237;os- , sino que nuestro ser hijos y descendencia del Padre lo hemos recibido mediante Cristo y, consecuentemente, lo tenemos por &#233;l. Desde la eternidad, la santa condici&#243;n de hijos llega a nosotros como un don &#8211; un regalo- de Cristo.<\/p>\n<p>Por amor nos predestin&#243; a ser adoptados como hijos suyos (v.5) A fin de entender esta frase de Pablo hay que tener en cuenta a que tipo de adopci&#243;n se refiere. O mejor a&#250;n, que era lo que Pablo y los receptores de su carta entend&#237;an con respecto a la adopci&#243;n. Efeso estaba bajo la jurisprudencia romana y su sociedad se reg&#237;a conform&#225;ndose a sus leyes. Adem&#225;s, tambi&#233;n hay que tener presente que toda la regi&#243;n llamada Capadocia aceptaron de buen grado las leyes romanas despu&#233;s de su integraci&#243;n al Imperio. Sus ciudades eran Ciudades Senatoriales por lo que se reg&#237;an por las leyes emanadas por el Senado Romano y sus ciudadanos eran a la vez ciudadanos romanos.<\/p>\n<p>Entonces las iglesias que recibieron dicha Carta &#8211;recordemos que se trat&#243; de una carta circular enviada a las iglesias de la Regi&#243;n, tal como comentamos en la introducci&#243;n de la misma- entendieron que la adopci&#243;n mencionada por Pablo se conformar&#237;a al concepto romano de la misma. Al menos en su similitud, porque al estudiarla nos damos cuenta de que existe la mentada similitud.<\/p>\n<p>\nLa adopci&#243;n en el Imperio Romano y conforme a sus leyes ten&#237;a como base la patria potestad del &#8220;Pater Familias&#8221; Este t&#237;tulo ten&#237;a un especial significado puesto que dicho Pater familias jam&#225;s independizaba a sus hijos, es decir, la familia era indivisible. Dicho Pater ten&#237;a derecho de vida y muerte sobre sus hijos, as&#237; ning&#250;n hijo ten&#237;a que responder de sus actos ante la ley, solo ante su padre y en caso de que hubiese cometido un delito la ley se dirig&#237;a al padre y le informaba del delito cometido y este marcaba el castigo al que se ten&#237;a que someter. Pod&#237;a condenarle de muerte y ejecutarle personalmente, ordenar que fuese encarcelado, o vendido como esclavo. En cuanto a la adopci&#243;n, la persona adoptada adquir&#237;a una nueva personalidad. Todo su pasado quedaba borrado y era lo mismo que si hubiese nacido en aquel momento y siendo considerado como hijo engendrado por su nuevo padre y adquiriendo todos los derechos y deberes de hijo. Esto llegaba hasta el de ser declarado heredero universal del padre, que era quien determinada quien de entre sus hijos seria su sucesor como Pater Familias. Como ejemplo podemos citar el caso de Ner&#243;n. Este era hijo de Cneio Domici Ahenobarbo y de Agripina la Joven que, a su vez, era hija de Germ&#225;nico y de Agripina la Mayor. Se cas&#243; en terceras nupcias con su t&#237;o Claudio de quien consigui&#243; que su hijo Ner&#243;n fuese adoptado por este y, adem&#225;s, que le declarase su heredero universal. Conseguido eso le envenen&#243; y Ner&#243;n fue nombrado Emperador como Pater Familias de la Familia Claudia. El premio que Agripina obtuvo con ello fue el ser asesinada por el hijo a quien hab&#237;a favorecido. Tambi&#233;n Cal&#237;gula lleg&#243; a Emperador como hijo adoptivo de Tiberio, que tambi&#233;n lo fue de Augusto e incluso este lo fue de Julio Cesar. (De hecho la Familia Claudia fue un aut&#233;ntico galimat&#237;as)<\/p>\n<p>Evidentemente esta menci&#243;n respecto a ley romana sobre la adopci&#243;n la ha motivado el hecho de saber en que pensaba Pablo cuando dijo que Dios nos predestin&#243; a ser adoptados como hijos suyos. Pablo repite este concepto en Rom. 8:14-17 donde la frase m&#225;s importante esta en el verso 16 &#8220;El Esp&#237;ritu mismo da testimonio a nuestro esp&#237;ritu, de que somos hijos de Dios&#8221;. Y lo somos a fin de que seamos un himno de alabanza a su gloria y generosidad, con la cual nos ha llenado de favores en el Esp&#237;ritu. As&#237;, cada uno de nosotros es un canto de alabanza, puesto que el cambio que se ha realizado en nuestras vidas y en nuestro destino es incomparable, toda vez que somos una nueva creaci&#243;n realizada por Dios. A fin de entender con m&#225;s claridad lo referente a esta &#8220;nueva creaci&#243;n&#8221; podemos remitirnos a lo que se dice en G&#233;nesis 1:2 &#8220;Y la tierra estaba desordenada y vac&#237;a, y las tinieblas estaban sobre la faz del abismo&#8230;&#8221; Esta frase vista a la luz de la ciencia moderna vienen a significar el caos. Todo el universo era ca&#243;tico y Dios lo convirti&#243; en liso y uniforme mediante &#8220;Sea la luz&#8221; (3) Luz igual a energ&#237;a, es decir, la potencia que separ&#243; la luz de las tinieblas. Si aplicamos eso al hombre y sus circunstancias queda claro que el pecado (las tinieblas) predominaban en su vida, era el caos, y la luz, la energ&#237;a de Dios, le ha conducido a una nueva ordenaci&#243;n donde la luz ha predominado sobre sus tinieblas y de la misma manera que los cielos (liberados del caos) cantan la gloria de Dios el hombre librado del caos y las tinieblas del pecado entona un canto alabanza a Dios. El mismo concepto lo encontramos en Col. 3:9b-10: &#8220;&#8230;habi&#233;ndoos despojado del viejo hombre, y revestido del nuevo, el cual conforme a la imagen del que lo cre&#243; se va renovando hasta el conocimiento pleno&#8221; Aqu&#237; Pablo nos recuerda algo muy interesante y es aquello que motiv&#243; al hombre a pecar contra Dios (Gen. 3:5b &#8220;&#8230;ser&#225;n abiertos vuestros ojos, y SER&#201;IS COMO DIOS, sabiendo el bien y el mal&#8221;) Es decir, el hombre no se conform&#243; con ser hecho a imagen de Dios y quiso ser igual a Dios. Este pecado no fue solo de Ad&#225;n sino que es el de toda la humanidad y est&#225; presente hoy con incluso m&#225;s intensidad que cuando se provoc&#243; la primera vez. Todas las ambiciones humanas est&#225;n bajo el signo de este pecado y quienes lo evidencian con mas claridad son aquellos que pretenden un jerarqu&#237;a sobre los dem&#225;s, aquellos que pretenden gobernarlo todo y a todos &#8220;por la gracia de Dios&#8221;. La r&#233;plica de Dios al pecado del hombre fue maravillosa. A lo largo de toda la Revelaci&#243;n b&#237;blica que culmina con la venida de Jesucristo, Dios nos dice: Has querido ser igual a Dios y con ello renunciaste a tu humanidad. Las consecuencias de semejante locura ha sido un constante proceso de deshumanizaci&#243;n. Te convertiste en un depredador en contra de tus hermanos los hombres y hab&#233;is venido a ser enemigos de todo y de todos incluy&#233;ndome a m&#237; que fui tu Creador. No entendisteis la gloria que os conced&#237; al haceros a mi imagen. Bien, ahora os voy a mostrar el valor de dicha dignidad haci&#233;ndome un hombre como vosotros. (Sal. 8:5)<\/p>\n<p>&#191;C&#243;mo, pues, todos aquellos que han recibido a Cristo como su Se&#241;or y Salvador no van a alabar a Dios? Al Dios que les ha llenado de bendici&#243;n desde toda la eternidad. Hijos de Dios mediante Jesucristo. Pero es que, adem&#225;s, los cristianos no hemos sido bendecidos &#250;nicamente al ser elegidos por Dios desde la eternidad, sino tambi&#233;n por haber experimentado aquel amor que Dios tiene para su Hijo &#218;nico, a su Hijo por excelencia. De este amor nos habla Pablo en Rom. 8:39. Y, adem&#225;s, est&#225; confirmado en Juan 17:23. Visto todo esto aun cabe preguntarnos en qu&#233; consiste el amor y en qu&#233; la gracia de Dios que tan benignamente nos ha concedido &#8220;en el Amado&#8221; en el cual &#8220;tenemos redenci&#243;n en su sangre, el perd&#243;n de pecados seg&#250;n las riquezas de su gracia. Pablo una aqu&#237; usa aqu&#237; el vocablo griego apolitrosis (apolitrosis) que viene a significar, por un lado, al liberaci&#243;n previo pago de un rescate, por ejemplo la redenci&#243;n de cautivos o delincuentes, tambi&#233;n liberaci&#243;n o redenci&#243;n de una situaci&#243;n extrema que la capacidad humana individual no puede conseguir, como en el caso del Rey Nabucodonosor en Dan. 4:34 (es necesario leer el contexto en 4:28.34) En aquella situaci&#243;n el poderoso Rey de Babilonia nada pod&#237;a hacer a fin de librarse de aquella situaci&#243;n y por ello reconoce que solo el Dios Alt&#237;simo que anunciaba el profeta Daniel ten&#237;a dicha capacidad. Todos y cada uno de los cristianos ha tenido que reconocer que viv&#237;a una situaci&#243;n parecida y que su liberaci&#243;n ha sido por obra del Alt&#237;simo.<\/p>\n<p>Incluso los antiguos paganos &#8211; no tanto los modernos- reconoc&#237;an su impotencia para librarse de su condici&#243;n de fracaso. S&#233;neca dijo de s&#237; mismo que era un homo non tolerabilis, a&#241;adiendo que la totalidad de los hombres aman a sus vicios al tiempo que los odian necesitando una mano que baje a fin de levantarles. Como vemos mostraba la misma incapacidad que manifest&#243; el Rey de Babilonia.<\/p>\n<p>En el octavo vers&#237;culo Pablo afirma que Cristo, mediante su gracia, nos ha hecho sobreabundar en toda sabidur&#237;a e inteligencia. Esta afirmaci&#243;n tiene dos vertientes, una espiritual y otra que, en nuestro tiempo y cultura bien la podemos cualificar de cient&#237;fica. Interesante tema que desarrollaremos en el pr&#243;ximo estudio. <\/p>\n<p>Estudio n&#186; V.-<\/p>\n<p>CONOCIMIENTO Y SABIDUR&#205;A CRISTIANA<\/p>\n<p>Texto B&#225;sico. Ef. 1:8-10.-<\/p>\n<p>Introducci&#243;n:<\/p>\n<p>Finalizamos el pasado estudio diciendo a este tema tenemos dos aspectos, uno cient&#237;fico y otro espiritual. Personalmente lo encuentro altamente interesante aunque hay que tener muy presente que en el mismo ha un evidente peligro que, en muchas ocasiones, los cristianos &#8211;tanto los que lo son de una forma nominal, como los que podemos considerar aut&#233;nticos o con un compromiso real- hay ca&#237;do en el mismo y con resultados nefastos para el testimonio cristiano. Hecha esta advertencia pasemos a considerar lo que Pablo nos dice en esta pericopia.<\/p>\n<p>Cuerpo del Estudio.-<\/p>\n<p>I.- La sabidur&#237;a espiritual.-<\/p>\n<p>Pablo, despu&#233;s de afirmar que se ha hecho sobreabundar la sabidur&#237;a y la inteligencia (v. 8), en el 9 hace una sorprendente afirmaci&#243;n: &#8220;d&#225;ndonos a conocer el mu sth rion (misterio) de su voluntad. He remarcado el vocablo coloc&#225;ndolo en griego como en el original por una raz&#243;n. Misterio, -al contrario que &#8220;inc&#243;gnita&#8221;- no puede ser desvelado mediante la capacidad humana. Ejemplo: Dios no puede ser ni desvelado ni comprendido por el hombre, de ah&#237; la necesidad de que el mismo Dios se haya &#8220;revelado&#8221; al hombre. Mediante dicha revelaci&#243;n el hombre puede entender de Dios aquello que Dios a dicho de s&#237; mismo. Por esta raz&#243;n Pablo dice &#8220;d&#225;ndonos a conocer el misterio&#8221;. Dar a conocer es sin&#243;nimo de &#8220;revelar&#8221;. Tambi&#233;n se podr&#237;a decir de esta otra manera: &#8220;Nos ha hecho conocer su designio secreto&#8221;.<\/p>\n<p>De hecho Pablo tiene muchas referencias respecto a lo que estamos comentando en 1. Cor. 2:7-9 y a Col. 1:26-27, y tambi&#233;n en dicha carta a los Colosenses se contempla la &#237;ntima relaci&#243;n de Cristo con la sabidur&#237;a (2:2). Dicha sabidur&#237;a, que hasta entonces fue escondida desde los eones del tiempo nos ha estado revelada en &#233;l y por medio de &#233;l en la predicaci&#243;n inspirada por &#233;l a Pablo (Col. 4:3) Adem&#225;s, en Efesios Pablo afirma que se trata de un misterio excelente (Efes. 3:3-5)<\/p>\n<p>Resumiendo, bien podemos decir que se trata del conocimiento de la voluntad de Dios, y no mediante elucubraciones filos&#243;ficas propias del pensar humano que, una de las m&#225;s acertadas y esgrimida por los ateos, es aquella que afirma que los dioses son creaci&#243;n de la mente humana. Cierto, hay miles de dioses creados por la f&#233;rtil mente humana, pero a la vez dicha fertilidad imaginativa nos muestra la necesidad que el hombre tiene de Dios, puesto que se hace preguntas que no tienen respuesta, una de ellas es: &#191;Qu&#233; sentido tiene la vida&#8221; &#191;Se puede responder a eso ninguno, no tiene ning&#250;n sentido? No, porqu&#233; quien tiene est&#225; inquietud jam&#225;s la aceptar&#225;. O ante la falta de respuesta su &#250;nica opci&#243;n ser&#225; procurar olvidarse de ella. Es estos mismos foros encontr&#233; la pregunta de una muchacha que escribi&#243;: &#8220;&#191;Y despu&#233;s, qu&#233;? Dejo la pregunta en el aire esperando respuestas. Pero aquellos que no tienen otro medio que la propia imaginaci&#243;n crear&#225;n divinidades que, de alguna manera, satisfagan su necesidad. Para darse cuenta de ello solo es necesario hacer un estudio de la gran diversidad de religiones que existen, o han existido, y pronto nos daremos cuenta que todas ellas est&#225;n adaptadas a las formas culturales de la sociedad donde aparecieron y que, por ello, tienen un dif&#237;cil trasvase a lo universal. Tenemos un ejemplo claro de ello con el budismo, junto con otras formas de religiosidad de origen hind&#250;, que pareces estar de moda en nuestro mundo occidental, pero no pasa mucho tiempo en mostrarse como un h&#237;brido, es decir, no tienen continuidad por falta de un mensaje comprensible a nuestra cultura. Por el contrario el misterio de Dios revelado en Cristo, fue un cambio total con respecto a las culturas donde se desarroll&#243;, es decir, un cambio absoluto para el juda&#237;smo y tambi&#233;n para el paganismo. Por ello, inicialmente fue rechazado por parte de ambas culturas. Ahora bien, ten&#237;a la autenticidad del &#218;nico Dios verdadero y consecuentemente era universal. Esta es la causa de que, desde esta perspectiva, hay cristianos en medio de todas las culturas de nuestro mundo.<\/p>\n<p>El paganismo ha desaparecido aunque quedan retazos del mismo que aun inciden en el cristianismo, especialmente en el catolicismo romano que, por esta causa es la menos universal de las distintas formas de cristianismo. Cualquier lector de estas p&#225;ginas y con una m&#237;nima capacidad de observaci&#243;n se puede dar cuenta que en pa&#237;ses de distinta cultura, el llamado catolicismo se sostiene mediante una asimilaci&#243;n de los antiguos mitos de aquella cultura. A eso tambi&#233;n le podemos a&#241;adir su defensa de lo que llaman la &#8220;tradici&#243;n&#8221; lo cual es una evidente muestra de su falta de universalidad. Claro que hay que reconocer que muchos misioneros -no todos, evidentemente- cristianos del protestantismo, cayeron en el mismo error enfatizando m&#225;s su cultura de procedencia que el aut&#233;ntico mensaje cristiano.<\/p>\n<p>Con respecto al juda&#237;smo vemos que ha quedado circunscrito entre aquellos que tienen un origen jud&#237;o y no se ha universalizado. Lo mismo ocurre con el mahometismo que tampoco tiene una expansi&#243;n universalista por mucho que sus l&#237;deres se esfuerces en ello. Adem&#225;s, culturalmente est&#225; en plena decadencia. Una cultura que no evoluciona, y que por ello no tiene el m&#225;s m&#237;nimo progreso. Una muestra de ello lo tenemos con el trato que dan a la mujer; a la que, en la pr&#225;ctica, ni siquiera la consideran un ser humano.<\/p>\n<p>II.- La Sabidur&#237;a cient&#237;fica.-<\/p>\n<p>Actualmente hay un claro divorcio entre ciencia y religiosidad. Parece ser que hay una mayor&#237;a de intelectuales que opinan que son dos conceptos irreconciliables a pesar de que haya un fuerte n&#250;mero de cient&#237;ficos que son creyentes. Lo que est&#225; claro es que la culpa de esta situaci&#243;n no se puede atribuir a los cient&#237;ficos sino de los religiosos. Que, en demasiadas ocasiones han pretendido, y a&#250;n pretenden, pontificar en un campo que no es de su competencia. Creen que en la Biblia tienen una explicaci&#243;n de todas las cosas y si bien es cierto que las hay y muy precisas, no es menos cierto que la Biblia no es una colecci&#243;n de libros de ciencia. Si a eso le a&#241;adimos que aquello que la Biblia dice estar&#225; a merced de la interpretaci&#243;n de su lector. Y a&#250;n tendremos que a&#241;adirle otra dificultad, la dependencia al acondicionamiento filos&#243;fico del int&#233;rprete. Un ejemplo claro de ello la encontramos con la condena de Galileo Galilei que su visi&#243;n de nuestro sistema solar choc&#243; de pleno con el de Ptolomeo que era el que daba por bueno la Instituci&#243;n que le conden&#243;. Los jueces de la Inquisici&#243;n no se basaron en la Revelaci&#243;n B&#237;blica, sino en las concepciones de un fil&#243;sofo griego y pagano. (Nueva falta de universalidad)<\/p>\n<p>Lo que si nos dice la Biblia es quien cre&#243; la vida en medio del universo y una cosa creada por Dios ha de tener sentido y el que no lo tiene es su desaparici&#243;n. Aquello que Juan dice al inicio de su evangelio es definitivo: &#8220;Todas las cosas por &#233;l fueron hechas, y sin &#233;l nada de lo hecho fue hecho. En &#233;l estaba la vida, y la vida era la luz de los hombres. La luz en las tinieblas resplandece, y las tinieblas no prevalecieron contra ella&#8221; (Jn. 1:3-5). Como vemos, en muy pocas palabras nos descubre el misterio de la creaci&#243;n divina. Pero nada dice del como de desarrolla la vida en cuanto que este es un campo que pertenece a la ciencia. Y m&#225;s, si tenemos en cuenta que la ciencia es el resultado de la capacidad del cerebro humano, cerebro creado por Dios y, por ende, tambi&#233;n es ciencia de Dios. S&#233; que se puede objetar que la ciencia humana ha cometido errores pero, precisamente los errores hacen progresar dicha ciencia toda vez que los cient&#237;ficos saben que est&#225; sujetos a errores, capacidad de error, y sabi&#233;ndolo, tambi&#233;n tienen el de rectificaci&#243;n. S&#243;lo aquellos que pretenden tener la verdad absoluta &#8211;los infalibles- carecen de esta capacidad de rectificaci&#243;n y se dedican a condenar a todos aquellos que no aceptan su pretendida &#8220;verdad&#8221;.<\/p>\n<p>Como conclusi&#243;n diremos que al cristiano le ha sido revelado el misterio de la relaci&#243;n querida por Dios con el hombre mediante Jesucristo. Dicha revelaci&#243;n incluye todas las cosas, es decir, desde la creaci&#243;n del Universo a la creaci&#243;n de la vida y la del hombre como ser vivo que es. Pero lo realmente importante es que la vida del hombre, tanto colectiva como individualmente, tiene sentido. Todo cuanto somos y pensamos no esta condenado a la desaparici&#243;n puesto que se nos ofrece ser algo m&#225;s que una creaci&#243;n. Ser hijos de Dios y como hijos herederos de su gloria manifestada, precisamente, en la creaci&#243;n. As&#237; es como la vida adquiere un aut&#233;ntico sentido. Aquella pregunta que apareci&#243; en los foros: &#191;Y despu&#233;s, qu&#233;? Tiene una respuesta. Una respuesta que no se puede fundamentar por medio de la ciencia, sino en la Revelaci&#243;n, puesto que la ciencia humana, nuestra ciencia, jam&#225;s tendr&#225; todas las respuestas.<\/p>\n<p>Estudio VI.-<\/p>\n<p>ORACI&#211;N Y ACCI&#211;N DE GRACIAS<\/p>\n<p>Texto B&#225;sico. Efes. 1:15-23<\/p>\n<p>Introducci&#243;n.<\/p>\n<p>Pablo en el ver. 16 afirma que no cesa de dar gracias a Dios por todos aquellos que recibieron su carta. En esta alabanza a Dios, el Ap&#243;stol hace que tambi&#233;n sea una intercesi&#243;n a favor de las comunidades a las que envi&#243; su misiva. As&#237;, Pablo da gracias al Se&#241;or (1:15ss) por la fe y el amor de los creyentes pero, adem&#225;s, esta acci&#243;n de gracias se enlaza, en el ver. 16b, con la petici&#243;n al Se&#241;or a que les sea revelado el conocimiento de la esperanza que reposa y se confirma en Cristo Jes&#250;s (ver, 17-19) Da la sensaci&#243;n que, subyugado por el tema que su intercesi&#243;n evoca, Pablo inicia un nuevo himno de alabanza, enalteciendo todo aquello que Dios ha realizado mediante Jesucristo. (ver, 20-23)<\/p>\n<p>Cuerpo del Estudio.-<\/p>\n<p>En esta pericopia tenemos ante nosotros una especia de s&#237;ntesis perfecta de las caracter&#237;sticas de una verdadera iglesia. En cuanto que iglesia es igual a comunidad y sabiendo que una comunidad esta compuesta por una serie de individuos unidos por unos determinados intereses que les son comunes, hay que determinar cuales son los intereses que une a la comunidad cristiana. Pablo cita dos, los m&#225;s importantes, los b&#225;sicos y, adem&#225;s, imprescindibles, que son: &#8220;la fe en el Se&#241;or Jes&#250;s, y el amor para con todos los hermanos. (v. 15).<\/p>\n<p>Ahora bien, no todos los creyentes tienen la misma manera de entender las ense&#241;anzas b&#237;blicas y eso puede conllevar diversidad en la interpretaci&#243;n de las Escrituras. Hoy en d&#237;a los hay que se manifiestan &#8220;fundamentalistas&#8221;, otros han sido titulados como &#8220;modernistas&#8221; o tambi&#233;n &#8220;liberales&#8221;. Los primeros sostienen que la Biblia &#8220;es&#8221; Palabra de Dios y que hay que interpretarla literalmente. Los otros afirman que la Biblia &#8220;contiene&#8221; la palabra de Dios y que hay que extraer de la misma el mensaje de Dios de en medio de un lenguaje que, en muchas ocasiones, es arcaico o que responde a situaciones distintas de las de los interpretes actuales. Tambi&#233;n los hay que ni siquiera se han planteado este tipo de disquisiciones y que las encuentran fuera de lugar, a&#241;adiendo que solo provocan discusiones que no llevan a ninguna parte como no sea a divisiones.<\/p>\n<p>Este panorama en medio de iglesias que, inicialmente, fueron formadas por jud&#237;os y gentiles con culturas absolutamente distintas, ser&#237;a mucho m&#225;s conflictivo de lo que podamos pensar y por ello es que no tardaron en aparecer movimientos como los de los judaizantes, que m&#225;s tarde desembocar&#237;an en el arrianismo y que pon&#237;an en cuarentena la trinidad de Dios en cuanto entend&#237;an que<\/p>\n<p>atacaba al concepto del Dios &#218;nico. Estas son reminiscencias de la cultura sem&#237;tica, la cual, posteriormente, dio salida y abon&#243; al mahometismo. En el otro extremo encontramos al gnosticismo enmarcado en la cultura griega y que negaba la humanidad de Cristo, puesto que hab&#237;an sido educados en una filosof&#237;a que Afirmaba que &#8220;la carne&#8221; es mala y, consecuentemente, Cristo no pod&#237;a encarnarse en algo malo. La muerte y la resurrecci&#243;n de Cristo no fue real y si una especie de representaci&#243;n teatral.<\/p>\n<p>Pablo combate ambas cosas, pero para que cualquier forma de combate tenga &#233;xito afirma que es necesario el amor para con todos los creyentes.<\/p>\n<p>Cuando en el seno de una comunidad de establece un tribunal con la potestad para certificar cual es la verdadera doctrina y permiti&#233;ndose acusar a unos u otros de herejes, puede ser que dicha comunidad tenga &#8220;fe&#8221;, pero no tiene amor. Seguro que ellos alegaran que tienen amor a la verdad, pero Pablo no dijo eso, lo que dijo es que el amor tiene que ser dirigido a los hermanos.<\/p>\n<p>Eso no impide en nada el argumentar respecto a la ense&#241;anza apost&#243;lica a fin de ver por su medio cual sea la verdadera doctrina. Cualquier cosa distinta a los que ense&#241;an las Escrituras es anatema (Gal 1:7-8) pero no ha de ser la comunidad quien pronuncie el anatema, sino la Palabra de Dios. (Heb. 4:2, 12 y 13) Esta es la raz&#243;n que hace que Pablo exclame en esta oraci&#243;n: &#8220;&#8230;que el Dios de Nuestro Se&#241;or Jesucristo, el Padre de gloria, os d&#233; esp&#237;ritu de sabidur&#237;a y de revelaci&#243;n en el conocimiento de &#233;l&#8221;. Posiblemente esta pensando en lo escrito en Eclesi&#225;stico, o Sir&#225;cida 15:1-10 (que todo y ser un libro fuera del canon de las Escrituras ser&#237;a harto conocido por quien hab&#237;a estudiado el rabinato a los pies de Gamaliel Hech. 22:3)<\/p>\n<p>As&#237;, pues, el conocimiento de Dios no depende de la mente humana por muy especulativa que esta sea. Este conocimiento solo se hace posible mediante la Revelaci&#243;n del mismo Dios y eso, precisamente, es lo Pablo pide en su oraci&#243;n: un pleno conocimiento de Dios por parte de los creyentes de Efeso y fundamentado en la Revelaci&#243;n De no ser as&#237; y cuando es fruto de la mentada especulaci&#243;n del saber humano ocurre aquello que afirman los estudiantes de la psicolog&#237;a de la religiosidad. Aquella m&#225;xima que dice: &#8220;El hombre asimila el car&#225;cter del objeto que adora&#8221;. Eso pasa en todos aquellos que ha imaginado a la divinidad conforme a sus especulaciones y, por ello, se han convertido en &#8220;creadores&#8221; de dioses. Dioses hechos a la imagen de sus creadores los cuales tienen los defectos de dichos creadores y cuyo resultado no es solo la superstici&#243;n, sino la sublimaci&#243;n de los propios vicios. Un ejemplo de lo que estamos diciendo bien pudiera ser las practicas de los llamados &#8220;cultos dionis&#237;acos&#8221;, (tan aberrantes que en la Roma Imperial, a pesar de su ancha manga respecto a la moral, fueron prohibidos) o la prostituci&#243;n como culto a una divinidad, o los cultos a la fertilidad, que no est&#225;n lejos de nosotros puesto que se puede observar que en la mayor&#237;a de las monta&#241;as llamadas &#8220;santas&#8221; y con alg&#250;n santuario o capilla donde se veneran v&#237;rgenes o santos acostumbra a haber alg&#250;n pe&#241;asco con una forma f&#225;lica. (Un ejemplo de ello lo tenemos en la de Montserrat, en Catalu&#241;a, en cuyo centro hay uno de los mencionados s&#237;mbolos f&#225;licos, que es conocido con el nombre de &#8220;Cavall Bernat&#8221;. Dicho nombre es una deformaci&#243;n del aut&#233;ntico que era &#8220;Carai&#8221; cuyo significado es el mismo que el del &#8220;carayo&#8221; gallego. La monta&#241;a era ya sagrada mucho antes del cristianismo y con &#233;ste paganizado se contin&#250;a adorando el s&#237;mbolo de la fertilidad y la diosa que tambi&#233;n simboliza la misma cosa. Los ateos tienen raz&#243;n cuando dicen que el hombre ha creado a sus dioses a la propia imagen. Pero no al Dios &#218;nico y Verdadero que no solo cre&#243; al hombre sino que tambi&#233;n se ha Revelado a fin que el hombre le conociera. Conoci&#233;ndole se abandonan todos aquellos que son de creaci&#243;n propia.<\/p>\n<p>La iluminaci&#243;n interior, que Pablo cita en el v. 18, es una respuesta a la pregunta que muchos seres humano se han hecho en la busca del sentido de la vida: &#8220;&#191;Y despu&#233;s, que? &#191;Qu&#233; sentido tiene todo eso?&#8221; Los moralistas que prescinden de Dios aseguran que la tiene en la medida de nuestras aportaciones a la humanidad sean grandes o peque&#241;as. Si bien esa es una buena respuesta, no responde a la angustia frente a la nada que pregonan porque, &#191;y la propia vida sin esperanza en el m&#225;s all&#225; de este mundo, que sentido tiene? &#191;Nos podemos conformar que en todos los epitafios de los sepulcros humanos se lea: Nac&#237; un d&#237;a cualquiera a la vida, he tenido momentos de gozo y de tristeza, de deseos y desenga&#241;os, esperanzas y frustraciones, juventud y ancianidad, y de que me ha servido todo eso? &#191;Para acabar en este lugar? En cierta ocasi&#243;n me contaron que en un sepulcro hab&#237;a una inscripci&#243;n o epitafio en letra tan peque&#241;a que era obligado acercarse a fin de saber que dec&#237;a. Quien se acercaba lo suficiente, le&#237;a: &#8220;&#191;Qu&#233; miras? Piensa que yo antes era como t&#250;, pero despu&#233;s t&#250; ser&#225;s como yo&#8221;. Me pregunto si aquel que mand&#243; colocar semejante inscripci&#243;n s&#243;lo fue por un curioso, y macabro, sentido del humor.<\/p>\n<p>Sin duda esta es la experiencia humana que menciona Pablo y contra toda desesperanza escribe lo que encontramos en los ver. 19 y 20 &#8220;&#8230;La operaci&#243;n del poder de su fuerza, la cual oper&#243; en Cristo, resucit&#225;ndole de los muertos&#8230;&#8221; La misma fuerza es la que nos resucitar&#225; a nosotros. Cristo esta sentado a la derecha de Dios. Y en aquel lugar es donde se manifiesta su poder, un poder que esta por encima de cualquier otro poder ya sea principados, autoridades, dominios, de este o de fuera de nuestro mundo. Y lo remata diciendo que no solo del mundo actual, sino tambi&#233;n el del futuro.<\/p>\n<p>Observemos atentamente lo que sigue, puesto que es altamente sugestivo: &#8220;y someti&#243; todas las cosas bajo sus pies, y lo dio por cabeza sobre todas las cosas a la iglesia, la cual es su cuerpo, la plenitud de Aquel que todo lo llena en todo&#8221;. As&#237;, Aquel que tiene todo el poder es la cabeza de la iglesia, y entonces la iglesia tambi&#233;n tendr&#225; todo el poder toda vez que la cabeza es quien gobierna la totalidad del cuerpo. Pero la relaci&#243;n de la iglesia con su cabeza tiene una clara diferenciaci&#243;n respecto al cuerpo humano, en el que la mayor&#237;a de sus funciones vitales son autom&#225;ticas, es decir, no hay una intervenci&#243;n de la consciencia individual en las mismas. La respiraci&#243;n o la mayor&#237;a de los reflejos autom&#225;ticos como mecanismos defensivos de la seguridad f&#237;sica, adem&#225;s del funcionamiento de las v&#237;sceras: coraz&#243;n, est&#243;mago, h&#237;gado, ri&#241;ones, etc. No dependen &#8211;repito- de la consciencia individual y mal nos ir&#237;a de ser as&#237; porque adem&#225;s de no tener tiempo para otras cosas, tampoco podr&#237;amos abastar las citadas. En cambio el &#8220;cuerpo de Cristo&#8221; est&#225; formado por individualidades totalmente libres y dicha libertad jam&#225;s ser&#225; limitada por la cabeza del Cuerpo, por lo cual es necesario asumir libremente lo que la Cabeza quiere de este cuerpo. Ve&#225;moslo:<\/p>\n<p>En el aspecto positivo<\/p>\n<p>-La fidelidad a la fe que hemos recibido de &#233;l<\/p>\n<p>-Procurar el desarrollo espiritual mediante aquello que nos ha sido dado por la Revelaci&#243;n y asistencia del<\/p>\n<p>Esp&#237;ritu Santo<\/p>\n<p>-El Amor, que es el motor que nos hace avanzar en el aut&#233;ntico sentido de la hermandad que conforma el<\/p>\n<p>Cuerpo de Cristo.<\/p>\n<p>Lo que, como negativo, no hemos de aceptar o practicar<\/p>\n<p>-Ning&#250;n otro tipo de poder en la iglesia. Nadie puede ostentar alg&#250;n tipo de Jerarqu&#237;a en el Cuerpo de Cristo.<\/p>\n<p>-Ninguna otra autoridad doctrinal que la Revelada por las Sagradas Escrituras.<\/p>\n<p>Es evidente que existen muchas m&#225;s, pero si las estudiamos nos damos cuenta que todas ellas derivan de las citadas. <\/p>\n<p>Estudio VII.-<\/p>\n<p>SALVADOS POR LA GRACIA DE DIOS<\/p>\n<p>Texto B&#225;sico. Ef. 2:1-10.-<\/p>\n<p>Introducci&#243;n.-<\/p>\n<p>Los muertos por causa del pecado han sido vivificados y trasladados con Cristo a los cielos.<\/p>\n<p>La petici&#243;n del Ap&#243;stol para que Dios conceda a los creyentes el conocimiento de la esperanza que ha sido puesta a su alcance mediante la vocaci&#243;n, ya no sigue, puesto que Pablo, despu&#233;s de su descripci&#243;n de la acci&#243;n de Dios mediante Jesucristo, que es quien da la mentada esperanza, pas&#243; de la intercesi&#243;n a una forma de alabanza por aquella acci&#243;n divina. Ahora sigue, en cierta manera, exponiendo la grandeza de esta obra de Dios. Pero parece ser que lo hace con un fuerte sentido de sensatez, presentando sus efectos a los gentiles comparando lo que eran anteriormente y lo que han llegado a ser ahora; pero, tambi&#233;n &#8211;en el verso 3- se contempla la situaci&#243;n de los cristianos procedentes del juda&#237;smo y, con los cuales, Pablo se siente de nuevo solidario.<\/p>\n<p>En los versos 3 y 4 retoma el hilo de su pensamiento expuesto en 1 y 2 que hab&#237;a interrumpido para desarrollarlo totalmente en dos fases (VV. 4-7 y VV. 8-10) donde presenta una ant&#237;tesis entre el anterior comportamiento y el actual como cristianos, remarcando que dicho cambio ha sido realizado por la acci&#243;n divina.<\/p>\n<p>Cuerpo del Estudio.-<\/p>\n<p>Observemos lo que nos dice en el verso 1: en este &#8220;vosotros&#8221;, se nos muestra que no solo los cristianos procedentes del juda&#237;smo sino toda la humanidad estaba muerta por causa del pecado. Pablo usa aqu&#237; u vocablo griego fuertemente expresivo y conocido por todos nosotros: nekros (nekros) y que tiene el significado de quien est&#225; a merced de la muerte en plena corrupci&#243;n y descomposici&#243;n. Dicho t&#233;rmino aparece en otros pasajes de Pablo: (Col. 2:13; Rom. 6:11-13)<\/p>\n<p>Curiosamente quien nos dio una descripci&#243;n de dicha corrupci&#243;n fue Oscar Wilder en su libro De Profundis, y con estas palabras: &#8220;Los dioses me lo han dado casi todo. Pero me deje seducir por una serie de absurdos y largos embrujos de gustos sensuales&#8230; Cansado de estar en las alturas decid&#237; bajar deliberadamente a las profundidades a la b&#250;squeda de nuevas sensaciones. Aquello que para m&#237; era parad&#243;jico en la esfera del pensamiento, lleg&#243; a ser la perversidad en la esfera de la pasi&#243;n. Dej&#233; de preocuparme por las vidas ajenas a m&#237;. Tomaba el placer donde quer&#237;a siguiendo mi viaje. Olvid&#233; que cada peque&#241;a acci&#243;n ordinaria del d&#237;a forma o deforma el car&#225;cter y, por lo tanto, aquello que se realiza en una escondida habitaci&#243;n llega el d&#237;a en que se proclama en alta voz desde los tejados. Dej&#233; de ser el due&#241;o de m&#237; mismo. Ya no era el capit&#225;n de mi alma, pero lo ignoraba. Me domin&#243; el placer que, finalmente, lleg&#243; a ser una horrible desgracia.<\/p>\n<p>Esta situaci&#243;n, que es com&#250;n a toda la humanidad, es la que describe Pablo como Nekros, toda vez que este mundo, desde la perspectiva de Dios, se ha convertido en una Nekropolis (Nekropolis) en donde reina el pecado (Rom. 5:12 y 21; 1.Cor. 15:56) Adem&#225;s, la forma como Pablo lo escribi&#243; en el original griego tiene una extraordinaria forma expresiva. La frase: &#8220;anduvisteis en otro tiempo, siguiendo la corriente de este mundo&#8230;&#8221; Aqu&#237;, para &#8220;mundo&#8221; dice:<\/p>\n<p>o kosmos (o kosmos) que viene a significar el mundo en el aspecto de la totalidad del espacio en el que transcurre nuestra existencia. En otros pasajes para definir lo mismo usa el vocablo &#8220;o aiw n&#8221; (o aion) que define la totalidad del tiempo o duraci&#243;n del universo. El tiempo del &#8220;cosmos&#8221;. Pero hay m&#225;s, y en este m&#225;s, se nos muestra la profundidad del pensamiento de Pablo, puesto que &#8220;cosmos&#8221; es lo contrario de &#8220;caos&#8221; (Gen. 1:2) El pecado consigui&#243; convertir al cosmos nuevamente en caos. Todo el mundo, todo el universo, toda la creaci&#243;n de Dios, el hombre la convirti&#243; en un caos y en el caos no es posible la vida. He aqu&#237; el porque nuestro e&#243;n, nuestro tiempo, est&#225; dominado por el nekros, es decir, la corrupci&#243;n. Cuantas veces no hemos o&#237;do exclamar: &#8220;Este mundo es un caos&#8221;. Cierto, porque en el mismo predominan la corrupci&#243;n pol&#237;tica, moral, social, religiosa&#8230; hasta el extremo de que nada escapa a dicha corrupci&#243;n. Si esta es una situaci&#243;n general, significa que nosotros tambi&#233;n estamos sumergidos en este ca&#243;tico mundo y por ello es que Pablo sigue diciendo: &#8220;&#8230;estando nosotros muertos en pecados, nos dio vida juntamente con Cristo (por gracia sois salvos), y, juntamente con &#233;l nos resucit&#243;, y asimismo, nos hizo sentar en los lugares celestiales con Cristo Jes&#250;s&#8221;.<\/p>\n<p>Observemos la solidez de sus afirmaciones.<\/p>\n<p>A.- A causa del pecado, el hombre, creaci&#243;n de Dios, pas&#243; del cosmos al caos.<\/p>\n<p>B.- Por esta causa qued&#243; inmerso en la muerte y la corrupci&#243;n.<\/p>\n<p>C.- Un cuerpo muerto y en estado de corrupci&#243;n no tiene la m&#237;nima posibilidad de hacer nada para cambiar su destino toda vez que la muerte lo ha hecho definitivo.<\/p>\n<p>D.- Pero frente a esta definitiva situaci&#243;n Pablo anuncia que, cuando est&#225;bamos muertos Dios nos dio vida con Cristo. Es decir, el mismo poder que resucit&#243; a Cristo nos resucit&#243; a nosotros.<\/p>\n<p>E.- Y acaba diciendo que nos ha hecho tomar asiento arriba en los cielos, con lo cual est&#225; diciendo que de nuevo el caos ha sido reconvertido en cosmos (Rom. 19:23)<\/p>\n<p>Pero aun hay otro detalle, a mi parecer, maravilloso, y es que Pablo dice todo eso en un absoluto presente. No dice que fue o que ser&#225;, sino que es, que se realiza en todo aquel que acepta este don de Dios.<\/p>\n<p>Con todo lo comentado hasta aqu&#237; nos da la sensaci&#243;n que Pablo ha estado preparando las mentes de sus lectores para el punto final (VV. 8 y 9).<\/p>\n<p>Por gracia, significa un don gratuito, un regalo, y quien hace un regalo no tiene en cuenta los m&#233;ritos de quien lo recibe puesto que entonces ser&#237;a una recompensa. Tampoco se hacen regalos a quien nos es indiferente sino a quien se ama. As&#237;, lo que motiv&#243; el regalo no fue otra cosa que el amor de Dios. (Lo he puesto en cursiva a fin que captemos el sentido del no otra cosa)<\/p>\n<p>Todo cristiano, como bien dice en v. 9, no puede presumir de sus obras, obras que abarcan desde el cumplir de la ley hasta cualquier otro m&#233;rito que pretendamos esgrimir. De lo que s&#237; podemos presumir es del regalo. Es aquello que hace quien ha recibido un espl&#233;ndido y valioso regalo, que, lleno de gozo, exclama: &#161;&#161;&#161;Mira lo que me han regalado!!! Precisamente esta es la mejor manera de testificar. Hacer saber a todos cuantos nos rodean lo que Dios nos ha regalado.<\/p>\n<p>Conclusi&#243;n.-<\/p>\n<p>Como conclusi&#243;n consideremos lo que se nos dice en el v. 10. Aqu&#237; cabe preguntar: &#191;Cu&#225;les son las buenas obras que Dios prepar&#243; para que anduvi&#233;semos en ellas? Sin duda se lo podemos preguntar a te&#243;logos, ex&#233;getas, estudiosos de las Escrituras, etc. etc. Pero, &#191;por qu&#233; no preguntarlo a Cristo directamente? Si vamos al evangelio de Juan (6:28-29) &#8220;&#8230;&#191;Qu&#233; debemos hacer para poner en pr&#225;ctica las obras de Dios? Respondi&#243; Jes&#250;s y les dijo: esta es la obra de Dios, que cre&#225;is en el que &#233;l ha enviado&#8221;<\/p>\n<p>&#191;Entonces, creer, es una obra meritoria? En absoluto, no es por ah&#237;, porqu&#233; la obra es creer en Aquel que Dios envi&#243;, es decir, Jesucristo. Luego, creer en &#233;l es tambi&#233;n creer en su obra. Y si creemos en su obra es porque hemos dejado de creer en las nuestras. A partir del regalo de Dios, que es Jesucristo, nuestra obra es testificar de la obra de Cristo. Esta es la principal labor de todo cristiano. Consecuentemente, si el motivo del obrar de Dios en Cristo fue el amor, el cristiano tiene que andar en amor, un amor que debe estar por encima de nuestras propias mezquindades y de las de nuestro pr&#243;jimo.<\/p>\n<p>De esta manera tambi&#233;n nosotros colaboramos en la tarea de convertir el &#8220;caos&#8221; de nuestro mundo en &#8220;cosmos&#8221;. Volvamos a Gen. 1:2-3. Como vemos el caos es tipificado por las tinieblas y la luz creada por Dios elimina las tinieblas y, consecuentemente, el caos.<\/p>\n<p>Una pregunta, sin respuesta, que se hace el famoso cient&#237;fico Stephen Hawking en su obra &#8220;Historia del Tiempo&#8221; donde dice: &#8220;Es dif&#237;cil entender c&#243;mo tales condiciones ca&#243;ticas iniciales podr&#237;an haber dado lugar a un universo que es tan uniforme y regular a gran escala, como lo es actualmente el nuestro &#8230;&#191;podr&#237;a ocurrir que nosotros estuvi&#233;semos viviendo en una regi&#243;n que simplemente, por casualidad, es suave e uniforme? A primera vista esto podr&#237;a parecer muy improbable, porque tales regiones suaves ser&#237;an superadas en gran n&#250;mero por la regiones ca&#243;ticas e irregulares&#8221;<\/p>\n<p>He aqu&#237; la pregunta sin respuesta, y no porque no la haya, sino porque la desconoce. Y la desconoce porque la ciencia humana no puede responderla, en cambio, Dios si puede y lo hace. Adem&#225;s, el &#250;ltimo p&#225;rrafo citado manifiesta una realidad que, si no en cuanto al mundo f&#237;sico en nuestro Universo al que llama suave e uniforme, si que ocurre en el aspecto espiritual, porque el caos, como hemos considerado, nos envuelve por todas partes, pero hay un peque&#241;o n&#250;cleo que no est&#225; dominado por dicho caos. Estos no dominados lo son en esperanza. Ahora bien, una esperanza que, en palabras de Pablo, se ha convertido en presente mediante el maravilloso don de Dios que es la fe.<\/p>\n<p>Estudio VIII<\/p>\n<p>RECONCILIACI&#211;N PARA LOS GENTILES<\/p><\/div>\n<div style=\"text-align:justify; color:#3d3d3d;\">Texto B&#225;sico. Ef. 2:11-22.-<\/p>\n<p>Introducci&#243;n.-<\/p>\n<p>Parece ser que bastar&#237;a con lo que el Ap&#243;stol ha expuesto en 2:1-10 con respecto a la maravillosa acci&#243;n de Dios entre los gentiles, porque, &#191;hay algo mayor que haber sido resucitados de entre los muertos y tambi&#233;n de un e&#243;n dominado por la &#8220;nekros&#8221;? Evidentemente no lo hay, y no obstante para Pablo la cuesti&#243;n tiene tambi&#233;n otra faceta que, contempl&#225;ndola, nos muestra lo que sucedido con los cristianos procedentes de la gentilidad y no solo desde el aspecto moral, sino tambi&#233;n el hist&#243;rico. Ellos, los que antes no eran &#8220;pueblo&#8221;, ahora y junto a los jud&#237;os, forman el nuevo pueblo de Dios. Esta es la idea que Pablo desarrolla en los versos del 11 al 22.<\/p>\n<p>Cuerpo del Estudio.-<\/p>\n<p>En primer lugar exhorta a los creyentes gentiles a reflexionar de cual era su situaci&#243;n anterior respecto a Israel.<\/p>\n<p>A fin de mostrar semejante cosa, Pablo rememora todo el plan de la salvaci&#243;n preparado y ejecutado por Dios, el cual se inici&#243; con Abraham. Con el mentado Patriarca Dios inici&#243; la construcci&#243;n de un pueblo que le fuese testigo ante toda la humanidad. La promesa que le hizo a Abraham en Gen. 12:2-3 no deja lugar a dudas. &#8220;Y har&#233; de ti una naci&#243;n grande, y te bendecir&#233;, y engrandecer&#233; tu nombre, y ser&#225;s bendici&#243;n. Bendecir&#233; a los que te bendijeren, y a los que te maldijeren maldecir&#233;; y ser&#225;n benditas en ti todas las familias de la tierra&#8221;. La se&#241;al externa de aquella alianza fue la circuncisi&#243;n (Gen. 17:9-12) tal como Pablo cita en el verso 11. A partir de aqu&#237; hace una enumeraci&#243;n de todo aquello que faltaba a los gentiles con relaci&#243;n a Dios.<\/p>\n<p>A.- Sin Cristo<\/p>\n<p>B.- Excluidos de la ciudadan&#237;a de Israel<\/p>\n<p>C.- Al margen de las alianzas y promesas de Dios.<\/p>\n<p>D.- Sin esperanza.<\/p>\n<p>E.- Sin Dios en medio del Cosmos.<\/p>\n<p>Claramente se ve que, quien predomina en todo eso es Cristo, toda vez que ser privados de Cristo significa serlo tambi&#233;n del resto de lo enumerado. Adem&#225;s, tambi&#233;n muestra que la promesa dada a Abraham de que en &#233;l, ser&#237;an benditas todas las familias de la tierra, es una inequ&#237;voca referencia a Cristo, es decir, la promesa es precisamente Cristo.<\/p>\n<p>Consecuentemente la condici&#243;n, condici&#243;n ineludible, para ser incluidos en la ciudadan&#237;a de Israel es la de estar en Cristo. Mediante dicha condici&#243;n se muestra tambi&#233;n que no se trata de una cuesti&#243;n racial (descendencia carnal de Abraham) sino de una descendencia espiritual por lo que s&#243;lo aquellos que est&#225;n unidos a Cristo lo est&#225;n tambi&#233;n con Abraham.<\/p>\n<p>Sin esa uni&#243;n no hay la menor esperanza. Jud&#237;os y gentiles est&#225;n en la misma situaci&#243;n. Los primeros cre&#237;an tener todas las garant&#237;as a causa de la promesa, pero lo tr&#225;gico fue que no aceptaron su cumplimiento y por ello eran sin esperanza. Los segundos, en cuanto desconoc&#237;an al Dios de la Creaci&#243;n y Se&#241;or del Universo, se somet&#237;an a los grandes fen&#243;menos de dicha Creaci&#243;n a los que divinizaban. Por esta causa a pesar de la gran cantidad de dioses a los que adoraban, estaban &#8220;sin Dios&#8221; (Rom. 1:25 y 1&#170;.Tes. 5:5) Si estaban sin Dios tambi&#233;n estaban lejos de sus promesas, pero Pablo recuerda que el mismo Dios hab&#237;a hecho una especial promesa para aquellos que estaban lejos (Is. 57:19; Hech. 2:39) y por ello afirma que el cumplimiento de la tal promesa se realiz&#243; mediante la sangre de Cristo. Ahora, pues, el estar cerca, significa un nuevo &#8220;orden social&#8221; entre jud&#237;os y gentiles y cabe remarcar que en Is. 57:19 cita primero a los que est&#225;n &#8220;lejos&#8221; qu&#233;, a los que est&#233;s &#8220;cerca&#8221;. Eso no significa una preeminencia respecto de los gentiles sino mostrar que, en realidad, todos estaban lejos.<\/p>\n<p>La afirmaci&#243;n de que &#8220;Cristo es nuestra paz&#8221; se fundamenta en lo que Isa&#237;as dice en 9:5-6. Entre jud&#237;os y gentiles hab&#237;a un muero de separaci&#243;n. No hay que olvidar que la palabra &#8220;gentil&#8221; significa &#8220;la otra gente&#8221;, es decir, los que no eran &#8220;pueblo&#8221;. Esta separaci&#243;n era tan radical que un jud&#237;o ni tan solo pod&#237;a entrar en el hogar de un gentil y menos a&#250;n comer en la misma mesa (Hech. 10:28) Adem&#225;s, Pablo puede estar pensando en el &#8220;muro&#8221; de separaci&#243;n existente en el Templo de Jerusal&#233;n donde una enrejado cerraba los atrios interiores de dicho Templo. En el mismo y a intervalos regulares hab&#237;a unos r&#243;tulos que advert&#237;an en griego y lat&#237;n que a los gentiles les estaba prohibido, bajo pena de muerte, traspasar el peribolos (peribolos) que era la periferia de los lugares reservados para aquellos que eran pueblo de Dios, y que conduc&#237;a directamente al lugar Sant&#237;simo, es decir, a la presencia de Dios. Pues bien, eso es lo que ha estado abolido en la persona de Cristo, que, cuando en la cruz exclam&#243; &#8220;consumado es&#8221; el velo del templo, aquel velo que separaba el lugar santo del sant&#237;simo se desgarr&#243; parti&#233;ndose por la mitad (Mat. 27:50-51) A partir de entonces el lugar sant&#237;simo, donde solo el Sumo Sacerdote y una sola vez al a&#241;o le era permitido entrar y para realizar la expiaci&#243;n de los pecados y con ello la renovaci&#243;n del pacto entre Dios y el pueblo de Israel, quedaba abierto de par en par y solo para los que estaban aparentemente cerca -los jud&#237;os- sino tambi&#233;n para los que estaban lejos -los gentiles-. De esta manera de dos pueblos se hace uno solo. Pablo lo refuerza en el ver. 16 donde nos dice que, mediante la cruz reconcili&#243; con Dios a ambos en un solo pueblo. Pero, tambi&#233;n hay que tener presente que con estas palabras Pablo va m&#225;s all&#225; de la paz entre dos pueblos que ten&#237;an dos distintas concepciones de la religiosidad al hablar de los que estaban cerca y los que estaban lejos. Los que estaban lejos ni tan solo ten&#237;an entrada en los atrios del Templo, pero los que estaban cerca tampoco pod&#237;an entrar a la presencia de Dios pues, como hemos dicho anteriormente, s&#243;lo el Sumo Sacerdote pod&#237;a entrar a la presencia de Dios. Ahora, pues, a unos y a otros les ha sido abierto aquel lugar cerrado d&#225;ndoles acceso al Padre por un mismo Esp&#237;ritu. (18)<\/p>\n<p>El prop&#243;sito de estas palabras de Pablo fue el mostrar a los creyentes gentiles que no ha de considerarse extranjeros o forasteros, sino conciudadanos de los santos en la familia de Dios (19). Consecuentemente los cristianos de la ciudad de Efeso deben olvidar las ense&#241;anzas de los llamados &#8220;judaizantes&#8221; que les dec&#237;an que para poder ser &#8220;pueblo&#8221; de Dios era imprescindible que se circuncidaran y que Pablo clarifica en Gal. 5:2. Su edificaci&#243;n como cristianos no depende de las antiguas pr&#225;cticas jud&#237;as sino en las de los Ap&#243;stoles y Profetas. (Aqu&#237; hay que tener en cuenta que los antiguos profetas de Israel &#8220;iban por libre&#8221;, es decir, ten&#237;an poco que ver con las pr&#225;cticas de los sacrificios sacerdotales que m&#225;s bien criticaban. (Sal. 51:17; Is. 1:11; Jer. 6:20) Ap&#243;stoles y profetas son el fundamento de la Piedra Angular que es Jesucristo, puesto que es en el Cristo donde reposa toda la construcci&#243;n y formaci&#243;n de un Templo Santo en el Se&#241;or. (20-21)<\/p>\n<p>En el &#250;ltimo verso hay una afirmaci&#243;n que es necesario considerar puesto que es altamente interesante (22). Como vemos hay dos enunciados:<\/p>\n<p>A.- Vosotros hab&#233;is sido edificados. (Es decir, integrados)<\/p>\n<p>B.- Para morada de Dios en el Esp&#237;ritu.<\/p>\n<p>Edificados e integrados, es aquel caso, a la<\/p>\n<p>Iglesia de Efeso pero, trascendiendo tiempo<\/p>\n<p>Tiempo y distancia, cada uno de aquellos<\/p>\n<p>Que aceptan a Cristo como su Salvador,<\/p>\n<p>Se integra en una iglesia y cada una de las<\/p>\n<p>Iglesias locales trabaja con el prop&#243;sito de<\/p>\n<p>Ayudar a Cristo en la edificaci&#243;n de la<\/p>\n<p>Iglesia Universal cuya edificaci&#243;n culminar&#225;<\/p>\n<p>Al final de los tiempos en la venida de Cristo.<\/p>\n<p>Este edificio es la &#8220;mansi&#243;n de Dios&#8221;.<\/p>\n<p>Una mansi&#243;n tiene significado de lugar<\/p>\n<p>&#205;ntimo que acostumbra a ser propio de<\/p>\n<p>una familia. Con esto se hace comprensible<\/p>\n<p>la paternidad de Dios. Reitero que eso ocurrir&#225;<\/p>\n<p>al final de los tiempos y entonces la Iglesia ser&#225;<\/p>\n<p>&#8220;cat&#243;lica&#8221; en su sentido de universalidad. Mientras,<\/p>\n<p>ahora, cada creyente es lar de Dios mediante<\/p>\n<p>el Esp&#237;ritu Santo (1&#170;. Cor 3:16-17)<\/p>\n<p>&#191;Tenemos plena conciencia de ser Santuario del<\/p>\n<p>Esp&#237;ritu? &#191;Somos plenamente consecuentes con<\/p>\n<p>Ello?<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Introducci&#243;n a la Ep&#237;stola Texto B&#225;sico. Efe. 1:1-2 A fin de iniciar este estudio con provecho, es conveniente tener una visi&#243;n preliminar respecto de la tem&#225;tica que nos presenta Pablo en esta carta, toda vez que, de esta forma conseguiremos una aproximaci&#243;n a la totalidad de las ideas que se desarrollan en la ep&#237;stola. A &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/la-epstola-de-efesios\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLa Ep&#237;stola de Efesios\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5652","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/5652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=5652"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/5652\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=5652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=5652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=5652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}