{"id":5668,"date":"2016-02-08T19:11:40","date_gmt":"2016-02-09T00:11:40","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/el-amor-al-dinero\/"},"modified":"2016-02-08T19:11:40","modified_gmt":"2016-02-09T00:11:40","slug":"el-amor-al-dinero","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/el-amor-al-dinero\/","title":{"rendered":"El amor al dinero"},"content":{"rendered":"<div>En 1 Timoteo Cap&#237;tulo seis, en los vers&#237;culos 6-10 la Biblia dice:<\/p>\n<p>\u00abSin embargo, grande ganancia es la piedad con contentamiento.<\/p>\n<p>Porque nada trajimos a este mundo, y es evidente que nada podremos sacar.<\/p><\/div>\n<div style=\"text-align:justify; color:#3d3d3d;\">As&#237; que, teniendo el sustento y con qu&#233; cubrirnos, estaremos contentos con esto.<\/p>\n<p>Porque los que desean enriquecerse caen en tentaci&#243;n y trampa, y en muchas pasiones insensatas y da&#241;inas que hunden a los hombres en ruina y perdici&#243;n.<\/p>\n<p>Porque el amor al dinero es ra&#237;z de todos los males; el cual codiciando algunos, fueron descarriados de la fe y se traspasaron a s&#237; mismos con muchos dolores.\u00bb<\/p>\n<p>Note que la Biblia dice que el amor al dinero es la ra&#237;z de todos los males.<\/p>\n<p>\u00abPorque el amor al dinero es ra&#237;z de todos los males; el cual codiciando algunos, fueron descarriados de la fe y se traspasaron a s&#237; mismos con muchos dolores.\u00bb<\/p>\n<p>Queda bastante claro que hay una diferencia entre una ra&#237;z que lleva a diferentes tipos de males y la ra&#237;z que lleva a todos los males. Estando saturado con la versi&#243;n King James de las Sagradas Escrituras, me sorprendi&#243; cuando vi una lectura diferente en la Nueva King James. Verificando a trav&#233;s de otras traducciones, hall&#233; que estaba de acuerdo con la Nueva King James. Esta peque&#241;a diferencia ha cambiado mi comprensi&#243;n de este pasaje de Sagrada Escritura. Cuando algunas personas dicen que no hay ninguna diferencia en doctrina de una traducci&#243;n a otra, no est&#225;n siendo honrados o no est&#225;n comparando seriamente.<\/p>\n<p>Ahora parece obvio que el propio Rey James no se cuid&#243; tal c&#243;mo dice el pasaje le&#237;do. Su amor de dinero era insaciable. Amaba las fiestas extravagantes, disfrut&#243; dando pr&#243;digos regalos a sus \u00abfavoritos masculinos,\u00bb y como resultado, constantemente estaba endeudado. Utiliz&#243; muchos planes para recaudar dinero; vendiendo toda clase de t&#237;tulos y hasta intent&#243; casar a su hijo con una princesa espa&#241;ola cat&#243;lica por su dote, que merec&#237;a la pena. Hizo a sus \u00abfavoritos masculinos\u00bb muy ricos. Los alberg&#243;, visti&#243;, aliment&#243; con art&#237;culos m&#225;s all&#225; de las limitaciones de la Sagrada Escritura que estamos tratando. El Rey James muri&#243; sin blanca y miserable. Parece que la &#250;ltima parte de los vers&#237;culos anteriores fue el destino del Rey James.<\/p>\n<p>Uno de los problemas que los traductores del Rey pueden haber tenido con este pasaje es la palabra griega &#8216;philarguria&#8217; que tradujeron por \u00abamor al dinero.\u00bb La Biblia del Companion declara en el margen que esta palabra en toda la Biblia s&#243;lo aparece aqu&#237;. Esto hace de la palabra un hapaxlegomenon, que es una traducci&#243;n de palabra griegas usadas en la Biblia que aparecen s&#243;lo una vez. Es dif&#237;cil darle un significado a una palabra si est&#225; s&#243;lo se usa una vez, sobre todo si no tenemos diccionarios de esa &#233;poca de la historia que nos d&#233; la definici&#243;n de esa palabra en ese momento en la historia del idioma griego. Los traductores del Rey se enfrentaron con muchos hapaxlegomenon que quiz&#225;s les forz&#243; a contar con la Vulgata Latina y traducciones anteriores que pose&#237;an en lugar de los centenares de manuscritos, papiros, etc. que tienen acceso hoy en d&#237;a los estudiosos.<\/p>\n<p>Todos los idiomas cambian significados de palabras de una generaci&#243;n a otra. Nuestra generaci&#243;n ha cambiado el significado de muchas palabras. Los diccionarios futuros tendr&#225;n que cambiar sus definiciones para conformarse a nuestro uso de esas palabras. Muchas personas no se dan cuenta de que el prop&#243;sito de los diccionarios es dar el significado de las palabras como se usan en la actualidad. Cuando una sociedad ya no usa una palabra de una cierta manera, los diccionarios dejar&#225;n caer ese significado. En otras palabras, usar un diccionario de ingl&#233;s del siglo 20 para tratar de entender el pensamiento de la sociedad inglesa del siglo 16 lleva ciertamente a muchos errores.<\/p>\n<p>He dicho lo anterior que es un poco trivial, y es &#250;til saber estas cosas. El tema de este art&#237;culo es el amor de dinero, no la etimolog&#237;a, etc., miremos este asunto.<\/p>\n<p>Me siento como si supiera mucho acerca del amor al dinero. Tanto como un ni&#241;o peque&#241;o, le dije a mi madre que ser&#237;a millonario y que le comprar&#237;a una casa grande. En los a&#241;os anteriores de conocer a Cristo, gast&#233; mucho de mi energ&#237;a intentando llegar a ser millonario antes de los 30 a&#241;os. En un momento dado, estuve en posici&#243;n hacerlo, pero mi conciencia entr&#243; en el Camino. Despu&#233;s de convertirme en cristiano, me animaron m&#225;s para que llegase a ser millonario que cuando estaba en el mundo secular. Despu&#233;s de todo las iglesias en las que estaba siempre requer&#237;an dinero para nuevos edificios, un campanario nuevo, un edificio para la escuela dominical, una casa nueva para el pastor. Se me ofrecieron planes m&#225;s lucrativos despu&#233;s de volverme cristiano que antes de. Y sin embargo, &#233;ramos los hijos de Abraham. &#201;l era rico y as&#237; debemos ser nosotros. &#191;Y no se ponen las riquezas de los paganos para nosotros los cristianos? Cada vez estaba m&#225;s seguro de dar al menos el 10% de todos mis ingresos a mi iglesia (no directamente a los pobres) y estaba animado a participar en cualquier aventura para recolectar dinero tal como me lo demandaba mi peque&#241;o y viejo coraz&#243;n.<\/p>\n<p>Hoy, me entrego mucho a este mammon que se le rinde culto en el nombre de Jes&#250;s, pero no me entrego definitivamente por amor al dinero. &#191;Qu&#233; es realmente el \u00abamor al dinero?\u00bb &#191;Si es una ra&#237;z, c&#243;mo es de profunda? Permita que veamos cuan lejos podemos rastrear esta ra&#237;z. Quiz&#225;s si llegamos a ver el extremo de la ra&#237;z, podr&#237;amos empezar a pasar hambre.<\/p>\n<p>La ra&#237;z de una planta es la fuente de mucho de lo qu&#233; la planta necesita para vivir. Extrae minerales, agua etc. que le dan nutrici&#243;n a la planta. Una planta no tiene alternativa donde se planta. Debe extraer del ambiente en que est&#225; plantada. Un cristiano tiene opciones acerca del tipo de tierra de donde extraer. Mi experiencia como cristiano me ha mostrado que la ra&#237;z del amor al dinero est&#225; bien viva en casi todas las denominaciones de la Cristiandad. Incluso se predica como una cosa buena en Am&#233;rica. De nuevo, s&#243;lo si la iglesia consigue su \u00abjusta\u00bb porci&#243;n.<\/p>\n<p>La mayor&#237;a de nosotros, cuando pensamos en dinero, piensa en d&#243;lares en nuestra cartera, acciones en un fondo mutuo, o tesorer&#237;a cargada en nuestra cuenta, o un capital donde m&#225;s rente, a algo as&#237;. Pero &#233;se realmente no es el problema aqu&#237;. El dinero es s&#243;lo un medio de intercambio de g&#233;neros y servicios. M&#225;s b&#225;sico a&#250;n, es un medio de intercambio de trabajo. Intercambio mi habilidad de hacer zapatos por su habilidad de cuidar beb&#233;s. En lugar de intercambiar servicios, intercambiamos un Pagar&#233; o un E.O.M. (usted me debe) que podemos intercambiar con alguien por lo que nuestra sociedad piensa tiene el mismo valor. Abraham Lincoln lo dijo esta manera, \u00abEl Capital es s&#243;lo el fruto del trabajo, y nunca podr&#237;a existir si el trabajo no hubiese existido primero.\u00bb<\/p>\n<p>Ahora si una hora de mi trabajo es el valor justo de una hora de m&#225;s trabajo de alguien, significar&#237;a que ese alguien que tiene mucho dinero en el banco y no compr&#243; muchas cosas ahorrar&#237;a simplemente su trabajo. Pero &#233;se no es normalmente el caso. Las personas con mucho dinero en el banco usualmente gastan tambi&#233;n mucho dinero. &#191;C&#243;mo es esto posible? Pues, la vieja naturaleza de Jacob (agarrado al tal&#243;n) parece haber aparecido con un esquema donde la hora de trabajo de unas personas consigue mucho m&#225;s que la hora de trabajo de otros. A&#250;n peor, algunos de nosotros \u00abJacobs\u00bb hemos entrado en el negocio del dinero, gerentes del capital, una ganancia hay miles de personas sentadas detr&#225;s de un escritorio para ganar m&#225;s dinero.<\/p>\n<p>El ingrediente m&#225;s importante para hacer todo este trabajo es esa cosa m&#225;gica llamada \u00abinter&#233;s.\u00bb La Ley de Mois&#233;s llam&#243; a esta cosa \u00abusura\u00bb &#161;y &#233;l era m&#225;s grande que ninguno! Los \u00abJacobs\u00bb (intelectuales, profesionales) de este mundo han cambiado el medio de intercambio para poder robar algo del trabajo de los Esaus (obreros generales) de este mundo. De hecho, el esquema se ha hecho tan sofisticado, que los \u00abJacobs\u00bb de este mundo pueden pasar este material llamado dinero a sus hijos, y sus hijos pueden hacer que el dinero trabaje por ellos en lugar de tener que trabajar ellos. Ya no tienen que trabajar para ganar su pan diario. De hecho, pueden conseguir m&#225;s dinero de las gentes s&#243;lo por tener metido el dinero en el banco. En otras palabras, hay muchas personas hoy ganando dinero por tener dinero, no por trabajar y ganar su pan, vestido, etc. he estado estudiando un poco de econom&#237;a s&#243;lo para saber el sistema que usa todo el mundo para pagar un d&#237;a de trabajo, y que no tiene nada que ver con los justos planes puestos por Dios.<\/p>\n<p>Ahora aquellos de ustedes quienes juegan a \u00abJacob\u00bb en esta situaci&#243;n, por favor no se sientan condenados. Ha nacido en una econom&#237;a mundial que tiene ciertos principios y usted simplemente est&#225; haci&#233;ndolo lo mejor que puede. No estoy escribiendo esto para condenarlo. Usted puede querer preguntar al Padre que busque en su coraz&#243;n y vea si hay alguna manera mala en usted. Tambi&#233;n puede preguntarle si hay algo que pueda hacer para entrar m&#225;s en Su l&#237;nea en cuanto a la econom&#237;a. Las cosas no son justas en este mundo. Nosotros lo hacemos lo mejor que podemos.<\/p>\n<p>Aquellos de ustedes que se sienten estafados por los gerentes del dinero, profesionales, doctores, abogados, pol&#237;ticos, ministros, hombres de negocios etc. y desean su \u00abjusto\u00bb reparto, s&#243;lo recuerde esto, que no suceder&#225; hasta que Jes&#250;s instaure Su Reino. Esta estructura entera es demasiado grande para poder desmantelarla ninguno de nosotros. Debemos aprender a estar satisfechos dondequiera que nuestro Padre nos tenga. Aprender a estar satisfecho con lo poco y aprender c&#243;mo manejar lo mucho. Un d&#237;a los \u00abJacobs\u00bb (todos nosotros) rendiremos cuentas y probablemente nos quedaremos cortos. Uno no tiene que tener dinero para tener \u00abamor al dinero.\u00bb El pobre y el rico re&#250;nen los requisitos para esta enfermedad. Bastante de econom&#237;a. Perm&#237;tanos volver de nuevo al asunto y mir&#233;moslo desde un punto de vista m&#225;s profundo.<\/p>\n<p>19&#8243;No os hag&#225;is tesoros en la tierra, donde la polilla y el moho destruyen, y donde ladrones entran y hurtan; 20sino haceos tesoros en el cielo, donde ni la polilla ni el moho destruyen, y donde ladrones no entran ni hurtan, 21porque donde est&#233; vuestro tesoro, all&#237; estar&#225; tambi&#233;n vuestro coraz&#243;n.<\/p>\n<p>22&#187;La l&#225;mpara del cuerpo es el ojo; as&#237; que, si tu ojo es bueno, todo tu cuerpo estar&#225; lleno de luz; 23pero si tu ojo es maligno, todo tu cuerpo estar&#225; en tinieblas. As&#237; que, si la luz que hay en ti es tinieblas, &#191;cu&#225;ntas no ser&#225;n las mismas tinieblas?<\/p>\n<p>24&#187;Ninguno puede servir a dos se&#241;ores, porque odiar&#225; al uno y amar&#225; al otro, o estimar&#225; al uno y menospreciar&#225; al otro. No pod&#233;is servir a Dios y a las riquezas [mammon].<\/p>\n<p>25&#187;Por tanto os digo: No os angusti&#233;is por vuestra vida, qu&#233; hab&#233;is de comer o qu&#233; hab&#233;is de beber; ni por vuestro cuerpo, qu&#233; hab&#233;is de vestir. &#191;No es la vida m&#225;s que el alimento y el cuerpo m&#225;s que el vestido? 26Mirad las aves del cielo, que no siembran, ni siegan, ni recogen en graneros; y, sin embargo, vuestro Padre celestial las alimenta. &#191;No val&#233;is vosotros mucho m&#225;s que ellas? 27&#191;Y qui&#233;n de vosotros podr&#225;, por mucho que se angustie, a&#241;adir a su estatura un codo? 28Y por el vestido, &#191;por qu&#233; os angusti&#225;is? Considerad los lirios del campo, c&#243;mo crecen: no trabajan ni hilan; 29pero os digo que ni aun Salom&#243;n con toda su gloria se visti&#243; como uno de ellos. 30Y si a la hierba del campo, que hoy es y ma&#241;ana se quema en el horno, Dios la viste as&#237;, &#191;no har&#225; mucho m&#225;s por vosotros, hombres de poca fe? 31No os angusti&#233;is, pues, diciendo: \u00ab&#191;Qu&#233; comeremos, o qu&#233; beberemos, o qu&#233; vestiremos?\u00bb, 32porque los gentiles se angustian por todas estas cosas, pero vuestro Padre celestial sabe que ten&#233;is necesidad de todas ellas. 33Buscad primeramente el reino de Dios y su justicia, y todas estas cosas os ser&#225;n a&#241;adidas.<\/p>\n<p>34&#187;As&#237; que no os angusti&#233;is por el d&#237;a de ma&#241;ana, porque el d&#237;a de ma&#241;ana traer&#225; su propia preocupaci&#243;n. Basta a cada d&#237;a su propio mal.\u00bb (Mateo 6:19-34, lea el capitulo entero.) <\/p>\n<p>Aqu&#237; est&#225; donde yo tengo mi problema con el amor al dinero. &#191;Por qu&#233; quiero una gran cuenta en el banco? No tengo ning&#250;n deseo de usar el dinero para poder controlar a las personas. Mi ego no encuentra satisfacci&#243;n ya en tener m&#225;s que el Sr. Jones. Realmente quiero que el Sr. Jones est&#233; confortable, feliz, y si &#233;l tiene mucho m&#225;s que yo, no me hace sentirme inferior. No quiero un palacio, un Cadillac, trajes de 500 d&#243;lares, o anillos de diamantes. &#161;Pero tampoco quiero despertarme cada ma&#241;ana vac&#237;o como un gorri&#243;n y confiar en Su provisi&#243;n durante el d&#237;a! Veo algunos gorriones en el mundo (gorriones humanos) que se despiertan por la ma&#241;ana y mueren el mismo d&#237;a porque no hab&#237;a nada de comida en su pa&#237;s. Miro la historia del mundo y veo que el &#225;vido siempre consigue m&#225;s que su porci&#243;n porque ellos lo robaron de alguien que ahora tiene menos de su porci&#243;n y nuestro Padre permite que pase. Si no tengo cuidado conmigo quiz&#225; ser&#233; el pr&#243;ximo accidente. &#191;Qui&#233;n soy yo para que &#201;l est&#233; sobre m&#237; para librarme de los estafadores? Si permite que un ni&#241;o africano muera de hambre porque nosotros los cristianos americanos gastamos un bill&#243;n d&#243;lares en propiedades de la iglesia, fondos de jubilaci&#243;n para pastores, y vidrieras de colores, entonces quiz&#225; &#201;l tambi&#233;n permitir&#225; que la codicia de otras personas me cause da&#241;o. &#191;Realmente baja aqu&#237; \u00abpuedo confiar completamente en &#201;l?\u00bb \u00ab&#191;Conf&#237;o realmente en &#201;l?\u00bb Somos muy r&#225;pidos al contestar religiosamente \u00abpor supuesto,\u00bb pero he sido m&#225;s honrado conmigo mismo estos d&#237;as.<\/p>\n<p>De todo las personas que conozco, debo confiar en &#201;l. He recibido tanta provisi&#243;n milagrosa, que podr&#237;a escribir libros de los milagros que &#201;l ha hecho en mi vida. Ha enviado &#225;ngeles, tuve una Biblia ca&#237;da del cielo cuando requer&#237; una, hubo personas que me dieron sobres con dinero. Sobres en el correo con dinero sin direcci&#243;n del remitente. Me ha dado un cuerpo saludable y una educaci&#243;n que pueden permitirme ingresar mucho m&#225;s que el sueldo medio. Pero definitivamente he visto Su habilidad para proveer milagrosamente.<\/p>\n<p>Sin embargo, en medio de todo esto, he tenido dolencias f&#237;sicas y no pod&#237;a ir al doctor debido a la falta de seguro, tuve que trabajar casi un a&#241;o como un esclavo por una fracci&#243;n del sueldo que verdaderamente me correspond&#237;a, de repente me encontr&#233; recibiendo bonos de comida y ayuda el&#233;ctrica. Podr&#237;a culpar de estas cosas a la codicia de otros, a mi estupidez, etc., pero veo la mano del Padre en todo. Aprend&#237; compasi&#243;n en medio de todo esto. &#201;l me mostr&#243; cu&#225;nto orgullo hab&#237;a todav&#237;a en m&#237; que pens&#233; que era m&#225;s que ninguno all&#237;, me mostr&#243; que todav&#237;a no confiaba completamente en &#201;l. Mientras las cosas no sean \u00abjustas\u00bb aqu&#237; abajo, quiz&#225;s siempre tendr&#233; problemas aqu&#237; en la tierra con esto. No s&#233;.<\/p>\n<p>&#191;Ahora si me crucificara de verdad con Cristo, ya no vivir&#237;a al ego, entonces no habr&#237;a ning&#250;n problema? Los hombres muertos no tienen que preocuparse por cosas como las facturas del hospital, o &#191;podr&#233; ayudar a mis hijos para que vayan a la universidad etc. o tendr&#225;n que defenderse por ellos mismos?<\/p>\n<p>Jes&#250;s habl&#243; acerca de no preocuparse por el ma&#241;ana delante de Sus disc&#237;pulos. Todav&#237;a estos disc&#237;pulos ten&#237;an que recurrir a la asistencia social Judaica mientras Jes&#250;s estaba con ellos. &#191;Recuerde que los granos de trigo que comieron el Sab&#225;t en el campo? No era su propio trigo el que estaban comiendo. Despu&#233;s en Pentecost&#233;s, la iglesia puso sus posesiones a los pies de los ap&#243;stoles. Primer intento de un comunismo cristiano. Pocos a&#241;os despu&#233;s, Pablo tuvo que ir a las iglesias Gentiles de alrededor para pedir ayuda para la primera iglesia, Jerusal&#233;n. Parece que el sistema administrativo o algo fue mal. Ellos estaban pobres y Yahweh lo permiti&#243;. Muchos ten&#237;an sus propiedades fuera de ellos porque eran cristianos. Muchos murieron.<\/p>\n<p>Hoy, en muchas partes del mundo, como en muchos pa&#237;ses musulmanes e hind&#250;es, la fe de uno a menudo significa una p&#233;rdida de ingresos, jugarse la vida, persecuci&#243;n y muerte. Si nuestro Creador deja que estas cosas vengan sobre sus propios hijos, hay un mecanismo muy natural dentro de nosotros que trata de cercar con seto nuestros intereses, crear un peque&#241;o amortiguador dividido en zonas, un as en la manga, por llamarlo as&#237;.<\/p>\n<p>Parte de mi falta de confianza viene del hecho que no le oigo a &#201;l en cada decisi&#243;n que trata de las cosas que conciernen al dinero. No hago el \u00abcontrol\u00bb de cada compra. No estoy muy seguro de cuanto debemos controlar. &#201;l quiere que lo hagamos lo mejor que podamos. Haci&#233;ndolo todo absolutamente bien se dice que uno es un buen siervo, pero pienso que nuestro Padre tiene inter&#233;s en producir m&#225;s que siervos.<\/p>\n<p>A decir bien la ra&#237;z de todo esto realmente comenz&#243; muy atr&#225;s en el Ed&#233;n. All&#237; fue donde el \u00abamor al dinero\u00bb verdaderamente comenz&#243;. La serpiente en el cap&#237;tulo 3 del G&#233;nesis le dijo a Eva que el Creador les dejaba fuera a ellos. Que hab&#237;a algo que ella deb&#237;a tener, pero Dios no quer&#237;a que lo tuviera. Ella no estaba satisfecha con su provisi&#243;n de Dios. Estaba abierta a conseguir m&#225;s de lo que se le dio. Ahora el Creador de Eva lo hizo de esa forma. Ten&#237;a la habilidad de codiciar m&#225;s de lo que se la dio y as&#237; que ella comi&#243; y tambi&#233;n su marido y por su causa la maldici&#243;n vino tambi&#233;n para nosotros.<\/p>\n<p>\u00ab17Y al hombre dijo:<\/p>\n<p>&#8212;Por cuanto obedeciste a la voz de tu mujer y comiste del &#225;rbol de que te mand&#233; diciendo: \u00abNo comer&#225;s de &#233;l\u00bb, maldita ser&#225; la tierra por tu causa; con dolor comer&#225;s de ella todos los d&#237;as de tu vida,18 espinos y cardos te producir&#225; y comer&#225;s plantas del campo.<\/p>\n<p>19Con el sudor de tu rostro comer&#225;s el pan, hasta que vuelvas a la tierra, porque de ella fuiste tomado; pues polvo eres y al polvo volver&#225;s.\u00bb (G&#233;n. 3: 17-19)<\/p>\n<p>En estos vers&#237;culos de la Biblia encontramos la fuente de nuestros problemas y tambi&#233;n la soluci&#243;n. &#161;&#191;Trabajo, espinos y cardos, sudor, polvo&#8211;quien quiere vivir en una vida que le guste esto?! &#161;Encima de eso, &#201;l dice que todo esto viene sobre nosotros por nuestra causa! La mayor&#237;a de las personas, cristianas y no-cristianas no puede sacar ning&#250;n sentido de este pasaje de la Sagrada Escritura. La mayor&#237;a de las personas, cristianas y no-cristianas hacen cualquier cosa para poder evitar lo anterior. Inventaremos todo g&#233;nero de esquemas para evitar el trabajo duro, sudor, etc. jugaremos, jugaremos a la bolsa en el mercado de las acciones, pondremos nuestra esperanza en una posible herencia, robos, estafas, crear sofisticadas corporaciones para robar a los pobres apareciendo como un ciudadano observante de la ley Piadoso. Elegiremos aun a diputados con nuestra propia naturaleza corrupta que aprueben leyes que nos hagan parecer legales mientras robamos al pobre. Pondremos varios niveles de direcci&#243;n intermedia entre nosotros y las v&#237;ctimas. Crearemos todo tipo de instituciones que declarar&#225;n que somos virtuosos, mientras en nuestros corazones, somos realmente ladrones. Hablamos pomposamente de c&#243;mo lo hemos puesto todo a los pies de Jes&#250;s, pero estamos s&#243;lo enga&#241;&#225;ndonos. La mayor&#237;a de nosotros verdaderamente no quiere que Dios nos hable acerca de c&#243;mo manejar nuestros recursos. &#201;l podr&#237;a querer que demos mucho de ello, y quiz&#225;s s&#243;lo nos pedir&#225; que hagamos eso.<\/p>\n<p>La iglesia es la instituci&#243;n de las riquezas en el mundo. Si viera los m&#233;todos que us&#243; para ser la instituci&#243;n m&#225;s rica y quien eran sus v&#237;ctimas usted se asustar&#237;a. Nuestra cinta La Iglesia es una Ramera Rica toca brevemente el asunto (en ingles). La iglesia es definitivamente una gran muchedumbre. La iglesia Cat&#243;lica Romana tiene almacenes llenos de arte precioso, joyas de oro con valiosas piedras incrustadas. Las denominaciones del Cristianismo encargan a los corredores de bolsa que se ocupen de sus carteras de acciones. Billones y billones de d&#243;lares mientras el mundo va supuestamente al infierno. Este insaciable deseo de acumular, del que la iglesia es muy culpable, es un deseo en el total de nuestros corazones. Queremos descanso. Queremos decidir cu&#225;ntas horas queremos trabajar, y cuando, y donde. &#161;Nosotros queremos seguros de la vida, seguros de jubilaci&#243;n, seguro para la universidad, seguro dental, seguro de salud, seguro, seguro, seguro! &#191;Porqu&#233;? &#161;Porque realmente nosotros no confiamos en &#201;l! Tenemos que cuidarnos por nosotros. Y verdaderamente nos gustar&#237;a librarnos de esto \u00abespinas y cardos, sudor, trabajo, y polvo\u00bb los negocios.<\/p>\n<p>Han existido sociedades en que muchas personas se las arreglaron para librarse de las \u00abespinas y cardos\u00bb los negocios. Quiz&#225;s la sociedad que la mayor&#237;a asocia con el mal en la Biblia es Sodoma. Se usa esta ciudad a menudo por los evangelistas para asustar a las personas en sus denominaciones. Pero lo que cuenta Dios del mal de Sodoma es bastante diferente de lo que dicen y retratan de esta ciudad la mayor&#237;a de los predicadores modernos. Aqu&#237; est&#225; lo que dice Dios de la situaci&#243;n de Sodoma: \u00ab49Esta fue la maldad de Sodoma, tu hermana: soberbia, pan de sobra y abundancia de ocio tuvieron ella y sus hijas; y no fortaleci&#243; la mano del afligido y del necesitado. 50Se llenaron de soberbia e hicieron abominaci&#243;n delante de m&#237;, y cuando lo vi, las quit&#233;.\u00bb<\/p>\n<p>(Ezequiel 16: 49,50) Todo el cap&#237;tulo debe leerse una docena de veces por aquellos que pertenecen al \u00abpueblo de Dios\u00bb de hoy.<\/p>\n<p>&#191;Nos damos cuenta de que la iglesia y los Estados Unidos son culpables? No hay ninguna duda en mi mente que la iglesia americana sola podr&#237;a aliviar todo el hambre del mundo inmediatamente. &#191;Porqu&#233; no lo hace?<\/p>\n<p>S&#233; que mi problema con Dios es uno de confianza. Cuando dije antes, si hay alguien quien no debe tener excusa para confiar absolutamente en &#201;l, debo ser yo. Creo que Su fin &#250;ltimo para toda la humanidad es bueno; creo que &#201;l salvar&#225; a toda la humanidad en el futuro; creo finalmente que &#201;l no hace acepci&#243;n de personas; creo que &#201;l nos ama a usted y a m&#237; con un amor indescriptible; creo que un d&#237;a limpiar&#225; toda l&#225;grima, y a&#250;n s&#233; que mi confianza debe ser m&#225;s profunda. Tambi&#233;n s&#233; que &#201;l es Quien va a trabajar esta cosa en mi coraz&#243;n. Decir que conf&#237;o en &#201;l y manifestar verdadera confianza son dos cosas completamente diferentes. Mis palabras son sin valor, pero cuando &#201;l lo perfeccione, entonces all&#237; se trabajar&#225; en m&#237; algo que Eva no ten&#237;a en el Ed&#233;n, verdadera confianza. Todos nosotros queremos un d&#237;a tener esta confianza, ser&#225; una cosa muy preciosa que ha trabajado en nosotros desde el Ed&#233;n. Habremos aprendido que en verdad &#201;l hace todas las cosas para nuestro bien. Necesitamos no creer en mentiras como que \u00abDios est&#225; lejos de nosotros.\u00bb Todo que lo que &#201;l detuvo de nosotros en el Ed&#233;n eran cosas como sufrimiento, dolor, ego&#237;smo, y trabajo. Cuando Eva confi&#243; en la palabra de la Serpiente, recibimos esas cosas que nuestro Padre detuvo de nosotros. Cuando nuestra confianza vuelva completamente a nuestro Hacedor, no nos enga&#241;aremos m&#225;s, y ser&#225;n limpiadas nuestras l&#225;grimas para siempre. Mi coraz&#243;n anhela ese d&#237;a.<\/p>\n<p>Tentmaker<\/p>\n<p>HCR Box 6D<\/p>\n<p>Hermann, MO 65041<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>En 1 Timoteo Cap&#237;tulo seis, en los vers&#237;culos 6-10 la Biblia dice: \u00abSin embargo, grande ganancia es la piedad con contentamiento. Porque nada trajimos a este mundo, y es evidente que nada podremos sacar. As&#237; que, teniendo el sustento y con qu&#233; cubrirnos, estaremos contentos con esto. Porque los que desean enriquecerse caen en tentaci&#243;n &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/el-amor-al-dinero\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEl amor al dinero\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5668","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/5668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=5668"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/5668\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=5668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=5668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=5668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}