{"id":5696,"date":"2016-02-08T19:11:56","date_gmt":"2016-02-09T00:11:56","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/predicar-la-vida\/"},"modified":"2016-02-08T19:11:56","modified_gmt":"2016-02-09T00:11:56","slug":"predicar-la-vida","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/predicar-la-vida\/","title":{"rendered":"Predicar La Vida"},"content":{"rendered":"<div>El horizonte de la muerte marca de tal manera la vida de los hombres, que con raz&#243;n la Escritura habl&#243; del &#8220;poder&#8221; de la muerte (cf. Ap 6,8; 20,6). Adem&#225;s &#8212;seg&#250;n te gusta recordar y predicar&#8212; la obra de Cristo fue resumida por la Carta a los Hebreos en estas palabras: &#171;As&#237; como los hijos participan de la sangre y de la carne, as&#237; tambi&#233;n particip&#243; &#233;l de las mismas, para aniquilar mediante la muerte al se&#241;or de la muerte, es decir, al Diablo&#187; (Heb 2,14).<\/div>\n<div style=\"text-align:justify; color:#3d3d3d;\">Por eso algunos pensadores dijeron que la filosof&#237;a era una larga reflexi&#243;n sobre la muerte, lo cual no deja de tener su raz&#243;n. Mas a ti y a cuantos creen os espera el magn&#237;fico reto de construir un pensamiento desde el horizonte de la vida: no s&#243;lo una reflexi&#243;n para que haya vida, pues no sois los creadores de la vida, sino un planteamiento desde la certeza de la vida, esto es, de que s&#237; hay vida.<\/p>\n<p>Una &#8220;cultura de la vida&#8221; no empieza con la tarea de construir ni con la tarea de preservar la vida. Empieza con el m&#225;s hermoso de los exordios: la seguridad de que s&#237; hay vida. Si no partes de esa convicci&#243;n absoluta y radical todo tu discurso ser&#225; una petici&#243;n de consenso; mas ni la vida ni la creaci&#243;n misma surgieron de un consenso, sino del poder sabio y amoroso de Dios, pues est&#225; escrito: &#171;&#191;Qui&#233;n abarc&#243; el esp&#237;ritu de Yahveh, y como consejero suyo le ense&#241;&#243;? &#191;Con qui&#233;n se aconsej&#243;, qui&#233;n le explic&#243; y le ense&#241;&#243; la senda de la justicia, y le ense&#241;&#243; la ciencia, y el camino de la inteligencia le mostr&#243;?&#187; (Is 40,13-14). Y m&#225;s adelante lees: &#171;Pues &#191;con qui&#233;n asemejar&#233;is a Dios, qu&#233; semejanza le aplicar&#233;is?&#187; (Is 40,18).<\/p>\n<p>Los que quieran defender la vida, pues, no han de partir de una sugerencia, ni de un consenso, ni de una petici&#243;n, ni de palabra alguna que pronuncien los labios humanos. Precisamente su error, a menudo, es que piden a moribundos adormilados y enviciados que den su acuerdo a los acentos y rimas de la canci&#243;n de la vida. Ni los paladares ni las narices de estos pobres pueden aprobar el suave gusto y aroma del designio creador de Dios.<\/p>\n<p>No te extra&#241;en ni turben mis palabras. Lo que yo quiero es que te levantes sobre ti mismo, y en cierto modo sobre la Historia misma de los hombres y accedas con tu mente a ese potent&#237;simo &#8220;&#161;Sea!&#8221; pronunciado por la boca de Dios en el proemio de la creaci&#243;n. Esa voz, que el mundo no conoce porque no lo reconoce a &#201;l, no se ha extinguido, sino que tiene sus ecos en las rec&#225;maras de las creaturas racionales. All&#237; puedes escucharlo.<\/p>\n<p>No fue la voz de los hombres sino esa voz divina la que rasg&#243; la nada y sembr&#243; de vida el campo est&#233;ril de la no existencia. S&#243;lo con la potencia de esa voz es posible descubrir la alegr&#237;a de ser y s&#243;lo con ella es posible quebrantar la dura sordera del mundo. As&#237; como Cristo con su voz poderosa levant&#243; a L&#225;zaro del sepulcro (Jn 11,43), as&#237; tambi&#233;n hay una voz venida del Padre, la &#171;palabra del juramento&#187;, como la llama la Carta a los Hebreos, que &#171;hace el Hijo perfecto para siempre&#187; (Heb 7,28).<\/p>\n<p>Esta es la voz que constituye a Jes&#250;s Crucificado como &#8220;Se&#241;or y Cristo&#8221; (Hch 2,36). Por eso lees: &#171;A Cristo, Dios le resucit&#243; al tercer d&#237;a y le concedi&#243; la gracia de aparecerse, no a todo el pueblo, sino a los testigos que Dios hab&#237;a escogido de antemano, a nosotros que comimos y bebimos con &#233;l despu&#233;s que resucit&#243; de entre los muertos. Y nos mand&#243; que predic&#225;semos al Pueblo, y que di&#233;semos testimonio de que &#233;l est&#225; constituido por Dios juez de vivos y muertos&#187; (Hch 10,40-42).<\/p>\n<p>As&#237; entiendes aquello que ense&#241;a Pablo, a saber que este Jes&#250;s ha sido &#171;constituido Hijo de Dios con poder, seg&#250;n el Esp&#237;ritu de santidad, por su resurrecci&#243;n de entre los muertos&#187; (Rom 1,4). Por eso &#171;tambi&#233;n nosotros os anunciamos la Buena Nueva de que la Promesa hecha a los padres Dios la ha cumplido en nosotros, los hijos, al resucitar a Jes&#250;s, como est&#225; escrito en los salmos: Hijo m&#237;o eres t&#250;; yo te he engendrado hoy (Sal 110).&#187; (Hch 13,32-33; cf. Heb 1,5). &#161;Esta es la voz de la vida, la voz que necesitas para defender la vida! Por lo cual, amado, hay que predicar la vida no con voces de muertos, sino con una voz fuerte, como la de los &#193;ngeles, seg&#250;n anunci&#243; Pablo: &#171;El Se&#241;or mismo, a la orden dada por la voz de un arc&#225;ngel y por la trompeta de Dios, bajar&#225; del cielo, y los que murieron en Cristo resucitar&#225;n en primer lugar&#187; (1 Ts 4,16; cf. Ap 5,2; 7,2; 14,6-7.9.15.18; 18,1-2; ).<\/p>\n<p>Tal &#8220;fortaleza&#8221; significa pronunciar la vida desde la certeza de la resurrecci&#243;n que ya se ha realizado en Cristo, y por tanto con la generosidad del que puede perderlo todo. Cuando est&#233;s dispuesto a morir con la convicci&#243;n &#237;ntima y humilde de resucitar Con cari&#241;o, estar&#225;s listo para predicar la vida. Lo dem&#225;s es ruido de palabras.<\/p>\n<p>Deja que te invite a la alegr&#237;a. Dios te ama; su amor es eterno.<\/p>\n<p>Por &#193;ngel<\/p>\n<p>Lunes, 7 de febrero del 2000<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El horizonte de la muerte marca de tal manera la vida de los hombres, que con raz&#243;n la Escritura habl&#243; del &#8220;poder&#8221; de la muerte (cf. Ap 6,8; 20,6). Adem&#225;s &#8212;seg&#250;n te gusta recordar y predicar&#8212; la obra de Cristo fue resumida por la Carta a los Hebreos en estas palabras: &#171;As&#237; como los hijos &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/predicar-la-vida\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abPredicar La Vida\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5696","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/5696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=5696"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/5696\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=5696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=5696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=5696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}