{"id":5702,"date":"2016-02-08T19:12:00","date_gmt":"2016-02-09T00:12:00","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/cuando-la-sal-pierde-su-sabor\/"},"modified":"2016-02-08T19:12:00","modified_gmt":"2016-02-09T00:12:00","slug":"cuando-la-sal-pierde-su-sabor","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/cuando-la-sal-pierde-su-sabor\/","title":{"rendered":"Cuando la sal pierde su sabor"},"content":{"rendered":"<div>A continuaci&#243;n tenemos las siguientes tres citas:<\/p>\n<p>Mateo 5:13 &#8220;Vosotros sois la sal de la tierra; pero si la sal se desvaneciere, &#191;con qu&#233; ser&#225; salada? No sirve m&#225;s para nada, sino para ser echada fuera y hollada por los hombres&#8221;<\/p><\/div>\n<div style=\"text-align:justify; color:#3d3d3d;\">Marcos 9: 49-50 &#8220;Porque todos ser&#225;n salados con fuego, y todo sacrificio ser&#225; salado con sal. Buena es la sal; mas si la sal se hace ins&#237;pida, &#191;con qu&#233; la sazonar&#233;is? Tened sal en vosotros mismos; y tened paz los unos con los otros&#8221;<\/p>\n<p>Lucas 14:34-35 &#8220;Buena es la sal; mas si la sal se hiciere ins&#237;pida, &#191;con qu&#233; se sazonar&#225;? Ni para la tierra ni para el muladar es &#250;til; la arrojan fuera. El que tiene o&#237;dos para o&#237;r, oiga&#8221;<\/p>\n<p>De estos vers&#237;culos podemos concluir que el ser sal es una caracter&#237;stica muy importante del cristiano. Sabemos las caracter&#237;sticas de la sal; las principales son: el dar sabor a los alimentos, la preservaci&#243;n de ellos y el provocar la sed. Se ha dicho mucho acerca de esto.<\/p>\n<p>Debemos tener presente que cumplimos un papel esencial en el mundo y es el de hacer de &#233;l un mejor lugar para vivir. Ahora, en estas tres citas se nos advierte contra el peligro de perder nuestras propiedades de sal, entonces la pregunta es: &#191;C&#243;mo pierdo yo mis propiedades de sal?. Una respuesta general podr&#237;a ser: pecando, apartarme de la voluntad de Dios. Todo esto es cierto. Pero la Biblia nos da elementos para precisar mejor esta respuesta. Sobre esto trata este estudio.<\/p>\n<p>Iremos cita por cita:<\/p>\n<p>Mateo 5:13 &#8220;Vosotros sois la sal de la tierra; pero si la sal se desvaneciere, &#191;con qu&#233; ser&#225; salada? No sirve m&#225;s para nada, sino para ser echada fuera y hollada por los hombres&#8221;.<\/p>\n<p>Esta advertencia la tenemos despu&#233;s de lo que se llama las bienaventuranzas (Mateo 5:1-12). Esta porci&#243;n de la escritura es parte del serm&#243;n del monte que se extiende en los cap&#237;tulos 5, 6 y 7 del evangelio de Mateo. Este discurso termina de esta manera: &#8220;Cualquiera, pues, que me oye estas palabras, y las hace, le comparar&#233; a un hombre prudente, que edific&#243; su casa sobre la roca. Descendi&#243; lluvia, y vinieron r&#237;os, y soplaron vientos, y golpearon contra aquella casa; y no cay&#243;, porque estaba fundada sobre la roca. Pero cualquiera que me oye estas palabras y no las hace, le comparar&#233; a un hombre insensato, que edific&#243; su casa sobre la arena; y descendi&#243; lluvia, y vinieron r&#237;os, y soplaron vientos, y dieron con &#237;mpetu contra aquella casa; y cay&#243;, y fue grande su ruina&#8221; (Mateo 7:24-27).<\/p>\n<p>Es claro que esto se puede aplicar a toda la doctrina que Jes&#250;s ense&#241;&#243;, pero Mateo coloca esta sentencia al final del serm&#243;n del monte, de modo que lo que en ella se habla es de vital importancia. Y uno de los temas tocados es las bienaventuranzas; y en especial es clave para que la sal no deje de ser salada.<\/p>\n<p>Bienaventurados los pobres de esp&#237;ritu, bienaventurados los que lloran, bienaventurados los mansos, bienaventurados los que tienen hambre y sed de justicia, bienaventurados los misericordiosos, bienaventurados los de limpio coraz&#243;n, bienaventurados los pacificadores y bienaventurados los perseguidos por causa de Cristo son dichos que si somos sinceros con nosotros mismos no tienen ning&#250;n atractivo. Es obvio que nuestro Se&#241;or ten&#237;a un prop&#243;sito al decirnos todo esto, y el prop&#243;sito m&#225;s claro es que el reino de los cielos es completamente diferente a lo que hemos estado acostumbrados en el mundo. <\/p>\n<p>Para los ap&#243;stoles y para nosotros antes de haber conocido la palabra de Dios la verdad era otra. Para nosotros ser bienaventurado es ser rico carnalmente hablando nunca pobre de esp&#237;ritu; para nosotros bienaventurado es estar siempre con una sonrisa en los labios pero Jes&#250;s nos dice que los que sufren por el estado actual de las cosas ellos son bienaventurados. Jes&#250;s nos impulsa a cambiar nuestra manera de pensar de una manera radical. En primer lugar en el reino de los cielos no se puede tener las mismas expectativas que en el mundo. Lo que necesitamos urgentemente es un cambio de mente. Romanos 12:2 &#8220;No os conform&#233;is a este siglo, sino transformaos por medio de la renovaci&#243;n de vuestro entendimiento, para que comprob&#233;is  cu&#225;l sea la buena voluntad de Dios, agradable y perfecta&#8221;<\/p>\n<p>En Lucas 16:13-15 dice: &#8220;Ning&#250;n siervo puede servir a dos se&#241;ores; porque o aborrecer&#225; al uno y amar&#225; al otro, o estimar&#225; al uno y menospreciar&#225; al otro. No pod&#233;is servir a Dios y a las riquezas. Y o&#237;an tambi&#233;n todas estas cosas los fariseos, que eran avaros, y se burlaban de &#233;l. Entonces les dijo: Vosotros sois los que os justific&#225;is a vosotros mismos delante de los hombres; mas Dios conoce vuestros corazones; por que lo que los hombres tienen por sublime, delante de Dios es abominaci&#243;n.&#8221;<\/p>\n<p>La frase &#8220;lo que los hombres tienen por sublime, delante de Dios es abominaci&#243;n&#8221; confirma lo que venimos diciendo. Esto es precisamente lo que Jes&#250;s nos quiere hacer entender en las bienaventuranzas. El sistema de Dios es completamente diferente que el sistema del mundo.<\/p>\n<p>Entonces un cambio total de nuestra perspectiva es necesario para ser sal.<\/p>\n<p>Marcos 9:49-50 &#8220;Porque todos ser&#225;n salados con fuego, y todo sacrificio ser&#225; salado con sal. Buena es la sal; mas si la sal se hace ins&#237;pida, &#191;con qu&#233; la sazonar&#233;is? Tened sal en vosotros mismos; y tened paz los unos con los otros&#8221;<\/p>\n<p>Leamos lo que Jes&#250;s dijo en los vers&#237;culos anteriores. Marcos 9:43-48 &#8220;Si tu mano te fuese ocasi&#243;n de caer, c&#243;rtala; mejor te es entrar en la vida manco, que teniendo dos manos ir al infierno, al fuego que no puede ser apagado, donde el gusano de ellos no muere, y el fuego nunca se apaga.<\/p>\n<p> Y si tu pie fuere ocasi&#243;n de caer, c&#243;rtalo; mejor te es entrar en la vida cojo, que teniendo dos pies ser echado en el infierno, al fuego que no puede ser apagado, donde el gusano de ellos no muere, y el fuego nunca se apaga. Y si tu ojo te fuere ocasi&#243;n de caer, s&#225;calo; mejor te es entrar en el reino de Dios con un ojo, que teniendo dos ojos ser echado al infierno, donde el gusano de ellos no muere, y el fuego nunca se apaga&#8221;<br \/>\nLo que normalmente es una locura, adquiere sentido en el reino de Dios. <\/p>\n<p>Para ser sal no se puede pensar como en el mundo, es decir aferrarse a cosas de este mundo por mantenerse en el pecado. Otra vez, lo de esta vida queda relegado. No es sino que cumplir el mandamiento antiguo &#8220;Amar&#225;s al Se&#241;or tu Dios con todo tu coraz&#243;n, y con toda tu alma, y con todas tus fuerzas, y con toda tu mente&#8221;. El mundo es el gran enemigo de Dios, si preferimos algo de este mundo que se superponga a &#233;l, perderemos nuestra calidad de sal. Y c&#243;mo termina Dios este tema: &#8220;buena es la sal; mas si la sal se hace ins&#237;pida, &#191;con qu&#233; la sazonar&#233;is?&#8221;<br \/>\nLucas14:34-35 &#8220;Buena es la sal; mas si la sal se hiciere ins&#237;pida, &#191;con qu&#233; se sazonar&#225;? Ni para la tierra ni para el muladar es &#250;til; la arrojan fuera. El que tiene o&#237;dos para o&#237;r, oiga&#8221;<\/p>\n<p>La lectura de Lucas 14:26-33 explicar&#225; totalmente lo que queremos decir y confirmar&#225; lo que venimos diciendo:<\/p>\n<p>&#8220;Si alguno viene a m&#237;, y no aborrece a su padre, y madre, y mujer, e hijos, y hermanos, y hermanas, y a&#250;n tambi&#233;n su propia vida, no puede ser mi disc&#237;pulo. Y el que no lleva su cruz y viene en pos de m&#237;, no puede ser mi disc&#237;pulo. Porque &#191;qui&#233;n de vosotros, queriendo edificar una torre, no se sienta primero y calcula los gastos, a ver si tiene lo que necesita para acabarla? No sea que despu&#233;s que haya puesto el cimiento, y no pueda acabarla, todos los que lo vean comiencen a hacer burla de &#233;l, diciendo: Este hombre comenz&#243; a edificar, y no pudo acabar. &#191;O qu&#233; rey, al marchar a la guerra contra otro rey, no se sienta primero y considera si puede hacer frente con  diez mil al que viene contra &#233;l con veinte mil? Y si no puede, cuando el otro est&#225; todav&#237;a lejos, le env&#237;a una embajada y le pide condiciones de paz. As&#237;, pues, cualquiera de vosotros que no renuncia a todo lo que posee, no puede ser mi disc&#237;pulo&#8221;<\/p>\n<p><b>Conclusi&#243;n<\/b><\/p>\n<p>La entidad que puede hacernos perder nuestra propiedad de sal, es el mundo. Tanto con su forma de pensar la cual nosotros arrastramos y por lo cual necesitamos una renovaci&#243;n en nuestra mente, y tambi&#233;n al aferrarnos compulsivamente a cosas de &#233;l; cosas que pueden ser tan &#237;ntimas como una parte de nuestro cuerpo o un familiar. Dios exige la prioridad. Jes&#250;s nos dijo: &#8220;Llevad mi yugo sobre vosotros, y aprended de m&#237;, que soy manso y humilde de coraz&#243;n; y hallar&#233;is descanso para vuestras almas; porque mi yugo es f&#225;cil y ligera mi carga&#8221; (Mateo 11:29-30). En resumen el materialismo nos quita nuestra sal.<\/p>\n<p>No pretendo parecer religioso ni espiritualoide, s&#243;lo creo en lo que dice la palabra de Dios la cual es la fuente de toda verdadera doctrina. Isa&#237;as 8:20: &#8220;&#161;A la ley y al testimonio! Si no dijeren conforme a esto, es porque no les ha amanecido&#8221;. Todo lo expuesto tiene resultados pr&#225;cticos no son s&#243;lo palabras. En Lucas 14:35 nos advierte: &#8220;Ni para la tierra ni para el muladar es &#250;til; la arrojan fuera. El que tiene o&#237;dos para o&#237;r, oiga&#8221;<\/p>\n<p>Iv&#225;n Salazar Contreras<\/p>\n<p>28 de Febrero del 2000<\/p>\n<p>Salazar Contreras Ivan Arturo [sacoia99@computextos.com]<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A continuaci&#243;n tenemos las siguientes tres citas: Mateo 5:13 &#8220;Vosotros sois la sal de la tierra; pero si la sal se desvaneciere, &#191;con qu&#233; ser&#225; salada? No sirve m&#225;s para nada, sino para ser echada fuera y hollada por los hombres&#8221; Marcos 9: 49-50 &#8220;Porque todos ser&#225;n salados con fuego, y todo sacrificio ser&#225; salado &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/cuando-la-sal-pierde-su-sabor\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCuando la sal pierde su sabor\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5702","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/5702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=5702"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/5702\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=5702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=5702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=5702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}