{"id":8426,"date":"2016-03-07T20:27:06","date_gmt":"2016-03-08T01:27:06","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/estudio-biblico-de-efesios-115-23\/"},"modified":"2016-03-07T20:27:06","modified_gmt":"2016-03-08T01:27:06","slug":"estudio-biblico-de-efesios-115-23","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/estudio-biblico-de-efesios-115-23\/","title":{"rendered":"Estudio b\u00edblico de Efesios 1:15-23"},"content":{"rendered":"<h2 class='estudio'>Efesios 1:15-23<\/h2>\n<p style=\"text-align: justify;\">Hoy llegaremos al final de este cap\u00edtulo 1 de Efesios. Despu\u00e9s de una introducci\u00f3n, hemos visto, en primer lugar, como Dios el Padre plane\u00f3 la iglesia (vv. 3 al 6). En segundo lugar, vimos como Dios el Hijo pag\u00f3 el precio por la iglesia derramando Su sangre en la cruz, por lo cual al creer en \u00c9l fuimos redimidos  (vv. 7 al 12). En tercer lugar, destacamos que Dios el Esp\u00edritu Santo protege a la iglesia (vv. 13 y 14). La \u00faltima parte de este cap\u00edtulo incluye la oraci\u00f3n del ap\u00f3stol Pablo, pidiendo conocimiento y poder para los creyentes. Esta secci\u00f3n se extiende desde los vers\u00edculos 15 al 23. <\/p>\n<p style=\"text-align: justify;\">En el d\u00eda de hoy, las circunstancias que nos impulsan a orar son las dificultades, las enfermedades, los problemas, o una crisis de una determinada iglesia. Y es triste que nuestra oraci\u00f3n tenga que estar motivada por causas negativas. Pero en el caso del ap\u00f3stol Pablo, lo que le impulsaba a orar a \u00e9l, eran las cosas positivas. En nuestro caso, la oraci\u00f3n a Dios est\u00e1 motivada por el deseo de tener ciertas cosas y de esa manera, se convierte en una lista de pedidos. \u00bfPor qu\u00e9 no le expresamos nuestro agradecimiento con mayor frecuencia?<\/p>\n<p style=\"text-align: justify;\">\u00c9ste fue el impulso que sinti\u00f3 el ap\u00f3stol Pablo cuando recibi\u00f3 las noticias e informes de la iglesia en \u00c9feso. Y dijo, \u00abno ceso de dar gracias por vosotros\u00bb. Resulta interesante que no pensamos con demasiada frecuencia en  Pablo como un destacado hombre de oraci\u00f3n. Le colocamos en el primer lugar de la lista como un gran misionero de la cruz. No nos imaginamos un mejor ejemplo de apostolado que el del ap\u00f3stol Pablo. Si tuvi\u00e9ramos que preparar una lista de los 10 mejores predicadores de la iglesia, con toda seguridad le colocar\u00edamos en el primer lugar. Pablo tambi\u00e9n fue uno de los mejores maestros de las Sagradas Escrituras. El Se\u00f1or Jes\u00fas fue, por supuesto el mejor maestro: Recordemos lo que dijeron los guardias en su informe  a los principales sacerdotes y fariseos sobre Jes\u00fas, palabras registradas en Juan 7:46: \u00a1Jam\u00e1s hombre alguno ha hablado como este hombre! Y el ap\u00f3stol Pablo continu\u00f3 con esa tradici\u00f3n. Y tambi\u00e9n fue un ejemplo como un buen pastor. De acuerdo con el relato de Lucas en los Hechos 20, Pablo llor\u00f3 al despedirse de los creyentes en \u00c9feso. El les amaba profundamente y ellos a \u00e9l.<\/p>\n<p style=\"text-align: justify;\">Siempre solemos evaluar el nivel de vida espiritual de una iglesia por la manera en que sus miembros aman a su pastor, o a sus l\u00edderes, siempre y cuando \u00e9stos sean fieles a la Palabra de Dios. La iglesia en \u00c9feso no solo amaba al ap\u00f3stol Pablo, sino que tambi\u00e9n amaban a la Palabra de Dios.<\/p>\n<p style=\"text-align: justify;\">Como hemos dicho, siempre que pensamos en alguien que se destacara en un \u00e1rea del servicio cristiano en la iglesia primitiva, el nombre de Pablo ocupa el primer lugar. \u00bfPor qu\u00e9 no colocarle tambi\u00e9n en un lugar de honor como representativo de un gran hombre de oraci\u00f3n? Consideramos a Mois\u00e9s como un gran intercesor en oraci\u00f3n en la cima del monte. Recordamos al rey David con sus salmos y la confesi\u00f3n de su grave pecado. Pensamos en el profeta El\u00edas, que se puso en pie \u00e9l solo frente a un altar empapado con agua en el Monte Carmelo, y ante cuya oraci\u00f3n descendi\u00f3 fuego del cielo. Y despu\u00e9s recordamos al profeta Daniel que abr\u00eda su ventana orientada hacia Jerusal\u00e9n y oraba, aunque viv\u00eda en una tierra hostil gobernada por un poder enemigo. Y el Se\u00f1or Jesucristo fue el Hombre de oraci\u00f3n, hasta tal punto que uno de Sus disc\u00edpulos le pidi\u00f3: \u00abSe\u00f1or, ens\u00e9\u00f1anos a orar\u00bb. (Lucas 11.1). <\/p>\n<p style=\"text-align: justify;\">\u00bfNo sab\u00eda usted que Pablo fue un gran hombre de oraci\u00f3n? Si hici\u00e9ramos una lista de citas B\u00edblicas de las veces en que Pablo dijo que estaba orando por alguien, nos sorprender\u00eda comprobar la extensa lista de oraci\u00f3n que ten\u00eda el ap\u00f3stol. \u00c9l or\u00f3 por mucha gente. Fue un gran hombre de oraci\u00f3n. <\/p>\n<p style=\"text-align: justify;\">En esta ep\u00edstola hay dos de las oraciones de Pablo. Estas oraciones revelan la preocupaci\u00f3n de Pablo como un hijo de Dios por otros creyentes. Una de las razones para evaluar si una persona es un hijo de Dios  es su vida de oraci\u00f3n. \u00bfQu\u00e9 nivel de dependencia de Dios siente esa persona? Si ella tiene una necesidad personal, se dirigir\u00e1 a Dios en oraci\u00f3n. Y tambi\u00e9n acudir\u00e1 a Dios en intercesi\u00f3n por otros. Recordemos, seg\u00fan el relato de los Hechos 9:11, cuando Anan\u00edas, en la ciudad de Damasco, se inquiet\u00f3 cuando el \u00e1ngel le dijo que se acercara a Saulo de Tarso. \u00c9l puso objeciones porque Saulo era el hombre que persegu\u00eda a la iglesia. Pero entonces el \u00e1ngel le dijo que Saulo estaba orando. \u00c9sa fue una indicaci\u00f3n a Anan\u00edas de que algo le hab\u00eda sucedido a Saulo de Tarso, a qui\u00e9n luego conocer\u00edamos como el ap\u00f3stol Pablo. <\/p>\n<p style=\"text-align: justify;\">En el vers\u00edculo 16 de este cap\u00edtulo 1 de Efesios, Pablo dijo que no cesaba de dar gracias a Dios por ellos. Ellos estaban en su lista de oraci\u00f3n y suponemos que todas las iglesias estaban incluidas en dicha lista.<\/p>\n<p style=\"text-align: justify;\">Continu\u00f3 diciendo haciendo menci\u00f3n de vosotros en mis oraciones. Seguramente mencion\u00f3 a los Efesios por sus nombres. El mencionar nombres concretos en nuestras oraciones es un ejemplo a imitar.<\/p>\n<p style=\"text-align: justify;\">Ya hemos mencionado que el motivo de la oraci\u00f3n de Pablo eran buenas noticias. Ahora veremos que no or\u00f3 por cosas materiales sino por bendiciones espirituales. \u00c9stas son las bendiciones de primera importancia. Vamos a comenzar nuestra lectura de hoy por el vers\u00edculo 16, que no puede separarse del vers\u00edculo 17:<\/p>\n<p style=\"text-align: justify;\">\u00abNo ceso de dar gracias por vosotros, haciendo memoria de vosotros en mis oraciones, para que el Dios de nuestro Se\u00f1or Jesucristo, el Padre de gloria, os d\u00e9 esp\u00edritu de sabidur\u00eda y de revelaci\u00f3n en el conocimiento de \u00e9l\u00bb<\/p>\n<p style=\"text-align: justify;\">Habiendo escrito que la iglesia es el cuerpo de Cristo. Y que el Padre la plane\u00f3, que Dios el Hijo pag\u00f3 un precio por ella, y que Dios el Esp\u00edritu Santo la proteg\u00eda, reconoci\u00f3 que los Efesios no ser\u00edan capaces de comprender estas verdades, a menos que el Esp\u00edritu de Dios fuera su maestro y les explicara la Palabra de Dios. Porque s\u00f3lo el Esp\u00edritu de Dios puede revelar el conocimiento de Dios. <\/p>\n<p style=\"text-align: justify;\">Un destacado maestro de la Biblia, el Dr. Ironside, practic\u00f3 una dependencia total del Esp\u00edritu Santo en su propio ministerio. En una ocasi\u00f3n, cuando estaba ense\u00f1ando el libro del Cantar de los Cantares, dijo que nunca hab\u00eda quedado satisfecho con el material que hab\u00eda encontrado en los tratados de Estudio B\u00edblico y entonces, se puso de rodillas y le pidi\u00f3 a Dios que le revelara el mensaje de ese libro. La verdad es que este hombre escribi\u00f3 una obra sobre el Cantar de los Cantares y, con toda sinceridad, su interpretaci\u00f3n es la \u00fanica que ha satisfecho mi propio coraz\u00f3n. <\/p>\n<p style=\"text-align: justify;\">\u00a1Qu\u00e9 experiencia hermosa y fruct\u00edfera es tener al Esp\u00edritu de Dios como el maestro que nos ense\u00f1e!  El vers\u00edculo 17 dice: \u00abQue el Dios de nuestro Se\u00f1or Jesucristo. . . os de esp\u00edritu de sabidur\u00eda y de revelaci\u00f3n en un mejor conocimiento de \u00e9l\u00bb.  \u00bfY c\u00f3mo tendr\u00e1 lugar esa acci\u00f3n divina? Se llevar\u00e1 a cabo por el Esp\u00edritu de Dios, el \u00fanico que puede abrir nuestros ojos y ense\u00f1arnos la Palabra de Dios.<\/p>\n<p style=\"text-align: justify;\">\u00abQue \u00e9l alumbre los ojos de vuestro entendimiento, para que sep\u00e1is cu\u00e1l es la esperanza a que \u00e9l os ha llamado, cu\u00e1les las riquezas de la gloria de su herencia en los santos\u00bb<\/p>\n<p style=\"text-align: justify;\">Otra versi\u00f3n, de forma m\u00e1s adecuada,  traduce literalmente el comienzo de este vers\u00edculo 18 de la siguiente manera: \u00abque os sean iluminados los ojos del coraz\u00f3n\u00bb. Porque son los ojos del coraz\u00f3n los que tienen que entender. Uno puede ser intelectualmente brillante, pero eso no garantiza que habr\u00e1 una comprensi\u00f3n de la verdad espiritual. Las Sagradas Escrituras ponen m\u00e1s \u00e9nfasis en la comprensi\u00f3n del coraz\u00f3n que en la de la mente. En Romanos 10:9-10, el ap\u00f3stol Pablo escribi\u00f3: \u00ab9Si confiesas con tu boca que Jes\u00fas es el Se\u00f1or y crees en tu coraz\u00f3n que Dios lo levant\u00f3 de entre los muertos, ser\u00e1s salvo, 10porque con el coraz\u00f3n se cree para justicia, pero con la boca se confiesa para salvaci\u00f3n\u00bb. <\/p>\n<p style=\"text-align: justify;\">En lo que se refiere al conocimiento espiritual, ninguna persona puede comprenderlo aparte del Esp\u00edritu de Dios. Eso es lo que el ap\u00f3stol Pablo, citando al profeta Isa\u00edas, escribi\u00f3 en Primera de Corintios 2:9-10: \u00abCosas que ojo no vio, ni o\u00eddo oy\u00f3, ni han subido al coraz\u00f3n del hombre, son las que Dios ha preparado para los que le aman. Pero Dios nos las revel\u00f3 a nosotros por el Esp\u00edritu; porque el Esp\u00edritu todo lo escudri\u00f1a, aun lo profundo de Dios\u00bb.  Y este ministerio del Esp\u00edritu Santo se convierte en realidad entre nosotros, s\u00f3lo en cuanto a lo que usted y yo estemos dispuestos a permitir que el Esp\u00edritu de Dios nos ense\u00f1e.<\/p>\n<p style=\"text-align: justify;\">El Dr. Vernon McGee visit\u00f3 en una ocasi\u00f3n a una anciana, que no pod\u00eda leer ni escribir, a quien sus amigos  le\u00edan la Biblia.  Teniendo en cuenta las limitaciones de la anciana, su prop\u00f3sito era compartir con ella las ense\u00f1anzas de la Palabra de Dios. Despu\u00e9s de explicarle las implicaciones de Juan 14 y para su sorpresa, la anciana le se\u00f1al\u00f3 algunos detalles sobre ese cap\u00edtulo que al Dr. McGee le hab\u00edan pasado desapercibidos, que no figuraban en los comentarios B\u00edblicos que \u00e9l hab\u00eda le\u00eddo y que revelaron la percepci\u00f3n espiritual de aquella mujer. \u00bfC\u00f3mo los hab\u00eda ella deducido? Sencillamente porque los ojos de su coraz\u00f3n hab\u00edan sido abiertos por el Esp\u00edritu Santo. <\/p>\n<p style=\"text-align: justify;\">El Esp\u00edritu de Dios quiere hoy ense\u00f1arnos.  Y una de las razones por la cual muchos en el pueblo de Dios no alcanzan una comprensi\u00f3n plena de las Sagradas Escrituras es que no  est\u00e1n dispuestos a que el Esp\u00edritu de Dios les ense\u00f1e. Los maestros, los cursos libres de Estudio B\u00edblico presenciales o a distancia, y los Seminarios tienen su lugar e importancia. \u00bfPor qu\u00e9 no permitir que el Esp\u00edritu de Dios sea quien nos ense\u00f1e?  Estimado oyente, ded\u00edquele tiempo a la lectura y estudio de la Biblia. A veces llegar\u00e1 usted a un pasaje al cual no le encuentra ning\u00fan significado. Si despu\u00e9s de releerlo no le encuentra ning\u00fan valor para su propia vida, dir\u00edjase a Dios en oraci\u00f3n manifest\u00e1ndole su dificultad para entender dicho pasaje B\u00edblico, y pidi\u00e9ndole que el Esp\u00edritu Santo gu\u00ede sus pensamientos y le ense\u00f1e. Eso os lo que otros maestros y yo hacemos, y sentimos que \u00c9l nos ayuda a entender y a aplicar las verdades de la Palabra de Dios. Cuando usted lea un pasaje de las Sagradas Escrituras, estimado oyente, \u00c9l puede tambi\u00e9n ense\u00f1arle a usted e iluminar para su comprensi\u00f3n y aplicaci\u00f3n pr\u00e1ctica aquellas p\u00e1ginas de la Biblia que a usted puedan resultarle oscuras, ambiguas o incomprensibles. De todas formas, debemos aceptar que hay algunos pasajes de la Biblia que se refieren a asuntos no esenciales para la fe cristiana y su aplicaci\u00f3n pr\u00e1ctica, que son interpretados de diferente manera por diversos maestros de la Biblia o simplemente, con diferentes matices. Es que Dios no nos ha revelado la totalidad de los detalles de los tiempos futuros, de aquellas \u00e9pocas muy cercanas a la culminaci\u00f3n de la historia y al triunfo final de Jesucristo. Y debemos respetar las \u00e1reas en las que Dios no nos ha dejado informaci\u00f3n espec\u00edfica, sabiendo que alg\u00fan d\u00eda tendremos acceso a la totalidad del programa de Dios para sus relaciones con los creyentes y los no creyentes. Pero todas las verdades necesarias para la salvaci\u00f3n, y la totalidad de las lecciones que deben ser aplicadas por los cristianos en su vida pr\u00e1ctica para vivir una vida de calidad espiritual y humana, as\u00ed como para agradar a Dios, se encuentran claramente expuestas en las Sagradas Escrituras.  <\/p>\n<p style=\"text-align: justify;\">La segunda lecci\u00f3n de este vers\u00edculo 18 parte de la frase para que sep\u00e1is cu\u00e1l es la esperanza a que \u00e9l os ha llamado, cu\u00e1les las riquezas de la gloria de su herencia en los santos.  Hemos mencionado anteriormente que tenemos una herencia en el Se\u00f1or. Tambi\u00e9n tenemos que saber que \u00c9l tiene una herencia en nosotros. Pensamos que encontramos una buena ilustraci\u00f3n de esta verdad en la tierra de Cana\u00e1n. La tierra de Cana\u00e1n pertenec\u00eda a Dios, pero \u00c9l se la entreg\u00f3 a los israelitas para que la poseyeran. Ellos est\u00e1n vinculados a esa tierra. Sin embargo, llegar\u00e1 un d\u00eda en el que Dios tomar\u00e1 posesi\u00f3n de todo este universo en el cual usted y yo vivimos hoy, y reclamar\u00e1 a Israel y a esa tierra como su propia posesi\u00f3n. En la actualidad, usted y yo, como cristianos, somos Su iglesia y Dios act\u00faa por medio de nosotros. Pero llegar\u00e1 el tiempo en el cual reinaremos con \u00c9l. Dios nos reclamar\u00e1 como Su herencia. A veces nos hemos preguntado sobre el alcance de esa verdad y reconocemos que es un \u00e1rea demasiado profunda para asimilarla con nuestra mente. Y necesitamos que el Esp\u00edritu Santo la convierta en una realidad comprensible y que afecte a nuestra vida. <\/p>\n<p style=\"text-align: justify;\">Continuando con nuestro estudio, vemos que Pablo continu\u00f3 expresando su petici\u00f3n a Dios. Leamos el vers\u00edculo 19 de Efesios cap\u00edtulo 1:<\/p>\n<p style=\"text-align: justify;\">\u00abY cu\u00e1l la extraordinaria grandeza de su poder para con nosotros los que creemos, seg\u00fan la acci\u00f3n de su fuerza poderosa.\u00bb<\/p>\n<p style=\"text-align: justify;\">Aqu\u00ed la palabra poder corresponde a la palabra griega \u00abdunameos\u00bb, el poder de la dinamita; la palabra acci\u00f3n  corresponde a la palabra griega \u00abenergeian\u00bb, que enfatiza la capacidad de ese poder para activar, para transmitir energ\u00eda. \u00bfY qu\u00e9 pudo lograr ese gran poder, esa gran fuerza, esa gran energ\u00eda? Leamos el vers\u00edculo 20: <\/p>\n<p style=\"text-align: justify;\">\u00abEsta fuerza oper\u00f3 en Cristo, resucit\u00e1ndolo de los muertos y sent\u00e1ndolo a su derecha en los lugares celestiales\u00bb<\/p>\n<p style=\"text-align: justify;\">Este tremendo poder fue suficiente para resucitar a Cristo de entre los muertos. Y no s\u00f3lo fue poder para la resurrecci\u00f3n, sino tambi\u00e9n para colocar a Cristo en su posici\u00f3n a la derecha de Dios, o sea, que fue un poder para la ascensi\u00f3n de Cristo. En muchas iglesias no se le da la debida importancia a la Ascensi\u00f3n. Siempre se enfatiza la Navidad y la llamada Semana Santa, pero parecemos relegar a un segundo plano el gran evento que ocurri\u00f3 despu\u00e9s. \u00bfNos hemos detenido a pensar en el poder que llev\u00f3 a Cristo nuevamente a su posici\u00f3n en el cielo? Humanamente hablando, nos impresiona el poder y la fuerza necesaria para elevar una nave y proyectarla hacia el espacio, transportando a personas y equipos de investigaci\u00f3n a distancias siderales, y la energ\u00eda para reintegrarlos a la tierra. Ese poder act\u00faa en el \u00e1mbito f\u00edsico. Pero el poder que intervino para que Cristo regresara a ocupar el lugar que le correspond\u00eda a la derecha de Dios en el cielo es el mismo poder que se encuentra disponible para los creyentes en la actualidad. Por tal motivo el ap\u00f3stol Pablo or\u00f3 a Dios para que los cristianos pudieran conocer la grandeza de ese poder. El ap\u00f3stol escribi\u00f3 lo siguiente en Filipenses 3:10, \u00abQuiero conocerlo a \u00e9l y el poder de su resurrecci\u00f3n\u00bb. Leamos, finalmente por hoy, los vers\u00edculos 21 al 23 de este primer cap\u00edtulo de Efesios:<\/p>\n<p style=\"text-align: justify;\">\u00abSobre todo principado y autoridad, poder y se\u00f1or\u00edo, y sobre todo nombre que se nombra, no s\u00f3lo en este siglo, sino tambi\u00e9n en el venidero. Y someti\u00f3 todas las cosas debajo de sus pies, y lo dio por cabeza sobre todas las cosas a la iglesia, la cual es su cuerpo, la plenitud de Aquel que todo lo llena en todo.\u00bb<\/p>\n<p style=\"text-align: justify;\">Y as\u00ed, el ap\u00f3stol Pablo concluy\u00f3 su oraci\u00f3n con una nota elevada. La iglesia es un organismo, es el cuerpo de Cristo, y Cristo es la Cabeza de la iglesia. Alg\u00fan d\u00eda futuro todo va a estar bajo Su control. El escritor de la carta a los Hebreos lo expres\u00f3 con claridad en su cap\u00edtulo 2:8, cuando dijo: \u00abTodo lo sujetaste bajo sus pies. En cuanto le sujet\u00f3 todas las cosas, nada dej\u00f3 que no le sea sujeto, aunque todav\u00eda no vemos que todas las cosas le sean sujetas. \u00ab<\/p>\n<p style=\"text-align: justify;\">En la \u00e9poca actual lo \u00fanico que se encuentra bajo Su control es la iglesia. Y al decir \u00abiglesia\u00bb nos referimos a la verdadera iglesia, la que est\u00e1 formada por verdaderos cristianos, por aut\u00e9nticos creyentes. Hay muchos grupos organizados que se identifican como iglesias, pero habr\u00eda que evaluar si escuchan y obedecen al Se\u00f1or de la iglesia. Porque algunos sectores del cristianismo parecen estar paralizados. Es que la visi\u00f3n m\u00e1s tr\u00e1gica de un hijo de Dios, figurativamente hablando, es contemplarle postrado en cama, impotente, incapacitado para salir de esa situaci\u00f3n, habiendo perdido su capacidad mental o espiritual, como si su cerebro estuviera separado de su cuerpo. A veces hemos visto a algunos que profesan ser cristianos, que act\u00faan como si estuvieran separados o distanciados de Cristo, que es la Cabeza de la iglesia. Estimado oyente, \u00c9l dijo, en Juan 14:15, \u00abSi me am\u00e1is, guardad mis mandamientos\u00bb. En otras palabras, yo pude mover un dedo o cualquier otra parte de mi cuerpo porque mi cabeza controla la situaci\u00f3n. Y cuando \u00c9l quiere que usted se mueva, es decir, que ejercite cualquier don que \u00c9l le haya dado, tendr\u00e1 que practicarlo con amor; si no es as\u00ed, significar\u00e1 que usted no est\u00e1 unido a Cristo. Y esto tiene una gran importancia en los tiempos que vivimos. El ap\u00f3stol Pablo ilustr\u00f3 la iglesia y nuestra relaci\u00f3n con ella de la siguiente manera en  Primera de Corintios 12:12-13, cuando escribi\u00f3: \u00ab12As\u00ed como el cuerpo es uno, y tiene muchos miembros, pero todos los miembros del cuerpo, siendo muchos, forman un solo cuerpo, as\u00ed tambi\u00e9n Cristo. 13Porque por un solo Esp\u00edritu fuimos todos bautizados para constituir un solo cuerpo, tanto jud\u00edos como griegos, tanto esclavos como libres; y a todos se nos dio a beber de un mismo Esp\u00edritu\u00bb.  <\/p>\n<p style=\"text-align: justify;\">Lo que tenemos que ver con claridad es que Cristo es la Cabeza del cuerpo, que es su iglesia, y al estar unidos a \u00c9l,  todos estamos bajo Su autoridad. En nuestro pr\u00f3ximo programa comenzaremos a estudiar el cap\u00edtulo 2 de esta carta a los Efesios, en el cual veremos a la iglesia como un templo. Pero hoy, estimado oyente, le invitamos a que eval\u00fae en qu\u00e9 condici\u00f3n se encuentra su relaci\u00f3n con Dios, y al examinarse a s\u00ed mismo pueda comprobar si verdaderamente se considera usted unido a su Salvador, el Se\u00f1or Jesucristo. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Efesios 1:15-23 Hoy llegaremos al final de este cap\u00edtulo 1 de Efesios. Despu\u00e9s de una introducci\u00f3n, hemos visto, en primer lugar, como Dios el Padre plane\u00f3 la iglesia (vv. 3 al 6). En segundo lugar, vimos como Dios el Hijo pag\u00f3 el precio por la iglesia derramando Su sangre en la cruz, por lo cual &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/estudio-biblico-de-efesios-115-23\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio b\u00edblico de Efesios 1:15-23\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8426","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/8426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=8426"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/8426\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=8426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=8426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=8426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}