{"id":9912,"date":"2016-03-11T19:20:23","date_gmt":"2016-03-12T00:20:23","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/la-grandeza-de-la-palabra-de-dios\/"},"modified":"2016-03-11T19:20:23","modified_gmt":"2016-03-12T00:20:23","slug":"la-grandeza-de-la-palabra-de-dios","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/la-grandeza-de-la-palabra-de-dios\/","title":{"rendered":"La Grandeza de la Palabra de Dios"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>\u00d3seas 8:12<\/strong><\/p>\n<p style=\"text-align: justify;\">La esperanza del cristiano descansa en la Palabra de Dios, esta palabra que ha venido de afuera de nuestro entorno humano, para marcarnos la direcci\u00f3n de nuestra vida (Salmo 119:105).<\/p>\n<p style=\"text-align: justify;\">Para este tiempo dispensacional, Dios ha enviado su palabra personal, (Col. 1:27) Cristo nuestra esperanza de gloria, y cuando dejamos de poner la atenci\u00f3n a esta palabra la vida se convierte en una tragedia. Este tema quiero dividirlo en tres partes.<\/p>\n<p style=\"text-align: justify;\"><strong>I. LA VERDAD BIBLICA<\/strong><\/p>\n<p style=\"text-align: justify;\">A. La Biblia procede de la mente de Dios<\/p>\n<p style=\"text-align: justify;\">1. Por la Biblia Dios habla al hombre (Salmo 119:130)<br \/>\n2. La palabra es escudo a los que en \u00e9l esperan (Proverbios 30:5)<br \/>\n3. En la Biblia Dios da testimonio de si mismo (Is. 55:11)<\/p>\n<p style=\"text-align: justify;\">B. La Biblia es la revelaci\u00f3n de Dios<\/p>\n<p style=\"text-align: justify;\">1. Si Dios no se revela nadie puede conocerle (Col. 1:26)<\/p>\n<p style=\"text-align: justify;\">2. Dios es infinito y el hombre un ser limitado<\/p>\n<p style=\"text-align: justify;\">C. La Biblia es la inspiraci\u00f3n de Dios<\/p>\n<p style=\"text-align: justify;\">1. Pedro nos habla de c\u00f3mo se confecciones el escrito B\u00edblico (2\u00aa Pe. 1:21)<br \/>\n2. El autor humano no escribi\u00f3 voluntariamente (Jr. 1:5)<br \/>\n3. Dios act\u00faa en la mente del profeta, para lo que el quiere comunicar (Jr. 1:9)<br \/>\n4. Pablo habla de otro aspecto de la inspiraci\u00f3n (2\u00aa Ti. 3:16)<br \/>\na) Pedro habla de la palabra impulsada por Dios<br \/>\nb) Pablo habla de la palabra soplada por Dios (trasmite vida)<\/p>\n<p style=\"text-align: justify;\">5. La palabra de Dios es viva (He. 4:12)<br \/>\n6. David dice en (2\u00ba de Samuel 23:2)<\/p>\n<p style=\"text-align: justify;\"><strong>II. CONSECUENCIAS DE LA VERDAD BIBLICA<\/strong><\/p>\n<p style=\"text-align: justify;\">A. Predicar la palabra de Dios (2\u00aa Ti.4:1-2)<\/p>\n<p style=\"text-align: justify;\">1. No se puede predicar otra cosa, que no sea la palabra<br \/>\n2. La idea del predicador debe quedar fuera de la iglesia (Pro. 30:6)<\/p>\n<p style=\"text-align: justify;\">B. no se puede a\u00f1adir ni quitar a la escritura<\/p>\n<p style=\"text-align: justify;\">1. Los saduceos le hab\u00eda quitado a la escritura lo que no encajaba con ellos (Lc.20:27)<br \/>\n2. Los fariseos le hab\u00edan a\u00f1adido a la escritura, doctrinas de hombres (Mt. 15:9)<br \/>\n3. El problema de este tiempo es predicar a un cristo de religi\u00f3n, que no cambia la vida de los cristianos<br \/>\n4. El mundo esta cansado de teolog\u00eda, quiere ver un cambio en la vida de los que dicen ser creyentes (Tito 1:16)<\/p>\n<p style=\"text-align: justify;\"><strong>II. MI RESPONSABILIDAD ANTE LA VERDAD BIBLICA<\/strong><\/p>\n<p style=\"text-align: justify;\">A. La Biblia es un mensaje de salvaci\u00f3n<\/p>\n<p style=\"text-align: justify;\">1. El hombre por su pecado esta sentenciado a muerte eterna<br \/>\n2. Pero un d\u00eda Dios hizo un milagro, Dios se revisti\u00f3 de hombre<br \/>\n3. La religi\u00f3n pretende cambiar al hombre por fuera<\/p>\n<p style=\"text-align: justify;\">B. Cristo es el \u00fanico que puede cambiar la vida del hombre<\/p>\n<p style=\"text-align: justify;\">1. Solo Jes\u00fas puede transformar la vida y darle vida eterna (2\u00aa Ti. 1:10)<\/p>\n<p style=\"text-align: justify;\"><strong>Conclusi\u00f3n.<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00bfDonde esta Cristo? Esta colgado en un cuadro o lo lleva colgado en el pecho, pues quiero decirle que ese Cristo no sirve para nada. Solo cuando Cristo esta en la vida de la persona puede haber un cambio en la vida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00d3seas 8:12 La esperanza del cristiano descansa en la Palabra de Dios, esta palabra que ha venido de afuera de nuestro entorno humano, para marcarnos la direcci\u00f3n de nuestra vida (Salmo 119:105). Para este tiempo dispensacional, Dios ha enviado su palabra personal, (Col. 1:27) Cristo nuestra esperanza de gloria, y cuando dejamos de poner la &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/la-grandeza-de-la-palabra-de-dios\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLa Grandeza de la Palabra de Dios\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9912","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/9912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=9912"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/9912\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=9912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=9912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=9912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}