{"id":9926,"date":"2016-03-11T19:20:32","date_gmt":"2016-03-12T00:20:32","guid":{"rendered":"http:\/\/www.biblia.work\/sermones\/agradecidos\/"},"modified":"2016-03-11T19:20:32","modified_gmt":"2016-03-12T00:20:32","slug":"agradecidos","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/sermones\/agradecidos\/","title":{"rendered":"Agradecidos"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Texto:<\/strong> Job 1:21<\/p>\n<p style=\"text-align: justify;\"><strong>Introducci\u00f3n:<\/strong><\/p>\n<p style=\"text-align: justify;\">En un mundo lleno de insatisfacci\u00f3n y presi\u00f3n social como el nuestro, es altamente posible que dejemos entrar la queja a nuestra vida, y terminemos siendo y comport\u00e1ndonos como ingratos delante del Se\u00f1or.<\/p>\n<p style=\"text-align: justify;\">Dos buenos amigos se encontraron en la calle un d\u00eda. Uno de ellos mir\u00f3 al otro y al verle triste y cabizbajo casi hasta las l\u00e1grimas le pregunt\u00f3:<\/p>\n<p style=\"text-align: justify;\">&#8211; \u00bfqu\u00e9 te pasa mi amigo?<\/p>\n<p style=\"text-align: justify;\">El amigo le contest\u00f3:<\/p>\n<p style=\"text-align: justify;\">&#8211; Hace tres semanas, un t\u00edo muri\u00f3 y me dej\u00f3 40 mil d\u00f3lares.<\/p>\n<p style=\"text-align: justify;\">&#8211; Eso es mucho dinero, contest\u00f3 el otro.<\/p>\n<p style=\"text-align: justify;\">&#8211; Pero eso no es todo, dos semanas atr\u00e1s, un primo muri\u00f3 y me dej\u00f3 85 mil d\u00f3lares.<\/p>\n<p style=\"text-align: justify;\">El amigo le dice: suena como que est\u00e1s siendo bendecido.<\/p>\n<p style=\"text-align: justify;\">&#8211; Es que t\u00fa no entiendes, dice el otro, la semana pasada una t\u00eda abuela muri\u00f3 y hered\u00e9 casi un cuarto de mill\u00f3n de d\u00f3lares.<\/p>\n<p style=\"text-align: justify;\">El amigo ahora estaba confundido,<\/p>\n<p style=\"text-align: justify;\">&#8211; \u00bfEntonces cu\u00e1l es el problema?<\/p>\n<p style=\"text-align: justify;\">&#8211; El problema es que esta semana no recibi&#8230;&#8230;&#8230;. \u00a1NADA!!!!!!!!!!!<\/p>\n<p style=\"text-align: justify;\">O.T Veamos lo que la biblia ense\u00f1a sobre ser agradecidos.<\/p>\n<p style=\"text-align: justify;\"><strong>1. La Biblia nos ense\u00f1a que ser agradecidos en la voluntad de Dios. 2 Tes 5:18<\/strong><\/p>\n<p style=\"text-align: justify;\">a. Ser llenos del Esp\u00edritu Santo incluye tener una actitud de gratitud.<\/p>\n<p style=\"text-align: justify;\">b. \u201cDando siempre gracias por todo al Dios y Padre, en el nombre de nuestro Se\u00f1or Jesucristo\u201d Efesios 5:20<\/p>\n<p style=\"text-align: justify;\"><strong>2. La Biblia nos ense\u00f1a que ser agradecido abre las puertas de provisi\u00f3n. Mateo 15:36<\/strong><\/p>\n<p style=\"text-align: justify;\">a. \u00bfPor qu\u00e9 dio gracias Jes\u00fas si lo que ten\u00eda no alcanzaba?<\/p>\n<p style=\"text-align: justify;\">b. \u201cSer agradecido es una de las llaves de la vida que abren las puertas m\u00e1s dif\u00edciles\u201d<\/p>\n<p style=\"text-align: justify;\">c. El agradecimiento es el primer paso en un acto de Fe.<\/p>\n<p style=\"text-align: justify;\"><strong>3. La Biblia nos ense\u00f1a que ser agradecidos activa los milagros. Juan 11:41<\/strong><\/p>\n<p style=\"text-align: justify;\">a. El agradecimiento prepara el camino para el milagro, sin importar cu\u00e1n complicado, dif\u00edcil sea la situaci\u00f3n\u2026<\/p>\n<p style=\"text-align: justify;\">b. Si comenzamos a ser agradecidos, comenzaran a soltarse los milagros<\/p>\n<p style=\"text-align: justify;\"><strong>4. La Biblia nos ense\u00f1a que ser agradecidos es una actitud del coraz\u00f3n. 2 Timoteo 3:1-2<\/strong><\/p>\n<p style=\"text-align: justify;\">a. Ingrato: Desagradecido, que olvida o desconoce los beneficios recibidos.<\/p>\n<p style=\"text-align: justify;\">b. Morder la mano que te alimenta y luego quejarte de indigesti\u00f3n<\/p>\n<p style=\"text-align: justify;\">c. La falta de agradecimiento nos igual con muchas personas que la Biblia compara \u201chombres amadores de si mismos\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>5. La Biblia nos ense\u00f1a que ser agradecidos es la forma de entrar en su presencia. Sal 100:4<\/strong><\/p>\n<p style=\"text-align: justify;\">a. Nadie puede entrar a la presencia de Dios sin una actitud de agradecimiento.<\/p>\n<p style=\"text-align: justify;\">b. Muchos no llegan a la presencia de Dios por su actitud de quejas y reproches.<\/p>\n<p style=\"text-align: justify;\"><strong>Conclusi\u00f3n:<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00bfEres una persona agradecida?<\/p>\n<p style=\"text-align: justify;\">\u00bfQu\u00e9 cambios debes hacer en tu vida en esta ma\u00f1ana?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Texto: Job 1:21 Introducci\u00f3n: En un mundo lleno de insatisfacci\u00f3n y presi\u00f3n social como el nuestro, es altamente posible que dejemos entrar la queja a nuestra vida, y terminemos siendo y comport\u00e1ndonos como ingratos delante del Se\u00f1or. Dos buenos amigos se encontraron en la calle un d\u00eda. Uno de ellos mir\u00f3 al otro y al &hellip; <a href=\"https:\/\/www.biblia.work\/sermones\/agradecidos\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abAgradecidos\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9926","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/9926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/comments?post=9926"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/posts\/9926\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/media?parent=9926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/categories?post=9926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/sermones\/wp-json\/wp\/v2\/tags?post=9926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}